{"id":240875,"date":"2025-03-20T12:00:00","date_gmt":"2025-03-20T11:00:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240875"},"modified":"2025-03-20T12:45:26","modified_gmt":"2025-03-20T11:45:26","slug":"la-situazione-critica-del-servizio-sanitario-nazionale-minaccciato-dai-tagli-continui","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/la-situazione-critica-del-servizio-sanitario-nazionale-minaccciato-dai-tagli-continui\/","title":{"rendered":"&#8220;La situazione critica del Servizio Sanitario Nazionale minaccciato dai tagli continui&#8221;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"316\" height=\"244\" class=\"wp-image-240876\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/Orazio_Schillaci.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/Orazio_Schillaci.jpg 316w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/Orazio_Schillaci-300x232.jpg 300w\" sizes=\"(max-width: 316px) 100vw, 316px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Da Roma l\u2019Associazione dei Consumatori Codici ci manda il seguente comunicato (nella nostra foto, il ministro della Salute Orazio Schillaci) ___________<\/p>\n\n\n\n<p><strong>Codici: i continui tagli dei fondi minacciano il Servizio Sanitario Nazionale<\/strong><\/p>\n\n\n\n<p>Il Servizio Sanitario Nazionale sta attraversando una fase di profonda crisi che rischia di aggravarsi ulteriormente a causa dei continui tagli dei fondi. L\u2019associazione Codici ha lanciato la campagna \u201cIndigniamoci!\u201d, che coinvolge tutti gli Sportelli presenti sul territorio nazionale per raccogliere le segnalazioni dei pazienti e fornire assistenza.<\/p>\n\n\n\n<p>\u201cIl taglio dei fondi alla sanit\u00e0 non fa altro che peggiorare una situazione gi\u00e0 critica \u2013 dichiara Ivano Giacomelli, Segretario Nazionale di Codici \u2013. Siamo preoccupati per l\u2019impatto che queste decisioni politiche hanno sulla salute dei cittadini, in particolare dei pi\u00f9 vulnerabili. \u00c8 inaccettabile che in un Paese avanzato come l\u2019Italia, i pazienti debbano soffrire a causa di carenze organizzative e strutturali evitabili. Non solo. Visto che il Servizio Sanitario Nazionale \u00e8 destinato ad un continuo e inesorabile definanziamento, \u00e8 necessario aumentare la produttivit\u00e0, attualmente a livelli inaccettabili. Proprio in questi giorni abbiamo ricevuto una segnalazione da un cittadino romano che doveva fare un prelievo di sangue. L\u2019ambulatorio della Asl a cui si \u00e8 rivolto effettuava 30 prelievi a partire dalle 7, senza prenotazione. Nel vicino centro della Croce Rossa lo stesso servizio era aperto fino alle 11, senza limiti e pagando sempre solo il ticket. \u00c8 chiaro che cos\u00ec non va\u201d.<\/p>\n\n\n\n<p>Con la campagna \u201cIndigniamoci!\u201d l\u2019associazione Codici mette a disposizione i propri esperti e legali per fornire ai pazienti ed ai parenti delle vittime di malasanit\u00e0 una serie di servizi come: consulenze legali, psicologiche, mediche; costituzione di parte civile nei processi penali; azione civile di risarcimento danni; assistenza e consulenza per le indagini difensive. \u00c8 possibile segnalare casi di malasanit\u00e0 telefonando al numero 065571996, inviando un messaggio WhatsApp al numero 3757793480 oppure scrivendo un\u2019e-mail all\u2019indirizzo&nbsp;<a href=\"javascript:webmail.View.mailto({mailto:'segreteria.sportello@codici.org', subject: ''})\">segreteria.sportello@codici.org<\/a>.<\/p>\n\n\n\n<p>Roma, 20 marzo 2025<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/la-situazione-critica-del-servizio-sanitario-nazionale-minaccciato-dai-tagli-continui\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/la-situazione-critica-del-servizio-sanitario-nazionale-minaccciato-dai-tagli-continui\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Da Roma l\u2019Associazione dei Consumatori Codici ci manda il seguente comunicato (nella nostra foto, il ministro della Salute Orazio Schillaci) ___________ Codici: i continui tagli dei fondi minacciano il Servizio Sanitario Nazionale Il Servizio Sanitario Nazionale sta attraversando una fase di profonda crisi che rischia di aggravarsi ulteriormente a causa dei [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240875"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240875"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240875\/revisions"}],"predecessor-version":[{"id":240877,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240875\/revisions\/240877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240876"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}