{"id":240887,"date":"2025-03-20T14:19:53","date_gmt":"2025-03-20T13:19:53","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240887"},"modified":"2025-03-20T14:19:54","modified_gmt":"2025-03-20T13:19:54","slug":"giovane-di-cavallino-arrestato-per-droga-vicino-a-una-discoteca","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/giovane-di-cavallino-arrestato-per-droga-vicino-a-una-discoteca\/","title":{"rendered":"GIOVANE DI CAVALLINO ARRESTATO PER DROGA VICINO A UNA DISCOTECA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"877\" height=\"696\" class=\"wp-image-240890\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103825_Stupefacenti-GruppoLE_2-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103825_Stupefacenti-GruppoLE_2-1.jpg 877w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103825_Stupefacenti-GruppoLE_2-1-300x238.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103825_Stupefacenti-GruppoLE_2-1-768x609.jpg 768w\" sizes=\"(max-width: 877px) 100vw, 877px\" \/><\/p>\n\n\n\n<p>Report del Comando Provinciale della Guardia di Finanza di Lecce ___________<\/p>\n\n\n\n<p>Nell\u2019ambito dell\u2019intensificazione dei servizi di controllo economico del territorio, i Finanzieri del<br>Comando Provinciale di Lecce hanno svolto, nel capoluogo salentino, mirate attivit\u00e0 finalizzate a<br>contrastare il diffuso fenomeno dello spaccio e del consumo di sostanze stupefacenti, con particolare attenzione ai principali luoghi di attrazione per i giovani.<\/p>\n\n\n\n<p><br>In tale contesto, nei giorni scorsi, durante un posto di controllo nei pressi di una discoteca del<br>capoluogo, le unit\u00e0 specializzate \u2018Baschi Verdi\u2019 del Gruppo della Guardia di Finanza di Lecce hanno sottoposto a controllo un\u2019autovettura con a bordo due soggetti salentini, uno dei quali, il passeggero, tentava invano di disfarsi di 8 dosi preconfezionate di \u2018cocaina\u2019.<\/p>\n\n\n\n<p><br>Venivano, pertanto, estese le attivit\u00e0 di perquisizione presso l\u2019abitazione del soggetto trovato in<br>possesso dello stupefacente, dove venivano rinvenute ulteriori 30 dosi di cocaina, 9 di hashish e 33 di marijuana, confezionate per diversa tipologia e peso, un bilancino di precisione e circa 1.800 euro in contanti, presumibilmente provento dell\u2019attivit\u00e0 di spaccio, il tutto sottoposto a vincolo penale.<\/p>\n\n\n\n<p>Il soggetto, sentito il Pubblico Ministero di turno presso la Procura della Repubblica di Lecce, veniva tratto agli arresti domiciliari per ipotesi di spaccio di sostanze stupefacenti, nonch\u00e9 violenza e minaccia a pubblico ufficiale, mentre il conducente dell\u2019auto veniva segnalato, in stato di libert\u00e0, per porto abusivo di arma bianca atta ad offendere.<\/p>\n\n\n\n<p><br>L\u2019operazione rientra nel pi\u00f9 ampio dispositivo di contrasto ai traffici illeciti messo a punto dalla Guardia di Finanza di Lecce ed evidenzia il costante impegno delle Fiamme Gialle nell\u2019azione di repressione della commercializzazione e dell\u2019utilizzo di sostanze stupefacenti, per la salvaguardia della legalit\u00e0 e la tutela della salute dei cittadini.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1464\" height=\"898\" class=\"wp-image-240888\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103752_Stupefacenti-GruppoLE_1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103752_Stupefacenti-GruppoLE_1.jpg 1464w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103752_Stupefacenti-GruppoLE_1-300x184.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103752_Stupefacenti-GruppoLE_1-1024x628.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/19032025_103752_Stupefacenti-GruppoLE_1-768x471.jpg 768w\" sizes=\"(max-width: 1464px) 100vw, 1464px\" \/> __________<\/p>\n\n\n\n<p>AGGIORNAMENTO della redazione di leccecronaca.it<\/p>\n\n\n\n<p>La persona arrestata \u00e8 Sandro Colaci, 34 anni, di Cavallino.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/giovane-di-cavallino-arrestato-per-droga-vicino-a-una-discoteca\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/20\/giovane-di-cavallino-arrestato-per-droga-vicino-a-una-discoteca\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report del Comando Provinciale della Guardia di Finanza di Lecce ___________ Nell\u2019ambito dell\u2019intensificazione dei servizi di controllo economico del territorio, i Finanzieri delComando Provinciale di Lecce hanno svolto, nel capoluogo salentino, mirate attivit\u00e0 finalizzate acontrastare il diffuso fenomeno dello spaccio e del consumo di sostanze stupefacenti, con particolare attenzione ai principali luoghi di attrazione per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240887"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240887"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240887\/revisions"}],"predecessor-version":[{"id":240891,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240887\/revisions\/240891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240890"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}