{"id":24089,"date":"2014-02-03T12:38:05","date_gmt":"2014-02-03T12:38:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24089"},"modified":"2014-02-03T12:38:05","modified_gmt":"2014-02-03T12:38:05","slug":"sannicola-sequestro-marijuana","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/sannicola-sequestro-marijuana\/","title":{"rendered":"SANNICOLA: SEQUESTRO MARIJUANA"},"content":{"rendered":"<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div>\n<div>\n<p>\u00a0\u0096<a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lido-conchiglie-011.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lido-conchiglie-011-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-24090\" \/><\/a>Nell\u0092ambito del consueto controllo del territorio la Polizia Locale di Sannicola ha rinvenuto e sequestrato, in un lotto di terreno incolto, in pieno centro storico, a pochi metri da P.za della Repubblica, 130 grammi di marijuana.<\/p>\n<p>La marijuana era stata confezionata in circa 20 panetti, alcuni da 10 grammi e altri da 2 grammi ciascuno, i primi probabilmente destinati ad essere ceduti ad altri spacciatori e i secondi destinati allo spaccio al dettaglio.<\/p>\n<p>La droga era stata nascosta in barattoli di vetro occultati all\u0092interno di uno zaino nero.<\/p>\n<p>La sostanza stupefacente sequestrata avrebbe fruttato nella vendita circa 1.000 euro.<\/p>\n<p>Le conseguenti operazioni di polizia giudiziaria sono state effettuate unitamente alla Guardia di Finanza di Gallipoli.<\/p>\n<p>La Polizia Locale di Sannicola ha avviato le opportune indagini al fine di accertare la provenienza dello stupefacente ed individuare il detentore della sostanza ed i destinatari della stessa.<\/p>\n<p>&nbsp;<\/p>\n<p>N. 2 foto in allegato.<\/p>\n<p>&nbsp;<\/p>\n<p>F.to il Comandante<\/p>\n<p>Ten. Dott.ssa Maria Elena Marti<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div dir=\"ltr\">\n<form><\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/sannicola-sequestro-marijuana\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/sannicola-sequestro-marijuana\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00a0\u0096Nell\u0092ambito del consueto controllo del territorio la Polizia Locale di Sannicola ha rinvenuto e sequestrato, in un lotto di terreno incolto, in pieno centro storico, a pochi metri da P.za della Repubblica, 130 grammi di marijuana. La marijuana era stata confezionata in circa 20 panetti, alcuni da 10 grammi e altri da 2 grammi ciascuno, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24090,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24089"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24089"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24089\/revisions"}],"predecessor-version":[{"id":24091,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24089\/revisions\/24091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24090"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}