{"id":24095,"date":"2014-02-03T14:00:23","date_gmt":"2014-02-03T14:00:23","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24095"},"modified":"2014-02-03T14:00:40","modified_gmt":"2014-02-03T14:00:40","slug":"le-foibe-conoscere-per-capire-e-poi-ricordare","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-conoscere-per-capire-e-poi-ricordare\/","title":{"rendered":"LE FOIBE: CONOSCERE PER CAPIRE PER POI RICORDARE"},"content":{"rendered":"<table width=\"750\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#336699\" width=\"250\" height=\"0\"><\/td>\n<td>\n<p align=\"center\"><img decoding=\"async\" loading=\"lazy\" border=\"0\" src=\"http:\/\/www.lefoibe.it\/logo45.gif\" width=\"461\" height=\"152\" \/><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#FFFFFF\" width=\"250\">LE FOIBE<\/td>\n<td bgcolor=\"#336699\">le foibe &#8211; attualit\u00e0<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" bgcolor=\"#336699\" width=\"250\">\n<div><a href=\"http:\/\/www.lefoibe.it\/attualita.htm\">Attualit\u00e0<\/a><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul>\n<li><a href=\"http:\/\/www.lefoibe.it\/approfondimenti.htm\">Approfondimenti<\/a><\/li>\n<li><a href=\"http:\/\/www.lefoibe.it\/storie.htm\">Storia e Storie<\/a><\/li>\n<li><a href=\"http:\/\/www.lefoibe.it\/articoli.htm\">Articoli<\/a><\/li>\n<li><a href=\"http:\/\/www.lefoibe.it\/links.htm\">Altri siti<\/a><\/li>\n<li><a href=\"http:\/\/www.lefoibe.it\/online.htm\">Rassegna stampa online<\/a><\/li>\n<li><a href=\"http:\/\/www.foibadibasovizza.it\/\" target=\"_blank\">Foiba di Basovizza<\/a><\/li>\n<\/ul>\n<p><strong>Intervista all&#8217;Avv. Randazzo: &#8220;Ecco perch\u00e9 il boia delle foibe prende la pensione dallo Stato italiano&#8221;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: Verdana;font-size: xx-small\"><strong><\/strong>L&#8217;opinione 04\/08\/05<\/span><\/p>\n<p>L&#8217;avvocato penalista racconta dei tanti privilegi di cui godono gli assassini comunisti di Tito<\/p>\n<p><strong>Intervista all&#8217;Avv. Randazzo: &#8220;Ecco perch\u00e9 il boia delle foibe prende la pensione dallo Stato italiano&#8221; di Ruggiero Capone<\/strong><\/p>\n<p>&#8220;La giustizia \u00e8 come una tela di ragno: trattiene gli insetti piccoli, mentre i grandi trafiggono la tela e restano liberi&#8221;, questa frase di Solone (fondatore della democrazia ateniese, arconte che nel 594-593 avvi\u00f2 riforme, e primo poeta ad usare la lingua attica pregna d&#8217;omerismi) \u00e8 stata scelta dall&#8217;avvocato Luciano Randazzo perch\u00e9 sintesi di quanto avverrebbe nelle procure italiane ed in ogni palazzo pubblico del potere. Cos\u00ec Randazzo (vice segretario politico di Italia Moderata) ha tenuto nel suo studio una conferenza stampa, per acclarare che sono stati archiviati gli esposti presentati contro di lui da Oskar Piskulic (tra i maggiori autori del genocidio delle Foibe). L&#8217;opinione lo ha intervistato.<\/p>\n<p>&#8211; Piskulic ed altri autori di stragi impunite sono vivi e vegeti e trovano anche la forza di reagire contro chi chiede che vengano processati. Cosa ha dato loro la sicurezza di farla franca e di poter anche attaccare chi denuncia il loro operato?<\/p>\n<p>Per 60 lungi anni hanno goduto di protezioni politiche italiana. E questo ha dato a Piskulic la sicumera sufficiente a pensare di poter chiedere all&#8217; ordine degli avvocati di Roma misure punitive contro di me e l&#8217;avvocato Augusto Sinagra. E perch\u00e9 avremmo, secondo il partigiano titino Piskulic, vilipeso la Repubblica ed il governo italiano difendendo le vittime delle Foibe nell&#8217;udienza preliminare, tenutasi il 15 marzo 2000 innanzi ai giudici del tribunale di Roma Roberto Reali e Giuseppe Petitto. Di fatto Piskulic ed i suoi sodali sono assurti, in forza di certa propaganda comunista, ad eroi ed intoccabili, e non hanno sopportato che avessimo chiesto la loro incriminazione per il genocidio 30 mila istriani e per il conseguente esodo di oltre 300 mila italiani dalmati. Addirittura certi partiti politici e certe sigle sindacali li hanno spacciati per eroi della resistenza.<\/p>\n<p>&#8211; Che intende dire?<\/p>\n<p>Che ai capi partigiani titini di nazionalit\u00e0 slava l&#8217;Italia paga laute pensioni, in alcuni casi sono corrisposte mensilmente e procapite pensioni di oltre 3000 euro, perch\u00e9 alcuni di loro sono stati spacciati come alti dirigenti in pensione d&#8217;un noto sindacato italiano. Piskulic la percepisce ancora lui personalmente, ma nei casi di decesso c&#8217;\u00e8 stata una reversibilit\u00e0 della stessa a favore di giovani donne jugoslave sposatesi con gli infoibatori negli anni &#8217;90.<\/p>\n<p>&#8211; E l&#8217;ordine degli avvocati come s&#8217;\u00e8 comportato?<\/p>\n<p>Ha archiviato il procedimento a carico mio e dell&#8217;avvocato Sinagra, e perch\u00e9 i consiglieri dell&#8217;ordine hanno ben compreso quanto fosse fuori luogo l&#8217; accusa mossa dall&#8217;infoibatore. A quest&#8217;ultimo, tra l&#8217;altro, lo stato italiano ha pagato persino la difesa. Piskulic non \u00e8 un caso isolato, negli ultimi anni non pochi brigatisti hanno gabbato lo stato italiano.<\/p>\n<p>&#8211; E le persone indifese che fine fanno?<\/p>\n<p>La signora Sabrina Pietrolongo \u00e8 stata messa sotto i riflettori della trasmissione televisiva &#8220;Un giorno in pretura&#8221;, edizione dell&#8217;11 marzo 2004, ed il Garante per la protezione dei dati personali, in data 7 luglio 2005, ha censurato il programma di Rai Tre. Quindi ha intimato che le immagini relative alla mia assistita non siano nuovamente mandate in onda e, poi, ha inviato il provvedimento al Consiglio regionale e nazionale dell&#8217;Ordine dei giornalisti, perch\u00e9 vengano assunti provvedimenti contro il conduttore e gli autori. Questi ultimi hanno strumentalizzato il legame affettivo che c&#8217;era stato tra la mia cliente ed un imputato d&#8217;omicidio. Credo che in nessuna nazione civile sia consentito quest&#8217;uso spregiudicato della professione, e per dappi\u00f9 da un canale pubblico.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-conoscere-per-capire-e-poi-ricordare\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/03\/le-foibe-conoscere-per-capire-e-poi-ricordare\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>LE FOIBE le foibe &#8211; attualit\u00e0 Attualit\u00e0 Approfondimenti Storia e Storie Articoli Altri siti Rassegna stampa online Foiba di Basovizza Intervista all&#8217;Avv. Randazzo: &#8220;Ecco perch\u00e9 il boia delle foibe prende la pensione dallo Stato italiano&#8221; &nbsp; L&#8217;opinione 04\/08\/05 L&#8217;avvocato penalista racconta dei tanti privilegi di cui godono gli assassini comunisti di Tito Intervista all&#8217;Avv. Randazzo: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24095"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24095"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24095\/revisions"}],"predecessor-version":[{"id":24097,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24095\/revisions\/24097"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}