{"id":240973,"date":"2025-03-22T12:30:27","date_gmt":"2025-03-22T11:30:27","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=240973"},"modified":"2025-03-22T12:30:29","modified_gmt":"2025-03-22T11:30:29","slug":"il-reparto-prevenzione-crimine-di-lecce-non-chiudera-la-soddisfazione-e-i-ringraziamenti-del-sindacato-polizia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/22\/il-reparto-prevenzione-crimine-di-lecce-non-chiudera-la-soddisfazione-e-i-ringraziamenti-del-sindacato-polizia\/","title":{"rendered":"&#8220;Il Reparto Prevenzione Crimine di Lecce non chiuder\u00e0&#8221;. LA SODDISFAZIONE E I RINGRAZIAMENTI DEL SINDACATO POLIZIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1220\" height=\"1838\" class=\"wp-image-240974\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP.jpg 1220w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP-199x300.jpg 199w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP-680x1024.jpg 680w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP-768x1157.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/03\/SIAP-1020x1536.jpg 1020w\" sizes=\"(max-width: 1220px) 100vw, 1220px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. Il <strong>Sindacato Italiano Appartenenti Polizia<\/strong> &#8211; <strong>Segreteria Provinciale di Lecce<\/strong> &#8211; ci manda il seguente comunicato __________<\/p>\n\n\n\n<p>In riferimento alla vicenda del Reparto Prevenzione Crimine di Lecce<\/p>\n\n\n\n<p>Desidero esprimere, a nome mio e dell\u2019intera Segreteria Provinciale SIAP di Lecce, grande soddisfazione per l\u2019esito positivo conseguito in merito alla paventata chiusura del Reparto Prevenzione Crimine di Lecce ed un particolare Ringraziamento al Presidente Nazionale del SIAP, Dott. Francesco Tiani per tutta la determinazione e la lungimiranza operativa volta alla risoluzione dell\u2019annosa vicenda.<\/p>\n\n\n\n<p>L\u2019attenzione mediatica e la significativa pressione istituzionale esercitata nelle ultime settimane, cui abbiamo contribuito in maniera determinata e convinta, hanno prodotto un risultato di straordinaria rilevanza: il Ministero dell\u2019Interno, nella giornata di ieri, ha ufficialmente rivisto la propria posizione, scongiurando la soppressione non solo del Reparto di Lecce, ma dell\u2019intero assetto dei Reparti Prevenzione Crimine operanti in Puglia e in altre aree strategiche del Paese.<\/p>\n\n\n\n<p>Un passo indietro che \u00e8, in realt\u00e0, un grande passo avanti per la sicurezza dei territori, per la dignit\u00e0 professionale delle donne e degli uomini della Polizia di Stato, e per l\u2019interesse generale delle nostre comunit\u00e0.<\/p>\n\n\n\n<p>Colgo l\u2019occasione per rivolgere un sentito ringraziamento a tutte e tutti coloro che, a vario titolo, hanno sostenuto questa battaglia: colleghi, rappresentanti istituzionali ed alle associazioni Insieme abbiamo dimostrato che, quando si fa rete nel rispetto dei ruoli e delle funzioni, si possono raggiungere traguardi significativi a tutela del Sud e dei suoi contesti pi\u00f9 esposti.<\/p>\n\n\n\n<p>Il Reparto Prevenzione Crimine di Lecce non chiuder\u00e0. Ma soprattutto, oggi si afferma il principio che la sicurezza non pu\u00f2 essere oggetto di meri calcoli numerici o logiche di razionalizzazione cieca. La sicurezza \u00e8 un diritto e va garantita, con visione, rispetto e responsabilit\u00e0.<\/p>\n\n\n\n<p>Lecce 21 Marzo 2025<\/p>\n\n\n\n<p><strong>Gianluigi CASCIARO<\/strong><\/p>\n\n\n\n<p><strong>Segretario Generale Provinciale SIAP Lecce<\/strong><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/22\/il-reparto-prevenzione-crimine-di-lecce-non-chiudera-la-soddisfazione-e-i-ringraziamenti-del-sindacato-polizia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/03\/22\/il-reparto-prevenzione-crimine-di-lecce-non-chiudera-la-soddisfazione-e-i-ringraziamenti-del-sindacato-polizia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Il Sindacato Italiano Appartenenti Polizia &#8211; Segreteria Provinciale di Lecce &#8211; ci manda il seguente comunicato __________ In riferimento alla vicenda del Reparto Prevenzione Crimine di Lecce Desidero esprimere, a nome mio e dell\u2019intera Segreteria Provinciale SIAP di Lecce, grande soddisfazione per l\u2019esito positivo conseguito in merito alla paventata chiusura del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":240974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240973"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=240973"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240973\/revisions"}],"predecessor-version":[{"id":240975,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/240973\/revisions\/240975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/240974"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=240973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=240973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=240973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}