{"id":241603,"date":"2025-04-06T11:36:33","date_gmt":"2025-04-06T09:36:33","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=241603"},"modified":"2025-04-06T11:36:36","modified_gmt":"2025-04-06T09:36:36","slug":"novita-discografiche-paradiso-di-notte-nuovo-singolo-dellartista-salentina-io-sottoscritta-video","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/06\/novita-discografiche-paradiso-di-notte-nuovo-singolo-dellartista-salentina-io-sottoscritta-video\/","title":{"rendered":"NOVITA&#8217; DISCOGRAFICHE \/ &#8220;Paradiso di notte&#8221;, NUOVO SINGOLO DELL&#8217;ARTISTA SALENTINA IO SOTTOSCRITTA &#8211; video"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"961\" height=\"1280\" class=\"wp-image-241604\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/coverla.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/coverla.jpeg 961w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/coverla-225x300.jpeg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/coverla-769x1024.jpeg 769w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/coverla-768x1023.jpeg 768w\" sizes=\"(max-width: 961px) 100vw, 961px\" \/><\/p>\n\n\n\n<p>Nota stampa di Eleonora L. Moscara _______<\/p>\n\n\n\n<p>&#8220;Paradiso di notte&#8221;: il nuovo singolo de La sottoscritta esplora le ombre dell&#8217;amore, con la partecipazione straordinaria di Mylious Johnson alla batteria<\/p>\n\n\n\n<p>&#8220;Paradiso di notte&#8221;, il nuovo singolo della cantautrice salentina La sottoscritta (alias Francesca Falcone), disponibile a partire da oggi 6 aprile su tutte le piattaforme digitali e in streaming, accompagnato da un suggestivo videoclip su YouTube (link:\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/youtu.be\/U9bkL3Ntmg4\" target=\"_blank\">https:\/\/youtu.be\/U9bkL3Ntmg4<\/a>).\u00a0<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1011\" height=\"900\" class=\"wp-image-241605\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/centrola.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/centrola.jpeg 1011w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/centrola-300x267.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/centrola-768x684.jpeg 768w\" sizes=\"(max-width: 1011px) 100vw, 1011px\" \/><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il brano, anticipato da un&#8217;esclusiva anteprima live il 5 aprile presso &#8220;Fossi&#8221; a Otranto, alle ore 21.00, affronta tematiche profonde come il sacrificio di s\u00e9 e la consapevolezza di ricadere in dinamiche autodistruttive, simboleggiate dalla figura di &#8220;Lucifero&#8221;. &#8220;Paradiso di notte&#8221; \u00e8 un brano intenso e introspettivo, caratterizzato da un sound che spazia dal pop al rock, con influenze elettroniche e dream pop.\u00a0<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La produzione, curata da Luigi Russo presso Il Cantiere Laboratorio Musicale (Cutrofiano, LE), vede la partecipazione di musicisti di spicco come Mylious Johnson alla batteria, musicista di fama internazionale che ha collaborato con artisti del calibro di Madonna, Jovanotti e Tiziano Ferro e Marco Palumbo al basso. Il videoclip, diretto da Alessio Vetrano e Cristian Scarciglia, \u00e8 stato girato nell&#8217;Ex convento dei Frati Minori Francescani di Veglie (LE), in particolare nella Chiesa dedicata a Santa Maria di Veglie. Le riprese, che vedono la partecipazione di Francesca Falcone e Luca Negro come interpreti principali, insieme a un nutrito gruppo di comparse, creano un&#8217;atmosfera suggestiva e coinvolgente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Francesca Falcone, in arte La sottoscritta, \u00e8 una cantautrice e polistrumentista salentina con un background musicale eclettico. Nata il 23 ottobre 2000, ha iniziato a studiare chitarra all&#8217;et\u00e0 di 13 anni, per poi diplomarsi al liceo musicale E. Giannelli di Parabita e proseguire gli studi di Chitarra Jazz presso il Conservatorio Tito Schipa di Lecce. Oltre alla sua attivit\u00e0 di cantautrice, Francesca \u00e8 un&#8217;insegnante di chitarra e una musicista attiva in diverse formazioni, tra cui l&#8217;orchestra Li UcciOrkestra. Ha collaborato con artisti di fama internazionale come Mylious Johnson e ha aperto concerti di artisti come Franco Simone e Gianluca Grignani. <\/p>\n\n\n\n<p>&#8220;Paradiso di notte&#8221; rappresenta un nuovo capitolo nel percorso artistico de &#8220;La sottoscritta&#8221;, un&#8217;artista che continua a stupire con la sua versatilit\u00e0 e la sua capacit\u00e0 di esplorare sonorit\u00e0 diverse, senza mai perdere la propria identit\u00e0.<\/p>\n\n\n\n<p>Link utili:<\/p>\n\n\n\n<p>Instagram:&nbsp;<a href=\"https:\/\/www.instagram.com\/lasottoscritta__\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/lasottoscritta__\/<\/a><\/p>\n\n\n\n<p>Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/francesca.falcone.23\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/francesca.falcone.23<\/a><\/p>\n\n\n\n<p>Apple Music:&nbsp;<a href=\"https:\/\/music.apple.com\/us\/artist\/1631549166\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/music.apple.com\/us\/artist\/1631549166<\/a><\/p>\n\n\n\n<p>Videoclip:&nbsp;<a href=\"https:\/\/youtu.be\/U9bkL3Ntmg4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/youtu.be\/U9bkL3Ntmg4<\/a><\/p>\n\n\n\n<p>Testo e musica: Francesca Falcone, Luigi Russo<\/p>\n\n\n\n<p>Batteria: Mylious Johnson<\/p>\n\n\n\n<p>Basso: Marco Palumbo<\/p>\n\n\n\n<p>Produzione, mix e master: Luigi Russo (Il Cantiere Laboratorio Musicale &#8211; Cutrofiano &#8211; LE)<\/p>\n\n\n\n<p>Regia, riprese e montaggio video: Alessio Vetrano, Cristian Scarciglia<\/p>\n\n\n\n<p>Interpreti: Francesca Falcone, Luca Negro<\/p>\n\n\n\n<p>Comparse: Eva Croce, Elettra Savina, Lorena De Luca, Giorgia Spagnolo, Valentina Rapan\u00e0, Valentina D\u2019Urso, Lara De Donatis, Claudio Vincenti<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1600\" class=\"wp-image-241606\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola.jpeg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-300x300.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-1024x1024.jpeg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-150x150.jpeg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-768x768.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-1536x1536.jpeg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/fondola-60x60.jpeg 60w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/06\/novita-discografiche-paradiso-di-notte-nuovo-singolo-dellartista-salentina-io-sottoscritta-video\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/06\/novita-discografiche-paradiso-di-notte-nuovo-singolo-dellartista-salentina-io-sottoscritta-video\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nota stampa di Eleonora L. Moscara _______ &#8220;Paradiso di notte&#8221;: il nuovo singolo de La sottoscritta esplora le ombre dell&#8217;amore, con la partecipazione straordinaria di Mylious Johnson alla batteria &#8220;Paradiso di notte&#8221;, il nuovo singolo della cantautrice salentina La sottoscritta (alias Francesca Falcone), disponibile a partire da oggi 6 aprile su tutte le piattaforme digitali [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":241604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241603"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=241603"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241603\/revisions"}],"predecessor-version":[{"id":241607,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241603\/revisions\/241607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/241604"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=241603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=241603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=241603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}