{"id":24167,"date":"2014-02-04T15:30:12","date_gmt":"2014-02-04T15:30:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24167"},"modified":"2014-02-04T15:30:12","modified_gmt":"2014-02-04T15:30:12","slug":"inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/04\/inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish\/","title":{"rendered":"INSEGUIMENTO E ARRESTI SULLA SS 101: 1,5 KG. DI HASHISH"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-24167 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/04\/inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish\/oltremarini-alessandro\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/OLTREMARINI-ALESSANDRO-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/04\/inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish\/serra-fabrizio\/'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/SERRA-FABRIZIO-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Alle ore 17.20 circa del 3 febbraio 2014, durante un normale posto di controllo sulla SS.101 in direzione Gallipoli, una dipendente pattuglia dell\u2019Aliquota Radiomobile intimava l\u2019ALT ad un furgone Fiat Iveco di colore azzurro. Nella circostanza il conducente del mezzo mostrava titubanza ad arrestare la marcia, e dopo un primo momento durante il quale sembrava che stesse per accostare, ripartiva repentinamente a fortissima velocit\u00e0. A quel punto, ne scaturiva un breve inseguimento, nel corso del quale l\u2019autoradio, postasi immediatamente all\u2019inseguimento, affiancava il furgone in fuga, che in pi\u00f9 riprese tentava di buttarla fuoristrada, non riuscendovi grazie all\u2019abilit\u00e0 del militare autista. All\u2019inseguimento si aggiungeva quindi un\u2019altra autoradio, giunta nell\u2019immediatezza in supporto. Durante l\u2019inseguimento, i militari notavano lanciare dal finestrino lato passeggero del furgone un involucro di piccole dimensioni e di colore scuro. Cos\u00ec, mentre il secondo equipaggio si arrestava subito nel punto in cui era stato gettato il primo pacchetto, il primo continuava l\u2019inseguimento per ulteriori 500 metri, vedendo volare sempre dal finestrino del furgone un secondo pacchetto uguale al primo, riuscendo quindi finalmente ad affiancare e bloccare il furgone, dopo che questo aveva posto in essere manovre pericolose viaggiando a forte a velocit\u00e0, effettuando manovre spericolate cercando di buttare ripetutamente fuori strada le autoradio. Si procedeva quindi all\u2019identificazione del conducente del furgone e del passeggero, rispettivamente identificati in:<\/p>\n<p>&#8211; SERRA Fabrizio, 30enne di Taviano (LE), con precedenti di polizia,<\/p>\n<p>&#8211; OLTREMARINI Alessandro, 28enne di Gallipoli (LE), con precedenti di polizia.<\/p>\n<p>Nonostante la sopraggiunta oscurit\u00e0, la pioggia e la fitta vegetazione sottostante la strada, con l\u2019ausilio sia del Nucleo Investigativo del Comando Provinciale Carabinieri di Lecce che del Nucleo Cinofili della Guardia di Finanza di Lecce con il cane antidroga Valex, e grazie all\u2019intervento di mezzi e personale dei Vigili del Fuoco di Lecce muniti di fari per illuminare l\u2019ambiente, si riuscivano a recuperare gli involucri nei punti ove erano stati lanciati dagli occupanti del furgone, che sono risultati contenere 13 panetti di hashish confezionati in cellophane, per un peso complessivo di circa kg. 1,300. Inoltre, nelle successive perquisizioni personali e domiciliari, venivano rinvenuti addosso all\u2019OLTREMARINI altri 3 grammi di hashish e la somma contante di 400 euro, nonch\u00e9 10 grammi di marijuana custoditi sempre dall\u2019OLTREMARINI presso la sua abitazione. Per i suddetti motivi SERRA Fabrizio e OLTREMARINI Alessandro venivano tratti in arresto per \u201cdetenzione a fini di spaccio di sostanza stupefacente\u201d, nonch\u00e9 per il reato di \u201cresistenza a pubblico ufficiale\u201d per aver cercato, durante la fuga con il furgone, di speronare le auto dei Carabinieri. Al termine degli accertamenti, SERRA e OLTREMARINI, difesi rispettivamente dagli avvocati Biagio PALAMA\u2019 e Angelo NINNI, sono stati associati presso la Casa Circondariale di Lecce su disposizione del magistrato di turno presso la Procura di Lecce, Dott.ssa Carmen RUGGIERO.<\/p>\n<p align=\"center\"><em>\u00a0<\/em><\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<p align=\"center\"><em>\u00a0<\/em><\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<p align=\"center\"><em><br \/>\n<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/04\/inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/04\/inseguimento-e-arresti-sulla-ss-101-15-kg-di-hashish\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Alle ore 17.20 circa del 3 febbraio 2014, durante un normale posto di controllo sulla SS.101 in direzione Gallipoli, una dipendente pattuglia dell\u2019Aliquota Radiomobile intimava l\u2019ALT ad un furgone Fiat Iveco di colore azzurro. Nella circostanza il conducente del mezzo mostrava titubanza ad arrestare la marcia, e dopo un primo momento durante il quale sembrava [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24167"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24167"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24167\/revisions"}],"predecessor-version":[{"id":24170,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24167\/revisions\/24170"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}