{"id":241822,"date":"2025-04-11T13:45:44","date_gmt":"2025-04-11T11:45:44","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=241822"},"modified":"2025-04-11T13:49:15","modified_gmt":"2025-04-11T11:49:15","slug":"brillante-operazione-antidroga-della-polizia-di-stato-al-rione-castromediano-in-carcere-leccese","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/11\/brillante-operazione-antidroga-della-polizia-di-stato-al-rione-castromediano-in-carcere-leccese\/","title":{"rendered":"BRILLANTE OPERAZIONE ANTIDROGA DELLA POLIZIA DI STATO AL RIONE  CASTROMEDIANO, IN CARCERE LECCESE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"666\" class=\"wp-image-241823\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/resize.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/resize.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/resize-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/resize-768x511.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>(e.l.) ________ Ieri sera agenti della Polizia di Stato hanno arrestato in flagranza di reato Alessandro Sariconi, 46 anni,, di Lecce, con precedenti specifici di spaccio di sostanze stupefacenti.<\/p>\n\n\n\n<p>Si trova ora nel carcere di Borgo San Nicola, come disposto dal pm di turno presso la Procura della Repubblica.<\/p>\n\n\n\n<p>L\u2019arresto \u00e8 avvenuto nell\u2019ambito di un&#8217;attivit\u00e0 di controllo del territorio del rione Castromediano.<\/p>\n\n\n\n<p> Durante un servizio di osservazione, gli agenti hanno notato l&#8217;uomo uscire da un\u2019abitazione e salire a bordo di un\u2019autovettura condotta da un altro. L\u2019atteggiamento dei due ha insospettito gli operatori, che hanno deciso di procedere a un pedinamento e successivamente a un controllo del veicolo in via Francesco Camassa.<\/p>\n\n\n\n<p>Durante il controllo, il passeggero consegnava spontaneamente un involucro contenente cocaina e una somma di denaro in contanti pari a 4.200 euro, suddivisa in banconote di vario taglio. Alla luce dei fatti e dei precedenti riscontrari a carico del Sariconi, i poliziotti procedevano a una perquisizione personale e domiciliare.<\/p>\n\n\n\n<p>Nel corso della perquisizione personale, venivano rinvenuti, occultati negli indumenti intimi, diversi involucri contenenti sostanza stupefacente del tipo cocaina per un peso complessivo lordo di circa 44 grammi. La successiva perquisizione domiciliare consentiva di rinvenire ulteriori quantitativi di cocaina, per un totale quasi 100 grammi, sostanza da taglio per oltre 66 grammi, un bilancino elettronico intriso di polvere bianca e materiale per il confezionamento delle dosi.<\/p>\n\n\n\n<p>L\u2019operazione si inserisce in un pi\u00f9 ampio piano di contrasto allo spaccio di sostanze stupefacenti, condotto dalla Polizia di Stato con costante impegno sul territorio, volto a garantire la sicurezza dei cittadini e il rispetto della legalit\u00e0.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"707\" class=\"wp-image-241825\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/foto-materiale-sequestrato.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/foto-materiale-sequestrato.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/foto-materiale-sequestrato-300x236.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/foto-materiale-sequestrato-768x603.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/11\/brillante-operazione-antidroga-della-polizia-di-stato-al-rione-castromediano-in-carcere-leccese\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/11\/brillante-operazione-antidroga-della-polizia-di-stato-al-rione-castromediano-in-carcere-leccese\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ________ Ieri sera agenti della Polizia di Stato hanno arrestato in flagranza di reato Alessandro Sariconi, 46 anni,, di Lecce, con precedenti specifici di spaccio di sostanze stupefacenti. Si trova ora nel carcere di Borgo San Nicola, come disposto dal pm di turno presso la Procura della Repubblica. L\u2019arresto \u00e8 avvenuto nell\u2019ambito di un&#8217;attivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":241823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241822"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=241822"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241822\/revisions"}],"predecessor-version":[{"id":241826,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/241822\/revisions\/241826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/241823"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=241822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=241822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=241822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}