{"id":242028,"date":"2025-04-16T17:14:39","date_gmt":"2025-04-16T15:14:39","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242028"},"modified":"2025-04-18T11:24:13","modified_gmt":"2025-04-18T09:24:13","slug":"diamo-il-premio-pulitzer-a-questa-foto-di-struggente-bellezza","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/16\/diamo-il-premio-pulitzer-a-questa-foto-di-struggente-bellezza\/","title":{"rendered":"DATE IL PREMIO PULITZER A QUESTA FOTO DI DRAMMATICA BELLEZZA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"611\" height=\"382\" class=\"wp-image-242045\" style=\"width: 2500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/486620263_10236981041693578_1590063204698937474_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/486620263_10236981041693578_1590063204698937474_n.jpg 611w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/486620263_10236981041693578_1590063204698937474_n-300x188.jpg 300w\" sizes=\"(max-width: 611px) 100vw, 611px\" \/><\/p>\n\n\n\n<p>di <strong>Giuseppe Puppo ___________<\/strong><\/p>\n\n\n\n<p>&#8220;Slopping dall&#8217;acciaieria2 dell&#8217;ex Ilva Acciaierie d&#8217;Italia in questi minuti, 11.40 del 16 aprile 2025&#8221; <\/p>\n\n\n\n<p>&#8211; dice Luciano Manna, giornalista d&#8217;inchiesta, postando questa foto sul suo diario di Facebook, e aggiunge: <\/p>\n\n\n\n<p>&#8220;Spero che questo episodio sia citato da tutti i candidati a sindaco di Taranto, perch\u00e9 al di l\u00e0 delle vedute e delle politiche penso che sia dediderio comune e di tutti non sottostare ancora nel 2025 a episodi di inquinamento come questo che a Genova erano proibiti e banditi gi\u00e0 venti  anni fa, mentre a Taranto continuano indisturbati ed impuniti a generare un serio danno sanitario e la contaminazione della catena alimentare&#8221;. ______<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La fuoriuscita di gas e nubi rossastre dal siderurgico (<em>slopping<\/em>) \u00e8 un fenomeno documentato negli anni  dai periti chimici e dal nucleo specializzato dei Carabinieri. <\/p>\n\n\n\n<p>Lo slopping produce diossina, produce veleno, che si accumula nell&#8217;aria, nel terreno, nei polmoni e nei cervelli dei Tarantini e di quelli che abitano vicino, fino a un raggio di ottanta chilometri<\/p>\n\n\n\n<p>.<\/p>\n\n\n\n<p>A Taranto, citt\u00e0 bellissima e sfortunatissima, si voter\u00e0 il 25 maggio prossimo.<\/p>\n\n\n\n<p>Chiunque vinca, al di l\u00e0 delle belle, a volte, ipocrite, altre, comunque inutili intenzioni dei candidati a sindaco, vincer\u00e0 ancora una volta il Mostro, che continuer\u00e0 ad avvelenare e a uccidere, protetto dai vari decreti &#8216;salva Ilva&#8217; di tutti i governi nazionali che si sono fin qui succeduti.<\/p>\n\n\n\n<p>Ma a questa foto bisognerebbe assegnare il premio Pulitzer. Nei Musei, bisognerebbe esporla, a cominciare dal Marta di Taranto appunto, che di cultura potrebbe vivere, invece di morire di acciaio.<\/p>\n\n\n\n<p>Tutto l&#8217;acciaio del mondo non vale quanto la vita di un solo bambino.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>C&#8217;\u00e8 tanto di terribilmente affascinante, molto di drammaticamente suggestivo, in questa foto. E&#8217; c&#8217;\u00e8 pure sottintesa una speranza: che la nostra Grande Madre della Natura, in lotta quotidiana contro le offese del profitto, dei ricatti occupazionali, delle logiche delle multinazionali dell&#8217;alta finanza internazionale, possa prima o poi, da sola, in un modo o nell&#8217;altro, prevalere.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/16\/diamo-il-premio-pulitzer-a-questa-foto-di-struggente-bellezza\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/16\/diamo-il-premio-pulitzer-a-questa-foto-di-struggente-bellezza\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo ___________ &#8220;Slopping dall&#8217;acciaieria2 dell&#8217;ex Ilva Acciaierie d&#8217;Italia in questi minuti, 11.40 del 16 aprile 2025&#8221; &#8211; dice Luciano Manna, giornalista d&#8217;inchiesta, postando questa foto sul suo diario di Facebook, e aggiunge: &#8220;Spero che questo episodio sia citato da tutti i candidati a sindaco di Taranto, perch\u00e9 al di l\u00e0 delle vedute e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242028"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242028"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242028\/revisions"}],"predecessor-version":[{"id":242057,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242028\/revisions\/242057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242045"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}