{"id":242336,"date":"2025-04-24T15:16:18","date_gmt":"2025-04-24T13:16:18","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242336"},"modified":"2025-04-24T15:16:21","modified_gmt":"2025-04-24T13:16:21","slug":"report-della-polizia-di-stato-su-chiusura-esercizio-commerciale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/report-della-polizia-di-stato-su-chiusura-esercizio-commerciale\/","title":{"rendered":"REPORT DELLA POLIZIA DI STATO SU CHIUSURA ESERCIZIO COMMERCIALE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"662\" class=\"wp-image-242337\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/QUESTUBBRI-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/QUESTUBBRI-1.jpg 1000w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/QUESTUBBRI-1-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/QUESTUBBRI-1-768x508.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\n\n\n<p>Report della Questura di Brindisi ___________<\/p>\n\n\n\n<p>A seguito di controlli della Polizia di Stato di Brindisi, il 07 aprile, il Comune di Cellino San Marco ha emesso un provvedimento amministrativo, con il quale \u00e8 stata disposta la chiusura per un periodo non inferiore a giorni 30, e comunque fino alla risoluzione della non conformit\u00e0 riscontrata, dell\u2019attivit\u00e0 di somministrazione di alimenti e bevande con annessa sala giochi riconducibile ad un esercizio pubblico del luogo.<\/p>\n\n\n\n<p>L\u2019atto amministrativo \u00e8 la diretta conseguenza dei servizi straordinari di controllo interforze a tutela dell\u2019ordine e della sicurezza pubblica disposti dal Questore Giampietro Lionetti sul territorio della provincia brindisina, effettuati nella giornata del 27.03.2025, eseguiti congiuntamente da personale della Polizia di Stato, dai Carabinieri, della Guardia di Finanza, dal Sian-ASL di Brindisi e dell\u2019Agenzia dei Monopoli di Brindisi.<\/p>\n\n\n\n<p>La conseguente attivit\u00e0 istruttoria effettuata dalla Divisione Polizia Amministrativa e di Sicurezza della Questura di Brindisi ha tenuto conto sia di evidenti e significative criticit\u00e0 in ordine alle norme riferite alla sorvegliabilit\u00e0 interna dell\u2019esercizio, con particolare riferimento ai locali destinati a sala giochi, sia della presenza, con contestuale messa a disposizione degli avventori, di un apparecchio destinato a forma di gioco non rispondente alle caratteristiche prescritte dalla norma.<\/p>\n\n\n\n<p>Le ragioni innanzi riportate sono gli indici da cui \u00e8 stata tratta la consapevolezza del titolare dell\u2019esercizio per quanto attiene la gestione dello stesso in violazione delle norme previste per le contestazioni addebitategli.<\/p>\n\n\n\n<p>Brindisi, l\u00ec 24 aprile 2025<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/report-della-polizia-di-stato-su-chiusura-esercizio-commerciale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/report-della-polizia-di-stato-su-chiusura-esercizio-commerciale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Brindisi ___________ A seguito di controlli della Polizia di Stato di Brindisi, il 07 aprile, il Comune di Cellino San Marco ha emesso un provvedimento amministrativo, con il quale \u00e8 stata disposta la chiusura per un periodo non inferiore a giorni 30, e comunque fino alla risoluzione della non conformit\u00e0 riscontrata, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242336"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242336"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242336\/revisions"}],"predecessor-version":[{"id":242338,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242336\/revisions\/242338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242337"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}