{"id":242349,"date":"2025-04-24T15:54:29","date_gmt":"2025-04-24T13:54:29","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242349"},"modified":"2025-04-24T15:54:33","modified_gmt":"2025-04-24T13:54:33","slug":"altri-sequestri-a-carico-di-presunti-esponenti-della-sacra-corona-unita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/altri-sequestri-a-carico-di-presunti-esponenti-della-sacra-corona-unita\/","title":{"rendered":"ALTRI SEQUESTRI A CARICO DI PRESUNTI ESPONENTI DELLA SACRA CORONA UNITA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"600\" class=\"wp-image-242350\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/Pistola-logo.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/Pistola-logo.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/Pistola-logo-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/Pistola-logo-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n\n<p>Report della Questura di Lecce __________<\/p>\n\n\n\n<p><strong>Sigilli a beni di lusso: rinvenuti anche soldi e una pistola, proseguono le attivit\u00e0 della Polizia di Stato<\/strong><\/p>\n\n\n\n<p>Durante l\u2019attivit\u00e0 di esecuzione delle misure patrimoniali svoltasi nella giornata di ieri, gli agenti della Questura di Lecce hanno eseguito anche delle perquisizioni domiciliari nelle abitazioni dei soggetti gi\u00e0 detenuti.<\/p>\n\n\n\n<p>Le perquisizioni hanno dato esito positivo e in particolare a carico di uno dei due \u00e8 stato rinvenuta e sequestrata una pistola beretta px4 con matricola abrasa, un caricatore con all\u2019interno 12 cartucce calibro 40 e, in un involucro a parte, ulteriori 127 cartucce di vario calibro.<\/p>\n\n\n\n<p>L\u2019arma e le munizioni erano celati nel muro perimetrale dell\u2019abitazione, all\u2019interno di una nicchia ricavata.<\/p>\n\n\n\n<p>Inoltre, nascosti in diverse intercapedini ricavate all\u2019interno di alcuni mobili dell\u2019abitazione, \u00e8 stata trovata e sequestra la somma di Euro 14.500 suddivisa in banconote di vario taglio, oltre a due telefoni cellulari ed atri documenti utili per la prosecuzione delle indagini.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lecce, 24 aprile 2025 __________<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo di ieri<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"teOJKhBUWW\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/23\/beni-mobili-e-immobili-sequestrati-alla-sacra-corona-unita\/\">BENI MOBILI E IMMOBILI SEQUESTRATI ALLA SACRA CORONA UNITA<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;BENI MOBILI E IMMOBILI SEQUESTRATI ALLA SACRA CORONA UNITA&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/23\/beni-mobili-e-immobili-sequestrati-alla-sacra-corona-unita\/embed\/#?secret=r1oCmJUe6w#?secret=teOJKhBUWW\" data-secret=\"teOJKhBUWW\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/altri-sequestri-a-carico-di-presunti-esponenti-della-sacra-corona-unita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/24\/altri-sequestri-a-carico-di-presunti-esponenti-della-sacra-corona-unita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce __________ Sigilli a beni di lusso: rinvenuti anche soldi e una pistola, proseguono le attivit\u00e0 della Polizia di Stato Durante l\u2019attivit\u00e0 di esecuzione delle misure patrimoniali svoltasi nella giornata di ieri, gli agenti della Questura di Lecce hanno eseguito anche delle perquisizioni domiciliari nelle abitazioni dei soggetti gi\u00e0 detenuti. Le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242350,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242349"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242349"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242349\/revisions"}],"predecessor-version":[{"id":242351,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242349\/revisions\/242351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242350"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}