{"id":242431,"date":"2025-04-26T16:13:00","date_gmt":"2025-04-26T14:13:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242431"},"modified":"2025-04-26T17:14:20","modified_gmt":"2025-04-26T15:14:20","slug":"accusa-infamante-per-giovane-salentino-dipendente-comunita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/26\/accusa-infamante-per-giovane-salentino-dipendente-comunita\/","title":{"rendered":"ACCUSA INFAMANTE PER GIOVANE SALENTINO CHE LAVORAVA IN COMUNITA&#8217;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"263\" height=\"192\" class=\"wp-image-242432\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/download-3.jpeg\" alt=\"\">(e.l.) __________ Un giovane di 31 anni avrebbe abusato a pi\u00f9 riprese, per tre mesi, fino al febbraio scorso, di una ragazza di 16 anni, ospite di una comunit\u00e0 nel Salento di cui egli era dipendente. Adesso \u00e8 stato sospeso dal servizio. Lo avrebbe fatto anche stordendola con psicofarmaci e minacciandola affinch\u00e8 non dicesse niente a nessuno.<\/p>\n\n\n\n<p>Dopo la denuncia dei genitori della minorenne, con i quali lei si era alla fine confidata, i Carabinieri hanno avviato le indagini e la Procura della Repubblica di Lecce ha aperto un fascicolo con l&#8217;accusa di violenza sessuale aggravata.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/26\/accusa-infamante-per-giovane-salentino-dipendente-comunita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/26\/accusa-infamante-per-giovane-salentino-dipendente-comunita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) __________ Un giovane di 31 anni avrebbe abusato a pi\u00f9 riprese, per tre mesi, fino al febbraio scorso, di una ragazza di 16 anni, ospite di una comunit\u00e0 nel Salento di cui egli era dipendente. Adesso \u00e8 stato sospeso dal servizio. Lo avrebbe fatto anche stordendola con psicofarmaci e minacciandola affinch\u00e8 non dicesse niente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242431"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242431"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242431\/revisions"}],"predecessor-version":[{"id":242434,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242431\/revisions\/242434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242432"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}