{"id":242458,"date":"2025-04-28T11:29:29","date_gmt":"2025-04-28T09:29:29","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242458"},"modified":"2025-04-28T11:29:40","modified_gmt":"2025-04-28T09:29:40","slug":"la-polizia-di-stato-arresta-presunto-autore-di-rapina-alle-poste","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/28\/la-polizia-di-stato-arresta-presunto-autore-di-rapina-alle-poste\/","title":{"rendered":"LA POLIZIA DI STATO ARRESTA PRESUNTO AUTORE DI RAPINA ALLE POSTE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"512\" height=\"288\" class=\"wp-image-242459\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/macchina-polizia.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/macchina-polizia.png 512w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/04\/macchina-polizia-300x169.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/p>\n\n\n\n<p>Report della Questura di Brindisi ___________<\/p>\n\n\n\n<p>Polizia di Stato di Brindisi: arrestato il presunto autore della rapina all\u2019Ufficio Postale di San Vito dei Normanni<\/p>\n\n\n\n<p>Lo scorso 22 aprile, la Polizia di Stato di Brindisi ha tratto in arresto il presunto autore della rapina consumata a San Vito dei Normanni, presso l\u2019Ufficio Postale di via Brindisi, nella stessa mattinata.<\/p>\n\n\n\n<p>Il rafforzamento dei servizi di controllo del territorio finalizzati alla prevenzione dei reati, disposto dal Questore di Brindisi Giampietro Lionetti nel periodo delle festivit\u00e0 pasquali, ha portato cos\u00ec ad un importante risultato, poich\u00e9 le Volanti dell\u2019UPGSP della Questura hanno arrestato l\u2019uomo, brindisino classe 1982, gi\u00e0 noto alle Forze dell\u2019Ordine per reati della stessa natura e per reati legati al traffico di stupefacenti.<\/p>\n\n\n\n<p>Determinante \u00e8 stato il coordinamento tra la Sale Operative della Questura e dei Carabinieri, in quanto, subito dopo la consumazione della rapina, poco prima delle 10 del mattino, \u00e8 stata divulgata una puntuale descrizione dell\u2019autore della rapina e del motociclo utilizzato per fuggire dall\u2019uomo che, armato di pistola e con il volto travisato da un casco integrale, aveva fatto irruzione nell\u2019ufficio postale impossessandosi di una somma di denaro pari a circa 700 Euro.<\/p>\n\n\n\n<p>Cos\u00ec, intorno alle 10.30, una Volante della Polizia di Stato ha notato nel centro storico di Brindisi un individuo che viaggiava a bordo di un motociclo e che aveva le caratteristiche dell\u2019autore della rapina.<\/p>\n\n\n\n<p>Nonostante il casco indossato fosse diverso, gli agenti hanno pensato che si trattasse del rapinatore che aveva agito poco prima a San Vito dei Normanni: l\u2019intuizione si \u00e8 rivelata subito corretta, in quanto ha trovato riscontro in ulteriori elementi forniti nel frattempo dai Carabinieri di San Vito dei Normanni.<\/p>\n\n\n\n<p>Cos\u00ec, gli agenti delle Volanti e della Squadra Mobile hanno effettuato una perquisizione, durante la quale \u00e8 stata rinvenuta la pistola utilizzata durante la rapina, rivelatasi una scacciacani priva di tappo rosso, ed il casco utilizzato per coprire il volto.<\/p>\n\n\n\n<p>Immediato \u00e8 scattato l\u2019arresto del brindisino che, su disposizione dell\u2019Autorit\u00e0 Giudiziaria, \u00e8 stato condotto presso il carcere di Brindisi. Il denaro rinvenuto, la pistola, il casco ed il motociclo utilizzati per compiere il reato sono stati sequestrati.<\/p>\n\n\n\n<p>Brindisi, 28.04.2025<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/28\/la-polizia-di-stato-arresta-presunto-autore-di-rapina-alle-poste\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/04\/28\/la-polizia-di-stato-arresta-presunto-autore-di-rapina-alle-poste\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Brindisi ___________ Polizia di Stato di Brindisi: arrestato il presunto autore della rapina all\u2019Ufficio Postale di San Vito dei Normanni Lo scorso 22 aprile, la Polizia di Stato di Brindisi ha tratto in arresto il presunto autore della rapina consumata a San Vito dei Normanni, presso l\u2019Ufficio Postale di via Brindisi, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242459,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242458"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242458"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242458\/revisions"}],"predecessor-version":[{"id":242460,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242458\/revisions\/242460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242459"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}