{"id":242742,"date":"2025-05-06T14:01:36","date_gmt":"2025-05-06T12:01:36","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242742"},"modified":"2025-05-06T14:02:15","modified_gmt":"2025-05-06T12:02:15","slug":"non-ci-sono-ancora-le-consulte-il-principale-istituto-di-partecipazione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/06\/non-ci-sono-ancora-le-consulte-il-principale-istituto-di-partecipazione\/","title":{"rendered":"NON CI SONO ANCORA LE CONSULTE, &#8220;il principale istituto di partecipazione&#8221;"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"420\" height=\"454\" class=\"wp-image-242743\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/30-Fronte-Presicce-Alessandro.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/30-Fronte-Presicce-Alessandro.jpg 420w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/30-Fronte-Presicce-Alessandro-278x300.jpg 278w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo. L\u2019Adoc di Lecce ci manda il seguente comunicato ________<\/p>\n\n\n\n<p>La nuova Amministrazione ha dichiarato, in campagna elettorale, che sarebbe stata l&#8217;amministrazione dell&#8217;ascolto e della partecipazione.<\/p>\n\n\n\n<p>Va per\u00f2 detto che, fino ad oggi, la cosiddetta partecipazione si \u00e8 limitata forse a colloqui informali \u201cdi strada\u201d con singoli, ma non si \u00e8 esplicata nelle sedi istituzionali statutarie, atteso che mai la nostra associazione \u00e8 stata convocata su uno qualsiasi dei temi cittadini. Qualche audizione si \u00e8 registrata in alcune Commissioni, ma pi\u00f9 per sensibilit\u00e0 dei presidenti e dei commissari, che in attuazione di un modello di partecipazione come disegnato dallo Statuto.<\/p>\n\n\n\n<p>Ma la partecipazione \u00e8 una cosa importante e va fatta secondo le previsioni dello Statuto, che disciplina, appunto, gli istituti di partecipazione, i luoghi dove i corpi intermedi e rappresentativi dei cittadini svolgono quella funzione imprescindibile di compartecipazione democratica alle scelte della Citt\u00e0.<\/p>\n\n\n\n<p>Le Consulte, come noto, sono il principale istituto di partecipazione della Citt\u00e0.<\/p>\n\n\n\n<p>Ebbene, il Regolamento prevede che esse debbano essere ricostituite entro 6 mesi dall&#8217;insediamento del nuovo Consiglio. A norma di Regolamento, quindi, le Consulte si sarebbero dovute ricostituire a gennaio 2025 ed invece siamo ai primi di maggio e ancora il bando non \u00e8 stato pubblicato. Se anche fosse pubblicato oggi, esse non entrerebbero in esercizio prima dell&#8217;estate.<\/p>\n\n\n\n<p>Un gravissimo e colpevole ritardo, quindi, sta comprimendo e mortificando il dibattito democratico e il contributo che gli enti della cittadinanza attiva, le associazioni di categoria e i soggetti istituzionali (sindacati, ordini professionali, ecc.) possono dare alla Citt\u00e0. Ci\u00f2 a scapito dei cittadini e dei loro interessi e della qualit\u00e0 generale della partecipazione democratica.<\/p>\n\n\n\n<p>E&#8217; per questo che Adoc ha protocollato una pressante richiesta al Sindaco, al Presidente del Consiglio Comunale, al Segretario Comunale, nella sua qualit\u00e0 di garante della conformit\u00e0 dell&#8217;azione amministrativa alle leggi, allo Statuto ed ai regolamenti, al Presidente della VII Commissione (Statuto e Istituti di Partecipazione) e XII (Controllo e attuazione dei Regolamenti) affinch\u00e9 sia immediatamente pubblicato il Bando e riattivate le Consulte.<\/p>\n\n\n\n<p>Lecce, 06.05.2025<\/p>\n\n\n\n<p>Avv. Alessandro Presicce, presidente ADOC Lecce<\/p>\n\n\n\n<p>Federica Lella, volontaria SCU<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/06\/non-ci-sono-ancora-le-consulte-il-principale-istituto-di-partecipazione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/06\/non-ci-sono-ancora-le-consulte-il-principale-istituto-di-partecipazione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L\u2019Adoc di Lecce ci manda il seguente comunicato ________ La nuova Amministrazione ha dichiarato, in campagna elettorale, che sarebbe stata l&#8217;amministrazione dell&#8217;ascolto e della partecipazione. Va per\u00f2 detto che, fino ad oggi, la cosiddetta partecipazione si \u00e8 limitata forse a colloqui informali \u201cdi strada\u201d con singoli, ma non si \u00e8 esplicata [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,76,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242742"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242742"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242742\/revisions"}],"predecessor-version":[{"id":242744,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242742\/revisions\/242744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242743"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}