{"id":24288,"date":"2014-02-08T18:41:50","date_gmt":"2014-02-08T18:41:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24288"},"modified":"2014-02-08T18:46:36","modified_gmt":"2014-02-08T18:46:36","slug":"droga-e-munizioni-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/droga-e-munizioni-arrestato\/","title":{"rendered":"DROGA E MUNIZIONI: ARRESTATO"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/DSC06405.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/DSC06405-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-24298\" \/><\/a>Nel corso della notte appena trascorsa, in San Cesario di Lecce (le), i militari del Nucleo Investigativo, nel contesto delle attivit\u00e0 di ricerca dei responsabili della rapina perpetrata in data 06 feb 2014, successivamente sfociata in conflitto a fuoco con i militari della Stazione carabinieri di San Pietro In Lama (le), hanno arrestato in flagranza, con l\u2019ausilio della locale stazione carabinieri, per i reati di detenzione ai fini di spaccio di stupefacenti e detenzione abusiva di munizioni:<\/p>\n<p><strong>I. M.\u00a0<\/strong>35enne, residente San Cesario, incensurato.<\/p>\n<p>durante la perquisizione locale, eseguita presso l\u2019abitazione rurale a lui in uso, sono stati rinvenuti e sequestrati:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0quindici (15) grammi di cocaina, suddivisi in quattordici (14) dosi;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0tre (3) grammi di marijuana;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0un bilancino elettronico;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0un frullatore con residui di sostanza da taglio tipo mannite;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0euro trecentotrenta (330) in banconote di vario taglio, provento dell\u2019attivit\u00e0 di spaccio di stupefacenti;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0quattrocentosessantatr\u00e8 (463) cartucce da caccia cal. 12.<\/p>\n<p>L\u2019arrestato \u00e8 stato sottoposto agli arresti domiciliari presso la propria abitazione.<em><\/em><\/p>\n<p align=\"center\"><em><span style=\"text-decoration: underline\"><br \/>\n<\/span><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/droga-e-munizioni-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/droga-e-munizioni-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nel corso della notte appena trascorsa, in San Cesario di Lecce (le), i militari del Nucleo Investigativo, nel contesto delle attivit\u00e0 di ricerca dei responsabili della rapina perpetrata in data 06 feb 2014, successivamente sfociata in conflitto a fuoco con i militari della Stazione carabinieri di San Pietro In Lama (le), hanno arrestato in flagranza, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24288"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24288"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24288\/revisions"}],"predecessor-version":[{"id":24299,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24288\/revisions\/24299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24298"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}