{"id":242880,"date":"2025-05-09T12:32:58","date_gmt":"2025-05-09T10:32:58","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=242880"},"modified":"2025-05-09T13:03:12","modified_gmt":"2025-05-09T11:03:12","slug":"resoconto-del-convegno-organizzato-a-lecce-da-banca-generali-sulle-sfide-che-attendono-piccole-e-medie-imprese","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/09\/resoconto-del-convegno-organizzato-a-lecce-da-banca-generali-sulle-sfide-che-attendono-piccole-e-medie-imprese\/","title":{"rendered":"RESOCONTO DEL CONVEGNO ORGANIZZATO A LECCE DA BANCA GENERALI SULLE SFIDE CHE ATTENDONO PICCOLE E MEDIE IMPRESE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1200\" class=\"wp-image-242881\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1.jpg 1600w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/COVER-1-400x300.jpg 400w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n\n\n\n<p><strong>Tra dazi e incertezze sui mercati, Banca Generali Private a Lecce mette al centro patrimonio e imprese<\/strong><\/p>\n\n\n\n<ul>\n<li>Nel capoluogo salentino la private bank del Leone ha incontrato professionisti e imprenditori, in uno scenario economico e finanziario reso pi\u00f9 complesso dalle incertezze geopolitiche e commerciali<strong><\/strong><\/li>\n\n\n\n<li>Sotto i riflettori la protezione e valorizzazione del patrimonio attraverso gestione attiva e diversificazione, le sfide d\u2019impresa, anche in un\u2019ottica di passaggio generazionale e il valore della consulenza internazionale<strong><\/strong><\/li>\n<\/ul>\n\n\n\n<p><em>Lecce, 9 maggio 2025 <\/em>\u2013 In un<a> panorama economico e finanziario reso pi\u00f9 complesso dalle incertezze geopolitiche e sul commercio internazionale, <strong>Banca Generali Private mette al centro le imprese pugliesi con<\/strong> <strong>un convegno a Lecce. <\/strong>L\u2019insicurezza portata dalla minaccia dei dazi americani sta infatti gi\u00e0 frenando la fiducia e quindi la crescita in tutto il mondo, portando a una notevole volatilit\u00e0 sui mercati. Uno scenario che porta con s\u00e9 numerose sfide per le aziende, nella loro quotidiana ricerca di competitivit\u00e0, e per le famiglie, in un\u2019ottica di protezione nel tempo del patrimonio finanziario e d\u2019impresa.<\/a><\/p>\n\n\n\n<p>L\u2019evento \u00e8 stato promosso dai consulenti finanziari dell\u2019area del Sales Manager di Rete \u2013 Sud<strong> Corrado Liguori, <\/strong>attraverso l\u2019impegno delDistrict Manager<strong> Piero Menallo<\/strong>. Il convegnoha messo a confronto in una tavola rotonda <strong>Leandro Bovo<\/strong>, Head of Wealth and International Advisor di Banca Generali, <strong>Marzio Albonico<\/strong>, responsabile Servizio Family Protection &amp; Planning di Banca Generali &#8211; Presidente Generfid Spa Fiduciaria e <strong>Roberto Corradini, <\/strong>BG International Manager.<\/p>\n\n\n\n<p>Nell\u2019incontro, sono stati affrontati da vicino i temi delle pi\u00f9 urgenti delle sfide d\u2019impresa per le PMI che costituiscono la spina dorsale del tessuto produttivo italiano: dal tema <strong>del passaggio generazionale a quello della crescita e della ricerca di competitivit\u00e0<\/strong>, anche attraverso <strong>l\u2019attivit\u00e0 di M&amp;A e l\u2019approdo al mercato dei capitali<\/strong>. Oltre ai <strong>benefici di diversificazione dal rischio offerti dalla consulenza internazionale di BG International<\/strong> in un panorama di crescente incertezza sui mercati e <strong>allo scenario del commercio globale all\u2019indomani dell\u2019annuncio delle tariffe doganali americane<\/strong>.<\/p>\n\n\n\n<ul>\n<li>. Secondo le stime dell&#8217;Organizzazione Mondiale del Commercio (WTO) <strong>l\u2019incertezza sulla politica commerciale degli Stati Uniti porter\u00e0 il commercio globale a contrarsi dello 0,2% nel corso del 2025<\/strong>. In base alle pi\u00f9 recenti stime dell\u2019FMI, inoltre, <strong>l\u2019economia dell\u2019Eurozona crescer\u00e0 meno delle attese, solo dello 0,8% nel 2025.<\/strong> L\u2019Italia e la Germania, due dei Paesi con la maggior vocazione per l\u2019export, saranno tra le pi\u00f9 colpite, con <strong>una crescita attesa allo 0,4% per il nostro Paese e una stagnazione del Pil per Berlino<\/strong>.<\/li>\n\n\n\n<li><strong>Trecento miliardi di euro<\/strong> \u00e8 la cifra, riportata dall\u2019Associazione Italiana Private Banking (AIPB), che fotografa la dimensione del fenomeno <strong>passaggio generazionale in Italia da oggi al 2033 <\/strong>tra le famiglie private, e una parte importante di questa cifra \u00e8 rappresentata dal patrimonio d\u2019impresa. I dati pi\u00f9 accreditati indicano che solo il 13% di aziende familiari riesce ad arrivare alla terza generazione e il <strong>28% <\/strong>di quellecon un fatturato maggiore a 50 milioni di euro sono <strong>guidate da un leader ultrasettantenne<\/strong>; questi ultimi sono cresciuti costantemente negli ultimi anni portando con s\u00e9, oltre che un mancato ricambio generazionale, <strong>una minore crescita e una minore<\/strong> <strong>redditivit\u00e0<\/strong>. Risulta chiaro da questi dati come sia urgente indirizzare questa tematica aprendo un dialogo che consenta all\u2019imprenditore di agire per tempo con gli strumenti che sono a disposizione (cessione, management by out, riassetto della governance&#8230;)<\/li>\n\n\n\n<li><strong>Crescita e valorizzazione del patrimonio d\u2019azienda<\/strong>. Dopo un 2024 all\u2019insegna della prudenza, i mercati finanziari stanno mostrando segnali di ripresa, con le fusioni e acquisizioni (M&amp;A) a tornare protagoniste. Il calo dell\u2019inflazione e la riduzione dei tassi di interesse spingono le aziende a ripensare le proprie strategie di crescita e considerare attivit\u00e0&nbsp;M&amp;A. Secondo EY le operazioni di M&amp;A in Italia lo scorso anno sono state 1365 + 14% rispetto al 2023 e quasi il triplo rispetto al 2016. Nel 2024&nbsp;<strong>il valore delle operazioni di&nbsp;M&amp;A&nbsp;in Europa ha raggiunto i<\/strong>&nbsp;<strong>483 miliardi di dollari<\/strong>, con un aumento del&nbsp;<strong>16%<\/strong>&nbsp;rispetto all\u2019anno precedente. Financial Advisory, valutazioni d\u2019azienda, collocamenti azionari e obbligazionari, aumenti di capitale sono tutti strumenti utili alle Pmi per crescere e rimanere competitive nell\u2019attuale contesto di mercato.<\/li>\n<\/ul>\n\n\n\n<p><em>\u201cNell\u2019attuale scenario, complesso per l\u2019economia e i mercati, sempre pi\u00f9 famiglie e imprenditori ci chiedono di affiancarli da un lato con strumenti e strategie in grado di proteggere il patrimonio e dall\u2019altro, sempre pi\u00f9, nella quotidiana ricerca di competitivit\u00e0 e ricerca di soluzioni alle sfide d\u2019impresa. \u00c8 questa la missione di Banca Generali Private e dei suoi consulenti finanziari, che grazie a una sempre maggiore expertise specialistica e al costante lavoro sul territorio, si stanno affermando sempre pi\u00f9 come un punto di riferimento d\u2019eccellenza per famiglie e imprese\u201d, <\/em>ha commentato Corrado Liguori.<\/p>\n\n\n\n<p><em>\u201cSempre di pi\u00f9 ci troviamo al fianco dei nostri clienti imprenditori per accompagnarli non solo nella protezione patrimoniale per la famiglia e l\u2019azienda stessa, ma anche per aiutarli nel cogliere le migliori opportunit\u00e0 sul mercato con le loro imprese, nelle sfide che vanno dall\u2019apertura al mercato di capitali al confronto con le dinamiche di settore, passando dal supporto nel passaggio generazionale<\/em>\u201d, ha aggiunto Leandro Bovo.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"1600\" class=\"wp-image-242882\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/BGP_ConvegnoLecce_1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/BGP_ConvegnoLecce_1.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/BGP_ConvegnoLecce_1-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/BGP_ConvegnoLecce_1-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/05\/BGP_ConvegnoLecce_1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n\n<p><strong>Banca Generali<\/strong><\/p>\n\n\n\n<p>Banca Generali \u00e8 una banca private leader in Italia nella pianificazione finanziaria e nella tutela patrimoniale dei clienti, forte di una rete di consulenti-private bankers ai vertici del settore per competenze e professionalit\u00e0. La strategia della societ\u00e0 si basa su quattro elementi chiave: la consulenza qualificata di professionisti specializzati nella protezione della ricchezza delle famiglie e nel supporto alla pianificazione del loro futuro; un portafoglio prodotti all\u2019avanguardia con soluzioni su misura per le esigenze personali, servizi innovativi nel wealth management per la cura del patrimonio non solo finanziario, e strumenti innovativi che tramite la tecnologia valorizzano la relazione di fiducia tra consulente e cliente. La mission della banca evidenzia il ruolo di Persone di fiducia al fianco del cliente nel tempo per costruire e prendersi cura dei suoi progetti di vita. Quotata alla Borsa di Milano dal novembre del 2006 gestisce circa 103,8 miliardi di euro di masse (dati al 31 dicembre 2024) per conto di oltre 359 mila clienti. Presente in modo capillare sull\u2019intero territorio nazionale dispone di 54 filiali bancarie e oltre 170 uffici a disposizione degli oltre 2353 consulenti finanziari. Banca Generali segue un modello di architettura aperta e opera attraverso supporti digitali evoluti. Dal 2024 Banca Generali \u00e8 presente anche in Svizzera con BG Suisse per l\u2019offerta di servizi bancari e di investimento personalizzati.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/09\/resoconto-del-convegno-organizzato-a-lecce-da-banca-generali-sulle-sfide-che-attendono-piccole-e-medie-imprese\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/05\/09\/resoconto-del-convegno-organizzato-a-lecce-da-banca-generali-sulle-sfide-che-attendono-piccole-e-medie-imprese\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Tra dazi e incertezze sui mercati, Banca Generali Private a Lecce mette al centro patrimonio e imprese Lecce, 9 maggio 2025 \u2013 In un panorama economico e finanziario reso pi\u00f9 complesso dalle incertezze geopolitiche e sul commercio internazionale, Banca Generali Private mette al centro le imprese pugliesi con un convegno a Lecce. L\u2019insicurezza portata dalla [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":242881,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242880"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=242880"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242880\/revisions"}],"predecessor-version":[{"id":242883,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/242880\/revisions\/242883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/242881"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=242880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=242880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=242880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}