{"id":24290,"date":"2014-02-08T18:42:41","date_gmt":"2014-02-08T18:42:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24290"},"modified":"2014-02-08T18:42:41","modified_gmt":"2014-02-08T18:42:41","slug":"tenta-cavallo-di-ritorno-denunciato-per-estorsione","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/tenta-cavallo-di-ritorno-denunciato-per-estorsione\/","title":{"rendered":"TENTA \u201cCAVALLO DI RITORNO\u201d: DENUNCIATO PER ESTORSIONE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">I militari della Tenenza di Copertino hanno oggi deferito in stato di libert\u00e0 B.T., 42enne rumeno da anni residente nel Comune di Copertino, con l\u2019accusa di tentata estorsione. La storia dietro al deferimento dell\u2019uomo \u00e8 tipica del classico \u201ccavallo di ritorno\u201d. Infatti, venuto a sapere di alcuni furti avvenuti nell\u2019abitazione di un 65enne copertinese, ha nei giorni passati avvicinato la vittima, asserendo di poter recuperare la refurtiva. Quest\u2019ultima, formata da argenteria, gioielli vari e capi di abbigliamento di lusso, poteva essere recuperata, a suo dire, per la \u201cmodica\u201d cifra di 1500,00 euro. Alle richieste della vittima su come potesse recuperare la refurtiva, il rumeno ha risposto di conoscere gli autori del reato e di poter, quindi, intercedere con loro per restituire almeno una parte della refurtiva. In cambio, diceva, chiedeva solo piccole somme di denaro come ringraziamento. La vittima pensando inizialmente di poter risolvere la situazione privatamente, ha accettato, versando in due diverse occasioni somme per un totale di 100,00 euro, senza per\u00f2 riuscire a rinvenire alcunch\u00e9. Quando il rumeno, nella giornata di ieri, si \u00e8 nuovamente presentato chiedendo 20,00 euro, la vittima si \u00e8 recata ai Carabinieri per raccontare tutta la storia. Il rumeno \u00e8 stato cos\u00ec deferito in stato di libert\u00e0 con il reato di tentata estorsione. I militari della Tenenza stanno proseguendo le indagini per chiarire se quanto affermato dal rumeno riguardo il contatto con i ladri possa essere veritiero.<\/p>\n<p align=\"center\"><em>\u00a0<\/em><\/p>\n<p align=\"center\"><em><br \/>\n<\/em><\/p>\n<p align=\"center\"><em><br \/>\n<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/tenta-cavallo-di-ritorno-denunciato-per-estorsione\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/08\/tenta-cavallo-di-ritorno-denunciato-per-estorsione\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>I militari della Tenenza di Copertino hanno oggi deferito in stato di libert\u00e0 B.T., 42enne rumeno da anni residente nel Comune di Copertino, con l\u2019accusa di tentata estorsione. La storia dietro al deferimento dell\u2019uomo \u00e8 tipica del classico \u201ccavallo di ritorno\u201d. Infatti, venuto a sapere di alcuni furti avvenuti nell\u2019abitazione di un 65enne copertinese, ha [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24290"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24290"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24290\/revisions"}],"predecessor-version":[{"id":24291,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24290\/revisions\/24291"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}