{"id":24327,"date":"2014-02-09T09:24:07","date_gmt":"2014-02-09T09:24:07","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24327"},"modified":"2014-02-09T09:24:36","modified_gmt":"2014-02-09T09:24:36","slug":"samuele-bersani-si-sposta-al-15-aprile","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/09\/samuele-bersani-si-sposta-al-15-aprile\/","title":{"rendered":"SAMUELE BERSANI SI SPOSTA AL 15 APRILE I BIGLIETTI SARANNO RIMBORSATI"},"content":{"rendered":"<p>Si comunica che la data del concerto di Samuele Bersani, nell\u2019ambito del suo tour \u201cNuvola Numero Nove Tour 2014\u201d, prevista a Lecce per l\u20191 aprile prossimo presso il Teatro Politeama Greco, \u00e8 slittata al 15 aprile 2014.<\/p>\n<p>Il tutto, a causa di problemi di natura logistica. I biglietti acquistati e valevoli per lo spettacolo del 1 aprile 2014 saranno rimborsabili presso il punto vendita di acquisto, circuito bookingshow o biglietteria dello stesso Teatro Politeama Greco di Lecce.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/09\/samuele-bersani-si-sposta-al-15-aprile\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/09\/samuele-bersani-si-sposta-al-15-aprile\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si comunica che la data del concerto di Samuele Bersani, nell\u2019ambito del suo tour \u201cNuvola Numero Nove Tour 2014\u201d, prevista a Lecce per l\u20191 aprile prossimo presso il Teatro Politeama Greco, \u00e8 slittata al 15 aprile 2014. Il tutto, a causa di problemi di natura logistica. I biglietti acquistati e valevoli per lo spettacolo del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24327"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24327"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24327\/revisions"}],"predecessor-version":[{"id":24330,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24327\/revisions\/24330"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}