{"id":24337,"date":"2014-02-10T09:15:53","date_gmt":"2014-02-10T09:15:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24337"},"modified":"2014-02-10T09:22:21","modified_gmt":"2014-02-10T09:22:21","slug":"eroina-in-casa-al-posto-del-caffe-arrestato","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/10\/eroina-in-casa-al-posto-del-caffe-arrestato\/","title":{"rendered":"EROINA IN CASA AL POSTO DEL CAFFE\u2019: ARRESTATO"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/10\/eroina-in-casa-al-posto-del-caffe-arrestato\/20140208_182430\/\" rel=\"attachment wp-att-24338\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/20140208_182430-150x150.jpg\" alt=\"\" title=\"20140208_182430\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-24338\" \/><\/a>Nel pomeriggio dell\u20198 febbraio 2014, nel corso di un servizio antidroga, personale dell\u2019Aliquota Operativa e dell\u2019Aliquota Radiomobile della Compagnia di Lecce hanno individuato due soggetti che si allontanavano in maniera furtiva da un complesso di abitazioni nei pressi della SP Lecce-San Cataldo; gli stessi venivano opportunamente intercettati, condotti in caserma e sottoposti a perquisizione, e da tale attivit\u00e0 emergeva che proprio nella zona ove erano stati fermati avevano appena acquistato una dose di eroina del tipo \u201cbrown sugar\u201d. Acquisito quindi tale riscontro ad un\u2019attivit\u00e0 investigativa pi\u00f9 ampia che andava avanti da tempo, avendo cio\u00e8 trasformato in certezza quelli che fino a poco prima erano solo dei forti sospetti, i militari si sono recati in tale zona, precisamente in Via Beltrami, presso l\u2019abitazione di FUSO Emanuele, ed hanno proceduto alla perquisizione del domicilio di quest\u2019ultimo. Gi\u00e0 all\u2019atto dell\u2019ingresso dei carabinieri in casa, FUSO Emanuele cercava di defilarsi, ma veniva prontamente bloccato dai militari operanti. Tale atteggiamento sospetto trovava poi conferma durante la perquisizione, in quanto proprio all\u2019interno della sua camera da letto, occultato dietro ad un mobile, veniva rinvenuto un barattolo di latta, normalmente utilizzato per il caff\u00e8, con all\u2019interno 62 dosi gi\u00e0 confezionate di eroina \u201cbrown sugar\u201d, la medesima sostanza che era stata sequestrata ai due acquirenti poco prima, ed inoltre anche delle pastiglie di suboxone, un farmaco di solito utilizzato nelle terapie di disintossicazione da dipendenza come sostituivo degli oppiacei. Sempre durante la perquisizione, veniva altres\u00ec rinvenuto nella disponibilit\u00e0 di FUSO Emanuele un bilancino di precisione, nonch\u00e9 la somma contante di 305,00 euro in banconote di piccolo taglio occultata in un armadio. A seguito quindi del rinvenimento dell\u2019eroina e della presenza di tutti gli altri indicatori indizianti, FUSO Emanuele veniva condotto presso il Comando Provinciale dei Carabinieri e dichiarato in stato di arresto per \u201cdetenzione ai fini di spaccio di sostanze stupefacenti\u201d, ai sensi dell\u2019art. 73 del D.P.R. 309\/90. Dopo l\u2019arresto, su disposizione del Pubblico Ministero di turno presso la Procura di Lecce, Dott.ssa Carmen RUGGIERO, FUSO Emanuele \u00e8 stato associato presso la Casa Circondariale di Borgo San Nicola.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/10\/eroina-in-casa-al-posto-del-caffe-arrestato\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/10\/eroina-in-casa-al-posto-del-caffe-arrestato\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Nel pomeriggio dell\u20198 febbraio 2014, nel corso di un servizio antidroga, personale dell\u2019Aliquota Operativa e dell\u2019Aliquota Radiomobile della Compagnia di Lecce hanno individuato due soggetti che si allontanavano in maniera furtiva da un complesso di abitazioni nei pressi della SP Lecce-San Cataldo; gli stessi venivano opportunamente intercettati, condotti in caserma e sottoposti a perquisizione, e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24338,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24337"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24337"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24337\/revisions"}],"predecessor-version":[{"id":24343,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24337\/revisions\/24343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24338"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}