{"id":244021,"date":"2025-06-07T12:44:52","date_gmt":"2025-06-07T10:44:52","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=244021"},"modified":"2025-06-07T12:58:22","modified_gmt":"2025-06-07T10:58:22","slug":"condannato-per-tentato-omicidio","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/06\/07\/condannato-per-tentato-omicidio\/","title":{"rendered":"CONDANNATO PER TENTATO OMICIDIO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"705\" height=\"319\" class=\"wp-image-244024\" style=\"width: 1200px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/06\/ProcuraDiLecce3_d0.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/06\/ProcuraDiLecce3_d0.png 705w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/06\/ProcuraDiLecce3_d0-300x136.png 300w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/><\/p>\n\n\n\n<p>(e.l.) ___________ E&#8217; arrivato a sentenza a Lecce, giudice unico Tea Verderosa, pm Alessandro Prontera, il processo a carico di Giuseppe Proce, 24 anni, di Racale, accusato di tentato omicidio della fidanzata nella sua abitazione, in cui si era introdotto violentemente, armato di coltelli, il 25 giugno scorso.<\/p>\n\n\n\n<p>Nell&#8217;occasione rimase ferita anche la madre della vittima e solo l&#8217;intervento del fratello evit\u00f2 il peggio.<\/p>\n\n\n\n<p>E&#8217; stato condannato a nove anni e undici mesi di reclusione.<\/p>\n\n\n\n<p> <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/06\/07\/condannato-per-tentato-omicidio\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/06\/07\/condannato-per-tentato-omicidio\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.) ___________ E&#8217; arrivato a sentenza a Lecce, giudice unico Tea Verderosa, pm Alessandro Prontera, il processo a carico di Giuseppe Proce, 24 anni, di Racale, accusato di tentato omicidio della fidanzata nella sua abitazione, in cui si era introdotto violentemente, armato di coltelli, il 25 giugno scorso. Nell&#8217;occasione rimase ferita anche la madre della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":244024,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/244021"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=244021"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/244021\/revisions"}],"predecessor-version":[{"id":244025,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/244021\/revisions\/244025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/244024"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=244021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=244021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=244021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}