{"id":24470,"date":"2014-02-12T09:09:34","date_gmt":"2014-02-12T09:09:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24470"},"modified":"2014-02-12T09:09:34","modified_gmt":"2014-02-12T09:09:34","slug":"claudio-marullo-ci-ha-lasciati","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/12\/claudio-marullo-ci-ha-lasciati\/","title":{"rendered":"CLAUDIO MARULLO CI HA LASCIATI"},"content":{"rendered":"<p>Dopo aver combattuto per un anno contro un male che non gli ha lasciato scampo, Claudio Marullo \u00e8 deceduto.<br \/>\nDi lui ricordiamo la simpatia, l&#8217;affabilit\u00e0 e la cordialit\u00e0 scherzosa con la quale ci accoglieva tutte le volte che ci siamo incontrati.<br \/>\nAl fratello Luigi e a tutta la famiglia vanno le condoglianze della nostra redazione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/12\/claudio-marullo-ci-ha-lasciati\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/12\/claudio-marullo-ci-ha-lasciati\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Dopo aver combattuto per un anno contro un male che non gli ha lasciato scampo, Claudio Marullo \u00e8 deceduto. Di lui ricordiamo la simpatia, l&#8217;affabilit\u00e0 e la cordialit\u00e0 scherzosa con la quale ci accoglieva tutte le volte che ci siamo incontrati. Al fratello Luigi e a tutta la famiglia vanno le condoglianze della nostra redazione.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24470"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24470"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24470\/revisions"}],"predecessor-version":[{"id":24471,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24470\/revisions\/24471"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}