{"id":24494,"date":"2014-02-13T09:01:41","date_gmt":"2014-02-13T09:01:41","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24494"},"modified":"2014-02-13T09:04:12","modified_gmt":"2014-02-13T09:04:12","slug":"gang-band-il-san-valentino-protetto-del-guernica","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/13\/gang-band-il-san-valentino-protetto-del-guernica\/","title":{"rendered":"Gang Band.Il San Valentino \u201cprotetto\u201d del Guernica"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/13\/gang-band-il-san-valentino-protetto-del-guernica\/locandina-6\/\" rel=\"attachment wp-att-24495\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/locandina-150x150.jpg\" alt=\"\" title=\"locandina\" width=\"150\" height=\"150\" class=\"alignnone size-thumbnail wp-image-24495\" \/><\/a>Al Guernica di Arnesano il San Valentino si festeggia maniera \u201csicura\u201d, ironica e scatenata con un triplo concerto all\u2019insegna della musica autoprodotta di qualit\u00e0, in compagnia di Teenage Riot, URO e Complessino Vazca. Tre band che si alternano sul palco in una simbolica a provocatoria &#8220;Gang Band&#8221;.<\/p>\n<p>Gli URO, trio post-rock strumentale, vincitore delle selezioni regionali di Italia Wave Puglia 2012, con un primo Ep alle spalle, \u201cURO\u201d, e nuovamente alle prese con le nuove registrazioni. La quasi totale assenza di voce e cantato, il ricorso a tempi dispari e la frenesia ritmica, caratterizzano il loro stile inconfondibile.<\/p>\n<p>I Teenage Riot, anch&#8217;essi un trio che si muove tra il punk e il noise, propongono pezzi rabbiosi e schizofrenici, utili a districarsi dal logorante sistema socioculturale, in un&#8217;inquieta e frenetica ricerca di strade alternative. Attivo dal 2007, nel corso dei anni il gruppo si \u00e8 fatto spazio nella scena musicale underground salentina e pugliese esibendosi nei maggiori circoli, club e rassegne musicali della regione.<\/p>\n<p>I Complessino Vazca, un duo decisamente rock, chitarra e batteria secca, porta sul palco un prog\u2019n\u2019roll crudo e violento, che vuole condurre l&#8217;ascoltatore verso mistiche esperienze dal sapore hendrixiano e un po&#8217; boh\u00e8mien. Nella musica del Complessino Vazca non vi \u00e8 traccia alcuna di aridi intenti eruditi n\u00e9 di propositi rivoluzionari ma solo di tanta buona musica passionale.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;<\/p>\n<p>Matteo Tangolo<\/p>\n<p>Ufficio Stampa e Comunicazione<\/p>\n<p>SUM Project<\/p>\n<p>Via della Ferrandina 5, Lecce<\/p>\n<p>Contatti&amp;Web<\/p>\n<p>mobile<\/p>\n<p>+39 3288115940<\/p>\n<p>mail<\/p>\n<p>matteo@sumproject.org<\/p>\n<p>web<\/p>\n<p>www.sumproject.org<\/p>\n<p>www.facebook.com\/sumproject<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/13\/gang-band-il-san-valentino-protetto-del-guernica\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/13\/gang-band-il-san-valentino-protetto-del-guernica\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Al Guernica di Arnesano il San Valentino si festeggia maniera \u201csicura\u201d, ironica e scatenata con un triplo concerto all\u2019insegna della musica autoprodotta di qualit\u00e0, in compagnia di Teenage Riot, URO e Complessino Vazca. Tre band che si alternano sul palco in una simbolica a provocatoria &#8220;Gang Band&#8221;. Gli URO, trio post-rock strumentale, vincitore delle selezioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24495,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24494"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24494"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24494\/revisions"}],"predecessor-version":[{"id":24500,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24494\/revisions\/24500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24495"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}