{"id":245327,"date":"2025-07-03T14:42:47","date_gmt":"2025-07-03T12:42:47","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=245327"},"modified":"2025-07-03T14:43:49","modified_gmt":"2025-07-03T12:43:49","slug":"immigrato-extracomunitario-irregolare-rinchiuso-in-carcere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/03\/immigrato-extracomunitario-irregolare-rinchiuso-in-carcere\/","title":{"rendered":"IMMIGRATO EXTRACOMUNITARIO IRREGOLARE RINCHIUSO IN CARCERE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"2076\" height=\"1594\" class=\"wp-image-245328\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO.jpg 2076w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO-300x230.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO-1024x786.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO-768x590.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO-1536x1179.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/NARDO-2048x1573.jpg 2048w\" sizes=\"(max-width: 2076px) 100vw, 2076px\" \/><\/p>\n\n\n\n<p>Report della Questura di Lecce ___________<\/p>\n\n\n\n<p><strong>Nard\u00f2, importuna gli avventori della stazione violando anche il divieto di dimora. Arrestato dalla Polizia di Stato.<\/strong><\/p>\n\n\n\n<p>La Polizia di Stato di Lecce, lo scorso 2 luglio, ha dato esecuzione all\u2019ordinanza di custodia cautelare in carcere nei confronti di un 35enne originario del Ciad, senza fissa dimora e gi\u00e0 noto alle Forze dell\u2019Ordine, che la settimana precedente aveva pi\u00f9 volte violato la misura cautelare del divieto di dimora nel comune di Nard\u00f2.<\/p>\n\n\n\n<p>Il provvedimento restrittivo del Giudice per le Indagini Preliminari rappresenta l\u2019epilogo dell\u2019attivit\u00e0 investigativa degli agenti del Commissariato di P.S. di Nard\u00f2, che avevano segnalato il giovane per la commissione di numerosi reati, richiedendo l\u2019aggravamento della misura cautelare in atto.<\/p>\n\n\n\n<p>Nello specifico, lo scorso 25 giugno, era stato richiesto l\u2019intervento delle Volanti del Commissariato, nei pressi del bar della stazione, ove in un primo momento l\u2019uomo aveva arrecato disturbo ai passanti. Successivamente, si era reso responsabile di un episodio increscioso, importunando una donna, dapprima verbalmente, per poi aggredirla fisicamente costringendola a ripararsi all\u2019interno di un esercizio commerciale nelle vicinanze.<\/p>\n\n\n\n<p>Nell\u2019occasione, veniva rilevato che l\u2019uomo era presente nel territorio di Nard\u00f2, in violazione della misura cautelare del divieto di dimora, senza autorizzazione o giustificazione alcuna, peraltro mentre era intento ad importunare i presenti, mettendo in pericolo la loro incolumit\u00e0, come era gi\u00e0 avvenuto in altre occasioni.<\/p>\n\n\n\n<p>Inoltre, il giorno seguente, gli agenti del Commissariato venivano allertati nuovamente da personale sanitario del 118, intervenuto sempre nei pressi della stazione per uno straniero, presumibilmente in stato di ebrezza alcolica e con delle lesioni sul volto. Giunti sul posto, gli operatori accertavano che il soggetto si era allontanato a piedi dal luogo segnalato, ma dopo una breve ricerca, veniva rintracciato, appurando che si trattava dello stesso uomo denunciato il giorno precedente.<\/p>\n\n\n\n<p>Cos\u00ec, i poliziotti effettuavano un controllo per la ricerca di eventuali oggetti atti ad offendere, portando il giovane a consegnare spontaneamente una tenaglia da carpentiere, che veniva sequestrata.<\/p>\n\n\n\n<p>Vista la pericolosit\u00e0 sociale dell\u2019uomo, non contenuta dalla misura cautelare del divieto di dimora, l\u2019A.G. ha disposto la misura cautelare in carcere, eseguita dalla Polizia di Stato, che, dopo le formalit\u00e0 di rito, lo ha condotto presso la Casa Circondariale di Lecce.<\/p>\n\n\n\n<p><em>Si specifica che i provvedimenti adottati in fase investigativa e \/o dibattimentale non implicano alcuna responsabilit\u00e0 dei soggetti sottoposti ad indagini ovvero imputati e che le informazioni sul procedimento penale in corso sono fornite nel rispetto dei diritti della persona indagata e della presunzione di innocenza.<\/em><\/p>\n\n\n\n<p>Lecce, 3 luglio 2025.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/03\/immigrato-extracomunitario-irregolare-rinchiuso-in-carcere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/03\/immigrato-extracomunitario-irregolare-rinchiuso-in-carcere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Report della Questura di Lecce ___________ Nard\u00f2, importuna gli avventori della stazione violando anche il divieto di dimora. Arrestato dalla Polizia di Stato. La Polizia di Stato di Lecce, lo scorso 2 luglio, ha dato esecuzione all\u2019ordinanza di custodia cautelare in carcere nei confronti di un 35enne originario del Ciad, senza fissa dimora e gi\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":245329,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/245327"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=245327"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/245327\/revisions"}],"predecessor-version":[{"id":245330,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/245327\/revisions\/245330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/245329"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=245327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=245327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=245327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}