{"id":24571,"date":"2014-02-14T14:01:14","date_gmt":"2014-02-14T14:01:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24571"},"modified":"2014-02-14T14:01:42","modified_gmt":"2014-02-14T14:01:42","slug":"lidea-fissa-di-nicola-vacca","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/14\/lidea-fissa-di-nicola-vacca\/","title":{"rendered":"L&#8217;IDEA FISSA DI NICOLA VACCA"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lidea-fissa-foto.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lidea-fissa-foto-300x265.jpg\" alt=\"\" width=\"300\" height=\"265\" class=\"alignleft size-medium wp-image-24572\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lidea-fissa-foto-300x265.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/lidea-fissa-foto.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>UNA\u00a0 NUOVA POESIA DI NICOLA VACCA, che ci esorta ad andare oltre i recinti della solitudine disperata e dell&#8217;egoismo disperante, per aprirci agli altri.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>L&#8217;IDEA FISSA<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Questa \u00e8 la vita che abbiamo<\/p>\n<p>ora e qui si sta nel mezzo<\/p>\n<p>con una feroce matematica dello spreco.<\/p>\n<p>Riempire il vuoto con il vuoto<\/p>\n<p>\u00e8 l\u2019idea fissa di questo stare<\/p>\n<p>negli anfratti di una solitudine<\/p>\n<p>che ci toglie i baci che non daremo mai<\/p>\n<p>&nbsp;<\/p>\n<p>Questa \u00e8 la vita che abbiamo.<\/p>\n<p>Eppure ogni giorno uccidiamo<\/p>\n<p>la parola che apre all\u2019ascolto<\/p>\n<p>per paura di vivere il momento di tacere.<\/p>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/14\/lidea-fissa-di-nicola-vacca\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/14\/lidea-fissa-di-nicola-vacca\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>UNA\u00a0 NUOVA POESIA DI NICOLA VACCA, che ci esorta ad andare oltre i recinti della solitudine disperata e dell&#8217;egoismo disperante, per aprirci agli altri. &nbsp; L&#8217;IDEA FISSA &nbsp; Questa \u00e8 la vita che abbiamo ora e qui si sta nel mezzo con una feroce matematica dello spreco. Riempire il vuoto con il vuoto \u00e8 l\u2019idea [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24572,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24571"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24571"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24571\/revisions"}],"predecessor-version":[{"id":24575,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24571\/revisions\/24575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24572"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}