{"id":246317,"date":"2025-07-27T15:30:00","date_gmt":"2025-07-27T13:30:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246317"},"modified":"2025-07-27T16:32:57","modified_gmt":"2025-07-27T14:32:57","slug":"il-pranzo-della-domenica-angelo-cavalera-meglio-del-signor-wolf-risolve-problemi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/il-pranzo-della-domenica-angelo-cavalera-meglio-del-signor-wolf-risolve-problemi\/","title":{"rendered":"IL PRANZO DELLA DOMENICA \/ ANGELO CAVALERI MEGLIO DEL SIGNOR WOLF RISOLVE PROBLEMI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"1600\" class=\"wp-image-246318\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/angelo-cavalera.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/angelo-cavalera.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/angelo-cavalera-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/angelo-cavalera-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/angelo-cavalera-1152x1536.jpg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>di <strong>Raffaele Polo _________<\/strong><\/p>\n\n\n\n<p>\u00abIl mio idolo, il mio punto di riferimento \u00e8 sempre stato Honda, il fondatore e l&#8217;inventore delle motociclette e dei motori sempre pi\u00f9 potenti e sofisticati&#8230; Sin da bambino, si interessava e sperimentava, con i pochi mezzi a disposizione, fino ad ottenere quello che, nel suo pensiero, doveva essere realizzato&#8230;\u00bb&nbsp; <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A parlarmi di questo personaggio che, onestamente, non conoscevo, \u00e8 Angelo Cavaleri, mentre gustiamo, a casa sua, una immensa porzione di orecchiette. <\/p>\n\n\n\n<p>Angelo parla con piacere della sua attivit\u00e0, maturata con anni e anni di esperienza sul campo (sono ventisei, ci confessa). In effetti, \u00e8 bravissimo nelle riparazioni, installazioni e cura di tutti i meccanismi elettrici ed elettronici che ci circondano: televisori, frigoriferi, elettrodomestici non hanno segreti, per lui&#8230; <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abSolo esperienza o anche la scuola possono far raggiungere risultati ottimali?\u00bb, gli chiediamo, sbirciando le portate che seguiranno al &#8216;primo&#8217;: intravediamo pomodori, rucola e pesce&#8230; va benissimo!<\/p>\n\n\n\n<p>\u00abLa scuola serve, naturalmente. Ma senza l&#8217;esperienza e il confronto con la realt\u00e0, non si va da nessuna parte. Del resto come affermava Leonardo Da Vinci: &#8216;L&#8217;esperienza \u00e8 maestra della&nbsp; sapienza&#8217;, no?\u00bb<\/p>\n\n\n\n<p>Mentre parliamo (e mangiamo) il telefonino di Angelo \u00e8 sempre attivo. E lui, pazientemente, non si sottrae a domande e interpelli di ogni genere. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00ab\u00c8 cos\u00ec ogni giorno, anche oggi che \u00e8 domenica&#8230; Scusa, rispondo&#8230;\u00bb<\/p>\n\n\n\n<p>Ne approfittiamo per fare amicizia col gatto di casa, che non disdegna le nostre confidenze&#8230;<\/p>\n\n\n\n<p>Quando Angelo torna a nostra disposizione, gli chiediamo notizie della sua famiglia: <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abViviamo in quattro, io con mia moglie e le mie figlie, Giorgia e Martina. Poi c&#8217;\u00e8 Candy, vedo che vi siete gi\u00e0 presentati. \u00c8 un amore di gatta&#8230;.\u00bb<\/p>\n\n\n\n<p>\u00abIl tuo mestiere, per\u00f2, \u00e8 squistamente maschile. Come mai? E le tue figlie non seguiranno le orme del padre?\u00bb<\/p>\n\n\n\n<p>Angelo si serve una abbondante scelta di pesce con pomodorini e rucola, prima di rispondere pacatamente: <\/p>\n\n\n\n<p>\u00abParliamoci chiaro: avere un&#8217;azienda privata significa far fronte a tutto da soli ed essere sempre a disposizione. Non \u00e8 facile e, spesso, vorrei avere un lavoro sicuro in una azienda&#8230;Ma la passione vince sempre, ormai mi soddisfa molto risolvere qualsiasi problema sia nascosto nei fili e nei meccanismi&#8230; No, le donne, per tradizione e per antiche usanze, non frequentano certi mestieri. Adesso le cose sono cambiate ma non vorrei che le mie figlie sopportassero quello che faccio io, quotidianamente&#8230; E non credo che a loro interessi, d&#8217;altra parte&#8230;\u00bb<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Abbiamo terminato, ringraziamo Angelo per l&#8217;ottimo pranzo e, con indifferenza, gli chiediamo:\u00abAngelo, non si accende la lampadina nel frigo&#8230; Puoi fare qualcosa?\u00bb<\/p>\n\n\n\n<p>Il nostro bravo tecnico sorride e, per lui, risponde Candy con un sommesso miagolio&#8230;<\/p>\n\n\n\n<p>____________<\/p>\n\n\n\n<p><strong>( 62 \u2010 continua )<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/il-pranzo-della-domenica-angelo-cavalera-meglio-del-signor-wolf-risolve-problemi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/27\/il-pranzo-della-domenica-angelo-cavalera-meglio-del-signor-wolf-risolve-problemi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo _________ \u00abIl mio idolo, il mio punto di riferimento \u00e8 sempre stato Honda, il fondatore e l&#8217;inventore delle motociclette e dei motori sempre pi\u00f9 potenti e sofisticati&#8230; Sin da bambino, si interessava e sperimentava, con i pochi mezzi a disposizione, fino ad ottenere quello che, nel suo pensiero, doveva essere realizzato&#8230;\u00bb&nbsp; A [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246317"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246317"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246317\/revisions"}],"predecessor-version":[{"id":246573,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246317\/revisions\/246573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246318"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}