{"id":246320,"date":"2025-07-23T11:05:00","date_gmt":"2025-07-23T09:05:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246320"},"modified":"2025-07-23T13:44:05","modified_gmt":"2025-07-23T11:44:05","slug":"controlli-a-tappeto-della-polizia-di-stato-tra-galatina-aradeo-e-secli","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-della-polizia-di-stato-tra-galatina-aradeo-e-secli\/","title":{"rendered":"CONTROLLI A TAPPETO DELLA POLIZIA DI STATO TRA GALATINA, ARADEO E SECLI&#8217;"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"737\" height=\"415\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/limiti-eta-concorsi-polizia-737x415-1.jpg\" alt=\"\" class=\"wp-image-246321\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/limiti-eta-concorsi-polizia-737x415-1.jpg 737w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/limiti-eta-concorsi-polizia-737x415-1-300x169.jpg 300w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/><\/figure>\n\n\n\n<p>(f.f.)_______<\/p>\n\n\n\n<p>Proseguono i controlli straordinari della Polizia di Stato sul territorio, con un\u2019operazione interforze che ieri pomeriggio ha interessato i comuni di Galatina, Aradeo e Secl\u00ec. L\u2019attivit\u00e0 rientra nel piano di sicurezza predisposto dal Questore di Lecce, Giampietro Lionetti, in attuazione delle direttive emerse in sede di Comitato per l\u2019ordine e la sicurezza pubblica.<\/p>\n\n\n\n<p>Il servizio, coordinato dal Commissariato di Galatina e supportato dal Reparto Prevenzione Crimine e dalla Polizia Locale, ha avuto come obiettivo la prevenzione di reati contro la persona e il patrimonio, oltre a verifiche in materia di immigrazione irregolare e irregolarit\u00e0 amministrative.<\/p>\n\n\n\n<p>Sono stati istituiti sei posti di controllo lungo le principali arterie stradali, che hanno portato all\u2019identificazione di 179 persone e alla verifica di 59 veicoli. La polizia locale ha prestato particolare attenzione a ciclomotori e motocicli: cinque le sanzioni elevate per violazioni al codice della strada, tra cui una per guida con patente scaduta e una per mancanza di assicurazione.<\/p>\n\n\n\n<p>Nel corso delle verifiche, sono stati ispezionati anche nove esercizi pubblici \u2013 cinque a Galatina e quattro ad Aradeo \u2013 oltre a una sala giochi. Per due locali commerciali sono stati richiesti approfondimenti: i titolari sono stati invitati a presentare la documentazione presso il Commissariato per ulteriori accertamenti.<\/p>\n\n\n\n<p>Attenzione particolare \u00e8 stata dedicata anche alle aree della movida giovanile, per contrastare eventuali episodi legati allo spaccio di stupefacenti. Le attivit\u00e0 di controllo proseguiranno anche nei prossimi giorni, in un\u2019ottica di prevenzione e presidio costante del territorio.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-della-polizia-di-stato-tra-galatina-aradeo-e-secli\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-della-polizia-di-stato-tra-galatina-aradeo-e-secli\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)_______ Proseguono i controlli straordinari della Polizia di Stato sul territorio, con un\u2019operazione interforze che ieri pomeriggio ha interessato i comuni di Galatina, Aradeo e Secl\u00ec. L\u2019attivit\u00e0 rientra nel piano di sicurezza predisposto dal Questore di Lecce, Giampietro Lionetti, in attuazione delle direttive emerse in sede di Comitato per l\u2019ordine e la sicurezza pubblica. Il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246320"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246320"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246320\/revisions"}],"predecessor-version":[{"id":246323,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246320\/revisions\/246323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246321"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}