{"id":246342,"date":"2025-07-23T11:07:00","date_gmt":"2025-07-23T09:07:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246342"},"modified":"2025-07-23T18:20:30","modified_gmt":"2025-07-23T16:20:30","slug":"controlli-a-tappeto-dei-carabinieri-in-tuttto-il-territorio-salentino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-dei-carabinieri-in-tuttto-il-territorio-salentino\/","title":{"rendered":"CONTROLLI A TAPPETO DEI CARABINIERI IN TUTTO IL TERRITORIO SALENTINO: FRA GLI ALTRI INTERVENTI, A LIZZANELLO ARRESTATO GIOVANE PER MOLESTIE"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1634\" height=\"1240\" class=\"wp-image-246343\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra.png 1634w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra-300x228.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra-1024x777.png 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra-768x583.png 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/controllsopra-1536x1166.png 1536w\" sizes=\"(max-width: 1634px) 100vw, 1634px\" \/><\/p>\n\n\n\n<p>(f.f.) ____________ <\/p>\n\n\n\n<p>La tutela della sicurezza pubblica e il rispetto della legalit\u00e0 rappresentano pilastri imprescindibili dell\u2019attivit\u00e0 quotidiana dell\u2019Arma dei Carabinieri. Un impegno che si concretizza non solo attraverso la repressione dei reati, ma anche grazie a una costante azione preventiva e di prossimit\u00e0 sul territorio. <\/p>\n\n\n\n<p>In quest\u2019ottica si inseriscono le recenti operazioni svolte dai militari dell\u2019Arma in diverse localit\u00e0 della provincia di Lecce, che hanno portato all\u2019arresto di soggetti resisi responsabili di gravi violazioni di legge e alla sanzione di comportamenti illeciti.<\/p>\n\n\n\n<p><br>A Salice Salentino, i Carabinieri della locale Stazione (foto sopra) hanno arrestato un uomo sottoposto al regime della detenzione domiciliare presso una comunit\u00e0 terapeutica del casaranese. Il soggetto si era arbitrariamente allontanato dalla struttura lo scorso 13 luglio, violando le prescrizioni imposte dal provvedimento restrittivo. Le attivit\u00e0 investigative e il costante monitoraggio del territorio hanno permesso ai militari dell\u2019Arma di rintracciarlo presso la sua abitazione e di eseguire l\u2019arresto. Dopo le formalit\u00e0 di rito, l\u2019uomo \u00e8 stato riaccompagnato presso la comunit\u00e0 per la prosecuzione della misura come disposto dal pm di turno della Procura della Repubblica di Lecce.<\/p>\n\n\n\n<p><br>L\u2019intervento dimostra l\u2019attenzione riservata anche ai soggetti affidati a percorsi alternativi di reinserimento, la cui corretta esecuzione rappresenta una garanzia per l\u2019intera collettivit\u00e0.<\/p>\n\n\n\n<p><br>Ancora pi\u00f9 delicato il caso registrato a Lizzanello, dove, nella scorsa serata, i Carabinieri della locale Stazione, con il supporto dei colleghi della Stazione di Cavallino e del Nucleo Radiomobile della compagnia di Lecce, hanno dato esecuzione a un\u2019ordinanza di custodia cautelare in carcere nei confronti di un uomo gi\u00e0 sottoposto alla misura del divieto di avvicinamento all\u2019ex convivente. Il provvedimento, emesso dall\u2019Autorit\u00e0 Giudiziaria di Lecce, rappresenta un aggravamento resosi necessario a fronte della reiterazione di condotte persecutorie. In un periodo in cui la tutela delle vittime di violenza domestica e di genere \u00e8 al centro del dibattito pubblico e dell\u2019impegno istituzionale, questa operazione sottolinea come l\u2019Arma sia in prima linea nell\u2019ascolto, nell\u2019intervento e nella protezione delle persone pi\u00f9 vulnerabili. L\u2019arrestato \u00e8 stato associato presso la Casa Circondariale di Lecce, dove rester\u00e0 a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n\n\n\n<p><br>Infine a Gallipoli, nell\u2019ambito delle attivit\u00e0 di prevenzione e presidio delle aree turistiche, i Carabinieri del NORM (foto sotto) sono intervenuti presso il porticciolo del Canneto, dove hanno sanzionato due persone intenti a esercitare abusivamente l\u2019attivit\u00e0 di parcheggiatore. L\u2019intervento, effettuato ai sensi dell\u2019art. 7, comma 15 del Codice della Strada, rientra in una pi\u00f9 ampia strategia di contrasto alle micro-illegalit\u00e0 che comunque incidono negativamente sulla qualit\u00e0 della vita e sull\u2019immagine del territorio, specie durante la stagione turistica. La presenza costante dell\u2019Arma nelle zone maggiormente frequentate da cittadini e visitatori rappresenta un presidio attivo di legalit\u00e0 e decoro urbano.<\/p>\n\n\n\n<p><br>L\u2019Arma dei Carabinieri rinnova il proprio impegno al fianco della cittadinanza e invita tutti a collaborare, segnalando situazioni sospette o comportamenti illeciti. La sicurezza non \u00e8 solo un obiettivo da raggiungere, ma un bene comune da costruire insieme ogni giorno, attraverso la fiducia, la legalit\u00e0 e il senso civico.<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1754\" height=\"1069\" class=\"wp-image-246344\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto.png\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto.png 1754w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto-300x183.png 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto-1024x624.png 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto-768x468.png 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/conntrocarasotto-1536x936.png 1536w\" sizes=\"(max-width: 1754px) 100vw, 1754px\" \/><br><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-dei-carabinieri-in-tuttto-il-territorio-salentino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/controlli-a-tappeto-dei-carabinieri-in-tuttto-il-territorio-salentino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.) ____________ La tutela della sicurezza pubblica e il rispetto della legalit\u00e0 rappresentano pilastri imprescindibili dell\u2019attivit\u00e0 quotidiana dell\u2019Arma dei Carabinieri. Un impegno che si concretizza non solo attraverso la repressione dei reati, ma anche grazie a una costante azione preventiva e di prossimit\u00e0 sul territorio. In quest\u2019ottica si inseriscono le recenti operazioni svolte dai militari [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246343,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246342"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246342"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246342\/revisions"}],"predecessor-version":[{"id":246361,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246342\/revisions\/246361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246343"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}