{"id":246362,"date":"2025-07-23T18:43:14","date_gmt":"2025-07-23T16:43:14","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246362"},"modified":"2025-07-29T13:28:39","modified_gmt":"2025-07-29T11:28:39","slug":"laeroporto-di-leverano-le-battaglie-nei-cieli-del-salento-nella-seconda-guerra-mondiale-una-vera-e-propria-chicca-storica-recuperata-e-divulgata-su-leccecronaca-it-dal-piu-giovane-dei-nostri-re","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/laeroporto-di-leverano-le-battaglie-nei-cieli-del-salento-nella-seconda-guerra-mondiale-una-vera-e-propria-chicca-storica-recuperata-e-divulgata-su-leccecronaca-it-dal-piu-giovane-dei-nostri-re\/","title":{"rendered":"L&#8217;AEROPORTO DI LEVERANO. LE BATTAGLIE NEI CIELI DEL SALENTO NELLA SECONDA GUERRA MONDIALE. UNA VERA E PROPRIA CHICCA STORICA, RECUPERATA E DIVULGATA SU leccecronaca.it DAL PIU&#8217; GIOVANE DEI NOSTRI REDATTORI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1017\" height=\"684\" class=\"wp-image-246363\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/aeroporto1.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/aeroporto1.jpg 1017w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/aeroporto1-300x202.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/aeroporto1-768x517.jpg 768w\" sizes=\"(max-width: 1017px) 100vw, 1017px\" \/><\/p>\n\n\n\n<p>di <strong>Giovanni Gemma ___________<\/strong><\/p>\n\n\n\n<p>Nella piana strada verso il fresco mare di Porto Cesareo, le campagne intorno a Leverano sono d\u2019estate un <em>tran-tran<\/em> di persone. Chi va in vacanza, chi ci torna, chi usa le sue ore libere per andare a respirare la brezza salata, chi fugge dal lavoro e chi al lavoro ci va, tra i campi rigogliosi e i vigneti. <\/p>\n\n\n\n<p>\u00c8 lo spettacolo dell\u2019ampia pianura salentina, arrossato dal Sole che batte alternandosi con un cielo stellato senza orizzonti a limitarlo. Le cicale si alternano alle civette, l\u2019assolato al solitario.<\/p>\n\n\n\n<p>Luogo di passaggio, luogo di lavoro. Ma qui non ci interessano descrizioni da <em>pro loco<\/em>. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Questo rapidissimo affresco serviva per introdurre il suo opposto: un panorama di divise, munizioni, bombardieri, trincee improvvisate, svastiche, e infine sangue. \u00c8 pi\u00f9 nota, nella zona nordoccidentale del Salento, la presenza \u2013 dal 1944 al 1947 \u2013 di un campo profughi per ebrei sopravvissuti alla Shoah: il <em>Displaced Persons Camp number 34<\/em> dell\u2019agenzia ONU per l\u2019assistenza, a Santa Maria al Bagno.<\/p>\n\n\n\n<p>\u00c8 meno nota la presenza invece dell\u2019\u00abaeroporto di Lecce\u00bb, uno scalo militare costruito tra 1940 e 1941 a ridosso di Leverano. Una zona pianeggiante, non lontana dal capoluogo Lecce e nemmeno da Taranto \u2013 centro nevralgico della Marina italiana. Di cui oggi non rimane traccia \u2013 e ora capiremo perch\u00e9.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Innanzitutto, Lecce non era gi\u00e0 rifornita dallo scalo di Galatina? Era stato costruito nel 1931, cinque anni dopo era gi\u00e0 al rango \u00abregio aeroporto di II classe\u00bb, adatto a ospitare bombardieri e velivoli di trasporto militare. Inoltre, l\u2019aeroporto di Galatina, in piena campagna. grazie alle nebbie, era ottima per fornire una copertura \u201cnaturale\u201d alle strutture. Che bisogno c\u2019era, dunque, di costruire un altro aeroporto militare non lontano e, soprattutto, praticamente adiacente all\u2019abitato di Leverano, mettendo a rischio gli abitanti della cittadina?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il motivo si ritrova nelle avventure mussoliniane nel Mediterraneo. L\u2019Italia fascista tentava di ritagliarsi un ruolo dominante nel <em>mare nostrum<\/em>, invece si scopr\u00ec presto debole e inadeguata. La campagna in Grecia \u2013 \u00abspezzeremo le reni\u00bb eccetera eccetera \u2013 si stava risolvendo in una pericolosissima controffensiva delle forze greche (regolari e irregolari) sostenute dai britannici e aiutate indirettamente dai partigiani albanesi. La base marina di Taranto, gioiello mediterraneo di Roma, fu pesantemente danneggiata in un umiliante <em>raid<\/em> della RAF \u2013 che avrebbe fatto scuola nella Seconda guerra mondiale, tant\u2019\u00e8 che i giapponesi copiarono le tattiche britanniche per attaccare Pearl Harbor.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Mussolini e i suoi gerarchi, anche dinanzi alla prudenza di alcuni ufficiali dello Stato maggiore, sognavano un mare dominato, ma ben presto capirono che bisognava fortificare il gi\u00e0 esistente per non perdere anche quello. E, soprattutto, capirono che senza la forza dei tedeschi l\u2019Italia era \u2013 come avrebbe detto correttamente Churchill \u2013 \u00abventre molle\u00bb dell\u2019Europa. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>In questo contesto nasce l\u2019aeroporto di Leverano: un avamposto ufficialmente scollegato da Galatina, che per\u00f2 doveva fare da guardaspalle proprio a quest\u2019ultima e viceversa.<\/p>\n\n\n\n<p>E all\u2019inizio ci riusc\u00ec. <\/p>\n\n\n\n<p>Nella primavera del 1943, subito dopo la prima grande minaccia interna in vent\u2019anni al potere fascista \u2013 l\u2019ondata di scioperi nelle fabbriche del marzo di quell\u2019anno \u2013, i cieli italiani divennero un groviera per i bombardieri angloamericani. Anche la Puglia fu interessata da queste operazioni, in particolare Foggia divenne un cumulo di macerie.<\/p>\n\n\n\n<p>La zona leccese, priva di industrie strategiche o granai fondamentali, fu sostanzialmente risparmiata da grandi massacri. Ci\u00f2 nonostante, l\u2019Aviazione tedesca decise comunque di potenziare lo scalo di Lecce, riempiendolo di <em>Stuka<\/em> (tecnicamente <em>Junkers Ju 87<\/em>), agili e piccoli aerei da combattimento, e creando un comando militare di Berlino in una masseria leveranense,  dove si trovano dei graffiti in tedesco di annoiati avieri d\u2019oltralpe.<\/p>\n\n\n\n<p>La presenza dell\u2019aeroporto di Leverano, infatti, poteva essere un problema per i piani degli Alleati, che avrebbero dovuto cominciare da l\u00ec a poco l\u2019Operazione Husky: lo sbarco in Sicilia. Intanto, la paura di un\u2019invasione di terra metteva terrore tra i civili, disabituati a qualsiasi conflitto in casa, che perci\u00f2 iniziarono a scavare improvvisate trincee e sgangherati rifugi sotterranei.<\/p>\n\n\n\n<p>Il 2 luglio 1943, per la prima volta, il Salento si trov\u00f2 attraversato da un grosso stormo di <em>B-24 Liberator<\/em>, maestose e micidiali fortezze volanti della flotta alleata. L\u2019obiettivo era l\u2019aeroporto \u201cdi Lecce\u201d, ma \u2013 non si sa se per un errore di calcolo o per una mancanza di informazioni \u2013 l\u2019attacc\u00f2 non and\u00f2 del tutto bene.<\/p>\n\n\n\n<p>I B-24 si trovarono l\u2019aeroporto di Galatina, utilizzando una tersa mattinata (un rischio di non poco conto, per\u00f2 almeno si garantiva la visibilit\u00e0 dell\u2019obiettivo), e iniziarono a sganciare il loro carico. Allora, per\u00f2, trovarono anche una sorpresa: uno stormo di Stuka li intercett\u00f2, abbattendo i velivoli degli Alleati. Erano gli Stuka di Leverano, mai presi in considerazione nei piani alleati, che limitarono i danni alle strutture militari dell\u2019Asse in Salento.<\/p>\n\n\n\n<p>Tra gli aerei caduti, si ricordano bene gli anziani di Muro Leccese un B-24 che stava precipitando sul paesino, terrorizzando suo malgrado gli inermi abitanti; il pilota dell\u2019aereo evit\u00f2 alla fine il peggio, riuscendo a virare questo bestione dell\u2019aria con quel che rimaneva dei motori, andandosi a schiantare in un bosco di lecci poco fuori Muro. Nessuno degli otto avieri statunitensi sopravvisse.<\/p>\n\n\n\n<p>In ogni caso, il risultato non soddisfacente dell\u2019operazione diede da pensare a comandanti alleati, i quali decisero quindi di progettare l\u2019attacco alla giovane base leveranense. Nel frattempo, il ben riuscito sbarco in Sicilia indebol\u00ec le posizioni italotedesche. <\/p>\n\n\n\n<p>Fu all\u2019ora di pranzo del 23 luglio 1943 che quaranta B-24 terminarono la veloce carriera dell\u2019aeroporto di Leverano.<\/p>\n\n\n\n<p>Messa fuori gioco Galatina tre settimane prima, l\u2019incursione fu relativamente semplice \u2013 e fu un successo. <\/p>\n\n\n\n<p>Per alcuni minuti il paese visse un incubo: la vicinanza dell\u2019aeroporto all\u2019abitato insanguin\u00f2 l\u2019attacco di vittime civili, e rese inutilizzabile le piste. Fu un episodio abbastanza raro nella storia salentina della Seconda guerra mondiale: in un territorio dove le incursioni erano poche, i bombardamenti ancor di meno e le morti tra i paesani persino di meno, l\u2019attacco sull\u2019aeroporto di Leverano segn\u00f2 un \u201cpiccolo\u201d trauma per la comunit\u00e0 locale.<\/p>\n\n\n\n<p>Da allora, la vita quotidiana dei contadini salentini ha provveduto a eliminare le tracce dell\u2019aeroporto, mentre le autorit\u00e0 non hanno continuato in nessun modo il progetto dell\u2019aeroporto di Lecce. <\/p>\n\n\n\n<p>Eppure, nel paese ancora si tramandano le storie e gli aneddoti di una storia rapida e dolorosa che ha tracciato un sentiero diretto tra le sonnacchiose vicende del Tacco d\u2019Italia e la \u201cgrande\u201d Storia del conflitto pi\u00f9 sanguinoso d\u2019Europa. Una vicenda che il resto della provincia ha provveduto a rimuovere immediatamente dalla coscienza collettiva \u2013 un po\u2019 come quando oggi andiamo in spiaggia o su alcuni costoni marini e vediamo le vecchie torrette d\u2019avvistamento in cemento armato, segno di un capitolo di un saggio che non c\u2019\u00e8 mai stato bisogno di scrivere.<\/p>\n\n\n\n<p>Ma, mentre questi reperti del passato \u2013 in piedi o solo nella mente degli anziani \u2013 sono esclusi dalla narrazione del territorio nonostante la loro \u201crecente\u201d et\u00e0, fiumi di inchiostro e di marketing si versano sulle torri barbaresche o sulle masserie fortificate, segni di un passato decisamente pi\u00f9 vetusto.<\/p>\n\n\n\n<p>Un po\u2019, viene il sospetto si tratti di una mossa collettiva da Gattopardo: \u00e8 molto pi\u00f9 facile ricordare, per la popolazione e i suoi governanti, le difese da un nemico esterno che il fallimento di una guerra in cui, la miccia, l\u2019abbiamo accesa noi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/laeroporto-di-leverano-le-battaglie-nei-cieli-del-salento-nella-seconda-guerra-mondiale-una-vera-e-propria-chicca-storica-recuperata-e-divulgata-su-leccecronaca-it-dal-piu-giovane-dei-nostri-re\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/23\/laeroporto-di-leverano-le-battaglie-nei-cieli-del-salento-nella-seconda-guerra-mondiale-una-vera-e-propria-chicca-storica-recuperata-e-divulgata-su-leccecronaca-it-dal-piu-giovane-dei-nostri-re\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giovanni Gemma ___________ Nella piana strada verso il fresco mare di Porto Cesareo, le campagne intorno a Leverano sono d\u2019estate un tran-tran di persone. Chi va in vacanza, chi ci torna, chi usa le sue ore libere per andare a respirare la brezza salata, chi fugge dal lavoro e chi al lavoro ci va, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246363,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246362"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246362"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246362\/revisions"}],"predecessor-version":[{"id":246364,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246362\/revisions\/246364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246363"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}