{"id":246410,"date":"2025-07-24T13:10:00","date_gmt":"2025-07-24T11:10:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246410"},"modified":"2025-07-24T18:24:47","modified_gmt":"2025-07-24T16:24:47","slug":"lecce-scoperto-con-un-chilo-di-eroina-nello-zaino-arrestato-dalla-polizia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/24\/lecce-scoperto-con-un-chilo-di-eroina-nello-zaino-arrestato-dalla-polizia\/","title":{"rendered":"SCOPERTO CON UN CHILO DI EROINA NELLO ZAINO DURANTE UN CONTROLLO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/Foto-2-768x1024.jpg\" alt=\"\" class=\"wp-image-246411\" width=\"396\" height=\"528\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/Foto-2-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/Foto-2-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/Foto-2-1152x1536.jpg 1152w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/Foto-2.jpg 1200w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/figure>\n\n\n\n<p>(f.f.)________<\/p>\n\n\n\n<p>\u00c8 stato bloccato dagli agenti della Polizia di Stato nel tardo pomeriggio di ieri, mentre viaggiava a bordo della sua auto lungo una strada cittadina. Un normale controllo di routine, inserito nell\u2019ambito dei serrati servizi di pattugliamento del territorio disposti dalla Questura di Lecce, ha condotto all\u2019arresto di un uomo di 57 anni, Alessandro Petracca, di Surbo, con precedenti specifici, trovato in possesso di oltre un chilo di eroina.<\/p>\n\n\n\n<p>L\u2019episodio \u00e8 avvenuto intorno alle 18.45, quando una pattuglia della Sezione Volanti ha intercettato un veicolo sospetto che procedeva nella stessa direzione degli equipaggi. Alla richiesta dei documenti, l\u2019uomo \u2013 gi\u00e0 noto alle forze dell\u2019ordine per precedenti legati allo spaccio di droga \u2013 ha aperto lo zaino per recuperare il portafogli.<\/p>\n\n\n\n<p>\u00c8 stato proprio in quel momento che i poliziotti hanno notato due voluminosi panetti di cellophane marrone, sigillati con nastro bianco, nascosti all\u2019interno del bagaglio.L\u2019intuizione degli agenti ha trovato conferma nella perquisizione immediata dell\u2019auto e della persona, che ha portato al rinvenimento, sempre nello zaino, anche di un coltello a serramanico.<\/p>\n\n\n\n<p>La lama risultava imbrattata di una sostanza marrone, verosimilmente eroina, utilizzata con ogni probabilit\u00e0 per il frazionamento dello stupefacente.I controlli sono poi proseguiti nell\u2019abitazione dell\u2019uomo, dove gli agenti hanno scoperto un bilancino di precisione e un calendario con annotazioni quotidiane di somme di denaro, verosimilmente riconducibili a transazioni legate allo spaccio.<\/p>\n\n\n\n<p>La sostanza, del peso complessivo di 1,016 chilogrammi, \u00e8 stata sottoposta a narco-test da parte del personale della Polizia Scientifica, rivelando la presenza di eroina, morfina e codeina. Tutto il materiale rinvenuto, compresi il coltello, lo zaino e gli appunti contabili, \u00e8 stato sequestrato.Al termine delle formalit\u00e0 di rito, l\u2019uomo \u00e8 stato arrestato con l\u2019accusa di detenzione ai fini di spaccio di sostanze stupefacenti e, su disposizione del pubblico ministero di turno, trasferito presso la casa circondariale di Lecce, in attesa delle decisioni dell\u2019autorit\u00e0 giudiziaria.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/24\/lecce-scoperto-con-un-chilo-di-eroina-nello-zaino-arrestato-dalla-polizia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/24\/lecce-scoperto-con-un-chilo-di-eroina-nello-zaino-arrestato-dalla-polizia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)________ \u00c8 stato bloccato dagli agenti della Polizia di Stato nel tardo pomeriggio di ieri, mentre viaggiava a bordo della sua auto lungo una strada cittadina. Un normale controllo di routine, inserito nell\u2019ambito dei serrati servizi di pattugliamento del territorio disposti dalla Questura di Lecce, ha condotto all\u2019arresto di un uomo di 57 anni, Alessandro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246410"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246410"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246410\/revisions"}],"predecessor-version":[{"id":246430,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246410\/revisions\/246430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246411"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}