{"id":246441,"date":"2025-07-25T12:12:11","date_gmt":"2025-07-25T10:12:11","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246441"},"modified":"2025-07-25T12:12:14","modified_gmt":"2025-07-25T10:12:14","slug":"arrestato-a-brindisi-un-31enne-per-coltivazione-di-marijuana-in-casa","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/arrestato-a-brindisi-un-31enne-per-coltivazione-di-marijuana-in-casa\/","title":{"rendered":"ARRESTATO A BRINDISI UN 31ENNE PER COLTIVAZIONE DI MARIJUANA IN CASA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/175327626815fc86_l-logo.jpeg\" alt=\"\" class=\"wp-image-246442\" width=\"396\" height=\"297\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/175327626815fc86_l-logo.jpeg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/175327626815fc86_l-logo-300x225.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/175327626815fc86_l-logo-768x576.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/175327626815fc86_l-logo-400x300.jpeg 400w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/figure>\n\n\n\n<p>(f.f.)________<\/p>\n\n\n\n<p>Una coltivazione domestica di marijuana ben organizzata, con tanto di serre artigianali, essiccatori, lampade e fertilizzanti. \u00c8 quanto hanno scoperto gli agenti della Squadra Mobile della Questura di Brindisi nel tardo pomeriggio del 22 luglio, durante una perquisizione domiciliare a carico di un uomo del posto, classe 1993, gi\u00e0 noto alle forze dell\u2019ordine per precedenti specifici.<\/p>\n\n\n\n<p>L\u2019arresto \u00e8 scattato nell\u2019ambito di mirati controlli disposti dal Questore e rientra nell\u2019attivit\u00e0 ordinaria di contrasto allo spaccio di sostanze stupefacenti sul territorio.<\/p>\n\n\n\n<p>Gli agenti, insospettiti da alcune segnalazioni, hanno fatto irruzione nell\u2019abitazione del 32enne, dove hanno rinvenuto circa 3 chilogrammi di marijuana, gi\u00e0 in parte essiccata e pronta per essere immessa sul mercato, oltre a tutta la strumentazione necessaria per la coltivazione indoor della cannabis: semi, vasi, serre casalinghe, lampade a incandescenza, ventilatori e prodotti per la concimazione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"609\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/1753276518157ec0_l-logo.jpg\" alt=\"\" class=\"wp-image-246443\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/1753276518157ec0_l-logo.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/1753276518157ec0_l-logo-300x203.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/1753276518157ec0_l-logo-768x520.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Tutto il materiale, compresa la sostanza stupefacente, \u00e8 stato posto sotto sequestro. L\u2019uomo \u00e8 stato arrestato in flagranza di reato con l\u2019accusa di coltivazione illecita di sostanze stupefacenti.<\/p>\n\n\n\n<p>Dopo le formalit\u00e0 di rito, \u00e8 stato condotto presso la Casa Circondariale di Brindisi, come disposto dall\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/arrestato-a-brindisi-un-31enne-per-coltivazione-di-marijuana-in-casa\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/arrestato-a-brindisi-un-31enne-per-coltivazione-di-marijuana-in-casa\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)________ Una coltivazione domestica di marijuana ben organizzata, con tanto di serre artigianali, essiccatori, lampade e fertilizzanti. \u00c8 quanto hanno scoperto gli agenti della Squadra Mobile della Questura di Brindisi nel tardo pomeriggio del 22 luglio, durante una perquisizione domiciliare a carico di un uomo del posto, classe 1993, gi\u00e0 noto alle forze dell\u2019ordine per [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246441"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246441"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246441\/revisions"}],"predecessor-version":[{"id":246444,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246441\/revisions\/246444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246442"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}