{"id":246538,"date":"2025-07-26T18:35:01","date_gmt":"2025-07-26T16:35:01","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246538"},"modified":"2025-07-29T13:26:47","modified_gmt":"2025-07-29T11:26:47","slug":"un-albero-di-trenta-piani-piu-di-mezzo-secolo-fa-la-lucida-quanto-terribile-profezia-di-adriano-celentano-su-milano-emblema-delle-citta-disumanizzate-lecce-compresa-con-la-sua-edilizia-solo-pe","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/26\/un-albero-di-trenta-piani-piu-di-mezzo-secolo-fa-la-lucida-quanto-terribile-profezia-di-adriano-celentano-su-milano-emblema-delle-citta-disumanizzate-lecce-compresa-con-la-sua-edilizia-solo-pe\/","title":{"rendered":"UN ALBERO DI TRENTA PIANI. PIU&#8217; DI MEZZO SECOLO FA LA LUCIDA QUANTO TERRIBILE PROFEZIA DI ADRIANO CELENTANO SU MILANO, EMBLEMA DELLE CITTA&#8217; DISUMANIZZATE. LECCE COMPRESA, CON LA SUA EDILIZIA SOLO PER I RICCHI"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"642\" class=\"wp-image-246539\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/SANTA-ROSA.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/SANTA-ROSA.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/SANTA-ROSA-300x201.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/SANTA-ROSA-768x514.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p>di <strong>Giuseppe Puppo __________ <\/strong><\/p>\n\n\n\n<p>\u00abMalgrado gli sforzi di architetti e urbanisti di grande valore, non siamo riusciti a evitare sul piano globale un processo di lacerante decomposizione del tessuto urbano, la cementificazione del territorio, la lottizzazione del paesaggio, l&#8217;aumento della bruttezza nella qualit\u00e0 della vita e la distruzione dell&#8217;ambiente.<\/p>\n\n\n\n<p>Per non parlare del clamoroso fallimento nel ridurre il consumo di energia e l&#8217;impronta ecologica. L&#8217;economia della crescita agisce sui luoghi corrodendone il senso e sgretolando il tessuto sociale\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lui, Serge Latouche, 85 anni, economista e filosofo francese, ideatore della ormai celebre teoria della &#8216;decrescita felice&#8217;, \u00e8 tornato in questi giorni a parlare di quanto sta avvenendo alle nostre citt\u00e0.<\/p>\n\n\n\n<p>Chi non studia, ma almeno segue la cronaca, sapr\u00e0 di quanto sta avvenendo in questi giorni a Milano, dove c&#8217;\u00e8 una nuova &#8216;mani pulite&#8217; in corso che travolge l&#8217;amministrazione comunale di centro sinistra, e non solo, perch\u00e8 al governo di centro destra nazionale hanno fatto di tutto per salvarla, evidentemente per ragioni di complicit\u00e0, o connivenza politica.<\/p>\n\n\n\n<p>Gi\u00e0, non abbiamo bisogno degli esiti dell&#8217;indagine della magistratura, per capire chi siano i responsabili e che cosa abbiano fatto, al di l\u00e0 delle responsabilit\u00e0 penali che sono personali.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A noi che studiamo e seguiamo la cronaca, gli esiti letali di una sinistra che invece di fare le case popolari, che in Italia non si fanno pi\u00f9 dai tempi democristianissimi di Amintore Fanfani, fa i grattacieli per i fondi di investimento dell&#8217;alta finanza internazionale  e per gli speculatori dell&#8217;occulta strategia di dominio senza confini, sono gi\u00e0 evidenti: una metropoli, un tempo &#8216;capitale morale&#8217; del Paese, che espelle i suoi abitanti dal tessuto urbano e li condanna a vivere come in esilio altrove, perch\u00e9 sulle loro case offuscate da quelle moderne non batte pi\u00f9 il sole e perch\u00e9 il costo della vita \u00e8 diventato insostenibile, per quello che un tempo era &#8216;il ceto medio&#8217;, motore della dignit\u00e0 economica e del decoro sociale della Nazione.<\/p>\n\n\n\n<p>Quartieri ghetto, sia pur di lusso, dove nonostante ci\u00f2 regna l&#8217;anonimato e dove trionfa la solitudine, e quartieri ghetto della povert\u00e0 nelle periferie degradate.<\/p>\n\n\n\n<p>A Roma, se leviamo i grattacieli, mutatis mutandis \u00e8 lo stesso, per la speculazione edilizia, che impedisce alle giovani coppie di mettere su casa e dunque famiglia: acquisti impossibili per i prezzi esorbitanti, affitti &#8220;normali&#8221; introvabili, precariet\u00e0 diffusa dilagante.<\/p>\n\n\n\n<p>E a Lecce?<\/p>\n\n\n\n<p>Desidero ringraziare &#8211; soprattutto chi mi ha criticato: va bene tutto, ma tranquilli, non sono n\u00e9 parente, n\u00e9 sodale di Salvemini, n\u00e8 parente serpente, n\u00e8 nemico della Poli Bortone, cerco di fare solo il mio lavoro in onest\u00e0 intellettuale &#8211; i tanti lettori di <strong>leccecronaca.it <\/strong>che hanno seguito con attenzione la mia riflessione dell&#8217;altro giorno sulla citt\u00e0 vista dalla prospettiva semplice, ma efficace di una passeggiata a piedi lungo i viali cittadini. <\/p>\n\n\n\n<p>Detto quanto da quella sede ho voluto condividere, aggiungo adesso che dal punto di vista edilizio anche qui non ci sono grattacieli, ma ci sono i costruttori, gli affaristi e i lobbysti anche politici in servizio permanente effettivo, al servizio dei ricchi, non dei poveri, di chi fa affari con le speculazioni edilizie del &#8216;lusso&#8217; e non con un impegno per i ceti sociali popolari.<\/p>\n\n\n\n<p>No, in questa sede non voglio parlare della recente bufera giudiziaria che nel nostro Salento ha coinvolto politici e imprenditori, che tutti conoscete gi\u00e0 e di cui aspettiamo adesso gli esiti.<\/p>\n\n\n\n<p>Voglio per\u00f2 &#8211; a parte &#8211; fare due esempi, uno vecchio e uno nuovo, circoscritti alla stessa zona del campo sportivo di Santa Rosa, che a Lecce tutti chiamano il Coni.<\/p>\n\n\n\n<p>Qui, nel marzo 2014, in virt\u00f9 di decisioni incomprensibili e varianti urbanistiche impazzite, tagliarono tutti gli alberi su via Giammatteo di fronte alla scuola &#8220;delle suore&#8221; istituto Smaldone e, fatta tabula rasa, ci realizzarono una serie di villette di lusso: un vero e proprio scempio edilizio (nella foto di copertina, una manifestazione di protesta di cittadini, cui partecipai anche io)<\/p>\n\n\n\n<p>Qui, dal marzo 2015, in una zona fra l&#8217;altro gi\u00e0 congestionata dalle presenza di vecchi palazzi e nuove villette, sempre sul lato destro di via Giammatteo, stanno costruendo un altro mostro edilizio di cinque piani di lusso, spacciato quale giardino e oasi di confort. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Anche il Coni del resto \u00e8 sotto assedio, gi\u00e0 da tempo con il verde degli alberi mal curato, o trascurato del tutto. Sar\u00e0 un caso che da ieri hanno cominciato a sfoltire ed eradicare i pini anche all&#8217;interno?<\/p>\n\n\n\n<p>E ora rileggetevi per favore Serge Latouche.<\/p>\n\n\n\n<p>Chi invece non abbia voglia di studi impegnati, ascolti almeno per favore una canzone di musica leggera, a mio modo di intendere tornata in questi giorni di attualit\u00e0, con tutti i suoi significati e significanti profetici.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Un Albero Di Trenta Piani\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/ovWX09Uy2iQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>___________<\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo del 24 luglio scorso<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"CAh00Ccxvp\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/24\/se-una-mattina-destate-un-viaggiatore-a-piedi-in-una-lecce-disastrata-e-senza-piu-identita\/\">SE UNA MATTINA D&#8217;ESTATE UN VIAGGIATORE, A PIEDI, IN UNA LECCE DISASTRATA E SENZA PIU&#8217; IDENTITA&#8217;<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;SE UNA MATTINA D&#8217;ESTATE UN VIAGGIATORE, A PIEDI, IN UNA LECCE DISASTRATA E SENZA PIU&#8217; IDENTITA&#8217;&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/24\/se-una-mattina-destate-un-viaggiatore-a-piedi-in-una-lecce-disastrata-e-senza-piu-identita\/embed\/#?secret=5Zwkg7nX8a#?secret=CAh00Ccxvp\" data-secret=\"CAh00Ccxvp\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p> <\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/26\/un-albero-di-trenta-piani-piu-di-mezzo-secolo-fa-la-lucida-quanto-terribile-profezia-di-adriano-celentano-su-milano-emblema-delle-citta-disumanizzate-lecce-compresa-con-la-sua-edilizia-solo-pe\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/26\/un-albero-di-trenta-piani-piu-di-mezzo-secolo-fa-la-lucida-quanto-terribile-profezia-di-adriano-celentano-su-milano-emblema-delle-citta-disumanizzate-lecce-compresa-con-la-sua-edilizia-solo-pe\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo __________ \u00abMalgrado gli sforzi di architetti e urbanisti di grande valore, non siamo riusciti a evitare sul piano globale un processo di lacerante decomposizione del tessuto urbano, la cementificazione del territorio, la lottizzazione del paesaggio, l&#8217;aumento della bruttezza nella qualit\u00e0 della vita e la distruzione dell&#8217;ambiente. Per non parlare del clamoroso fallimento [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246539,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246538"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246538"}],"version-history":[{"count":8,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246538\/revisions"}],"predecessor-version":[{"id":246558,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246538\/revisions\/246558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246539"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}