{"id":246737,"date":"2025-08-03T15:30:00","date_gmt":"2025-08-03T13:30:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246737"},"modified":"2025-08-07T12:06:26","modified_gmt":"2025-08-07T10:06:26","slug":"il-pranzo-della-domenica-le-riduzioni-di-mauro-de-carlo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/03\/il-pranzo-della-domenica-le-riduzioni-di-mauro-de-carlo\/","title":{"rendered":"IL PRANZO DELLA DOMENICA \/\u00a0LE &#8216;RIDUZIONI&#8217; DI MAURO DE CARLO"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1600\" class=\"wp-image-246738\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago.jpg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago-169x300.jpg 169w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago-576x1024.jpg 576w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago-768x1365.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/07\/coverpolo-3-ago-864x1536.jpg 864w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n\n<p>di <strong>Raffaele Polo _____________<\/strong><\/p>\n\n\n\n<p>\u00c8 una vera e propria lezione di cucine quella&nbsp; che ci impartisce, sorridendo, Mauro De Carlo, che scopriamo lontano dalla sua veste ufficiale di Sindaco di Vernole. Al contrario di come ci aspettavamo, ci coinvolge subito nella preparazione di alcune misture che -lo confessiamo- conoscevamo molto superficialmente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abCome avrai indovinato, mi piace molto tutto ci\u00f2 che ruota attorno alla cucina: mangio tutto, sono una buona forchetta e anche un discreto cuoco.<\/p>\n\n\n\n<p>Preferisco un buon primo e secondi di pesce.&nbsp; Adoro le riduzioni, il fondo bruno e le spezie&#8230;\u00bb <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abSembra un linguaggio legato alla tua attivit\u00e0 di Sindaco. Fondo bruno? Riduzioni?\u00bb <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Mauro sorride e si cinge con un grembiulone, mentre spadella nella sua fornitissima cucina: <\/p>\n\n\n\n<p>\u00abPurtroppo e per fortuna, non faccio solo il sindaco. O meglio, non facevo solo il sindaco. Ora per ovvi motivi il tempo che dedico alla mia libera professione \u00e8 diminuito. Sono un consulente tecnico amministrativo (a partita iva&#8230;.per la gioia del fisco italiano) e quello continuer\u00f2 a fare quando terminer\u00f2 la mia attivit\u00e0 da amministratore. Comunque, non ti spaventare: tecnicamente, una riduzione \u00e8 una salsa molto saporita e piuttosto densa che si ottiene facendo restringere sul fuoco un ingrediente di partenza liquido e dal gusto meno intenso, tipicamente un vino o un aceto\u00bb. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Il profumo che si propaga dalla pentola indica che la salsa \u00e8 pronta e Mauro ci spiega ancora: <\/p>\n\n\n\n<p>\u00abIl fondo bruno, o fondo scuro, \u00e8 una salsa densa e saporita che si prepara con ossa e carne di vitello, pollo, agnello o selvaggina, a seconda della ricetta da realizzare, con l&#8217;aggiunta di verdure e aromi\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Siamo veramente sorpresi: mai visto un sindaco cos\u00ec fattivo e ricco di profumi e sostanza. Ci accomodiamo al tavolo, dove altre vivande ci attendono. E non possiamo che andare, con la memoria, al ricordo del pap\u00e0 di Mauro, Livio De Carlo, insigne letterato e autore di tante spassose commedie in dialetto salentino. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abSe adesso ci foss\u00e8 pap\u00e0, cosa ti direbbe?\u00bb <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u00abDi lui ricordo soprattutto la correttezza e la battuta sempre pronta. E un modo di guardarmi sotto gli occhiali con un orgoglio mai nascosto&#8230; \u00bb<\/p>\n\n\n\n<p>Ricordi, nostalgie, il tempo che passa, tutto si confonde, si armonizza con il pesante profumo del fondo bruno&#8230;.<\/p>\n\n\n\n<p>____________<\/p>\n\n\n\n<p><strong>( 63 \u2010 continua )<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/03\/il-pranzo-della-domenica-le-riduzioni-di-mauro-de-carlo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/03\/il-pranzo-della-domenica-le-riduzioni-di-mauro-de-carlo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Raffaele Polo _____________ \u00c8 una vera e propria lezione di cucine quella&nbsp; che ci impartisce, sorridendo, Mauro De Carlo, che scopriamo lontano dalla sua veste ufficiale di Sindaco di Vernole. Al contrario di come ci aspettavamo, ci coinvolge subito nella preparazione di alcune misture che -lo confessiamo- conoscevamo molto superficialmente. \u00abCome avrai indovinato, mi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246737"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246737"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246737\/revisions"}],"predecessor-version":[{"id":247011,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246737\/revisions\/247011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246738"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}