{"id":246872,"date":"2025-08-01T12:51:12","date_gmt":"2025-08-01T10:51:12","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246872"},"modified":"2025-08-01T12:59:26","modified_gmt":"2025-08-01T10:59:26","slug":"laltra-faccia-vera-del-made-in-italy-nel-settore-dellabbigliamento-di-lusso-nasconde-colossi-finanziari-multinazionali-e-mano-dopera-cinese-sfruttata-nei-subappalti-a-basso-costo-che-assicu","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/laltra-faccia-vera-del-made-in-italy-nel-settore-dellabbigliamento-di-lusso-nasconde-colossi-finanziari-multinazionali-e-mano-dopera-cinese-sfruttata-nei-subappalti-a-basso-costo-che-assicu\/","title":{"rendered":"L&#8217;ALTRA FACCIA &#8211; VERA &#8211; DEL MADE IN ITALY NEL SETTORE DELL&#8217;ABBIGLIAMENTO DI LUSSO: COLOSSI FINANZIARI E MANO D&#8217;OPERA CINESE  SFRUTTATA ASSICURANO ENORMI PROFITTI. MULTA DI TRE MILIONI E MEZZO AD ARMANI DALL&#8217; AGCM"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"540\" class=\"wp-image-246883\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/524781128_1212360227238686_4736373168660288853_n.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/524781128_1212360227238686_4736373168660288853_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/524781128_1212360227238686_4736373168660288853_n-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/524781128_1212360227238686_4736373168660288853_n-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n\n\n\n<p>(Rdl) _____________ Comunicato stampa di questa mattina dell&#8217; Autorit\u00e0 Garante della Concorrenza sul Mercato. Nella nostra foto, un fermo immagine dell&#8217;inchiesta di Report andata in onda su Rai3 il 27 luglio scorso _________<\/p>\n\n\n\n<p>Sanzione di 3,5 milioni di euro alle societ\u00e0 Giorgio Armani S.p.A. e G.A. Operations S.p.A. per pratica commerciale scorretta.<\/p>\n\n\n\n<p><strong><em>e due societ\u00e0 hanno diffuso dichiarazioni etiche e di responsabilit\u00e0 sociale ingannevoli in contrasto con le effettive condizioni di lavoro riscontrate presso fornitori e subfornitori cui \u00e8 stata esternalizzata larga parte della produzione di borse e accessori in pelle a marchio Armani.<\/em><\/strong><\/p>\n\n\n\n<p>L\u2019Autorit\u00e0 Garante della Concorrenza e del Mercato ha irrogato alle societ\u00e0 Giorgio Armani S.p.A. e G.A. Operations S.p.A. una sanzione di 3,5 milioni di euro per pratica commerciale ingannevole ai sensi del Codice del consumo, attuata dal 22 aprile 2022 fino al 18 febbraio 2025.<\/p>\n\n\n\n<p>In particolare, le societ\u00e0 hanno reso dichiarazioni etiche e di responsabilit\u00e0 sociale non veritiere e presentate in modo non chiaro, specifico, accurato e inequivocabile.<\/p>\n\n\n\n<p>Tali dichiarazioni sono presenti nel Codice Etico delle societ\u00e0, in documenti pubblicati sul sito Armani Values (www.armanivalues.com) e sul sito Armani (www.Armani.com) in cui \u00e8 presente un&nbsp;<em>link<\/em>&nbsp;che rimanda al sito Armani Values.<\/p>\n\n\n\n<p>Dall\u2019attivit\u00e0 istruttoria dell\u2019Autorit\u00e0 \u00e8 emerso, da un lato, che le societ\u00e0 hanno enfatizzato la loro attenzione alla sostenibilit\u00e0 &#8211; in particolare alla responsabilit\u00e0 sociale, anche nei confronti dei lavoratori e della loro sicurezza &#8211; che \u00e8 diventata uno strumento di&nbsp;<em>marketing<\/em>&nbsp;utilizzato per rispondere alle crescenti aspettative dei consumatori. Del resto, il nome stesso del sito aziendale (Armani Values) lo dimostra, come anche alcuni documenti acquisiti nel corso delle ispezioni, da cui emerge con evidenza l\u2019obiettivo di \u201c<em>aumentare la percezione positiva del&nbsp;<\/em>brand<em>&nbsp;dal punto di vista della sostenibilit\u00e0 \u2026 e dal punto di vista commerciale \u2026 portare il cliente a fare acquisti consapevoli anche dei \u2018valori\u2019 veicolati attraverso i nostri prodotti<\/em>\u201d.<\/p>\n\n\n\n<p>Dall\u2019altro lato, le societ\u00e0 hanno scelto di esternalizzare larga parte della propria produzione di borse e accessori in pelle a fornitori che, a loro volta, si sono avvalsi di subfornitori. <\/p>\n\n\n\n<p>Presso questi ultimi, in diversi casi, \u00e8 emerso che erano stati rimossi i dispositivi di sicurezza dai macchinari per aumentarne la capacit\u00e0 produttiva, in tal modo ponendo a grave rischio la sicurezza e la salute dei lavoratori. Inoltre, le condizioni igienico-sanitarie non erano adeguate, mentre i lavoratori erano spesso impiegati totalmente o parzialmente in \u201cnero\u201d.<\/p>\n\n\n\n<p>In tale contesto, \u00e8 evidente che il rispetto dei diritti e della salute dei lavoratori non \u00e8 risultato corrispondente al tenore delle dichiarazioni etiche e di responsabilit\u00e0 sociale diffuse da Giorgio Armani S.p.A. e G.A. Operations S.p.A..<\/p>\n\n\n\n<p>La consapevolezza di tale situazione gravemente lesiva dei lavoratori che producevano borse e accessori in pelle a marchio Armani \u00e8 con evidenza provata anche dal fatto che, durante un\u2019ispezione di Polizia Giudiziaria, era presente un dipendente di G.A. Operations preposto al controllo della qualit\u00e0 delle lavorazioni, il quale ha dichiarato di \u201c<em>recarsi mensilmente presso quel laboratorio da circa sei mesi<\/em>\u201d.<\/p>\n\n\n\n<p>Infine, in un documento interno alla Giorgio Armani S.p.A. del 2024, precedente all\u2019apertura della procedura di amministrazione giudiziaria richiesta dalla Procura della Repubblica di Milano, si afferma addirittura che \u201c<em>nella migliore delle situazioni riscontrate, l\u2019ambiente di lavoro \u00e8 al limite dell\u2019accettabilit\u00e0, negli altri casi, emergono forti perplessit\u00e0 sulla loro adeguatezza e salubrit\u00e0<\/em>\u201d.<\/p>\n\n\n\n<p><em>Roma, 1\u00b0 agosto 2025<\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/laltra-faccia-vera-del-made-in-italy-nel-settore-dellabbigliamento-di-lusso-nasconde-colossi-finanziari-multinazionali-e-mano-dopera-cinese-sfruttata-nei-subappalti-a-basso-costo-che-assicu\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/laltra-faccia-vera-del-made-in-italy-nel-settore-dellabbigliamento-di-lusso-nasconde-colossi-finanziari-multinazionali-e-mano-dopera-cinese-sfruttata-nei-subappalti-a-basso-costo-che-assicu\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) _____________ Comunicato stampa di questa mattina dell&#8217; Autorit\u00e0 Garante della Concorrenza sul Mercato. Nella nostra foto, un fermo immagine dell&#8217;inchiesta di Report andata in onda su Rai3 il 27 luglio scorso _________ Sanzione di 3,5 milioni di euro alle societ\u00e0 Giorgio Armani S.p.A. e G.A. Operations S.p.A. per pratica commerciale scorretta. e due societ\u00e0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246883,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246872"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246872"}],"version-history":[{"count":6,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246872\/revisions"}],"predecessor-version":[{"id":246889,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246872\/revisions\/246889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246883"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}