{"id":246890,"date":"2025-08-01T11:01:00","date_gmt":"2025-08-01T09:01:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246890"},"modified":"2025-08-01T16:02:47","modified_gmt":"2025-08-01T14:02:47","slug":"san-foca-due-abusi-edilizi-in-zona-vincolata-denunciati-i-proprietari","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/san-foca-due-abusi-edilizi-in-zona-vincolata-denunciati-i-proprietari\/","title":{"rendered":"SAN FOCA, DUE ABUSI EDILIZI IN ZONA VINCOLATA: DENUNCIATI I PROPRIETARI"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/San-Foca-A.jpg\" alt=\"\" class=\"wp-image-246891\" width=\"393\" height=\"294\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/San-Foca-A.jpg 984w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/San-Foca-A-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/San-Foca-A-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/San-Foca-A-400x300.jpg 400w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/figure>\n\n\n\n<p>(f.f.)_________<\/p>\n\n\n\n<p>Nuovi controlli contro l\u2019abusivismo edilizio lungo le coste salentine: i Carabinieri Forestali hanno scoperto due interventi edilizi irregolari a San Foca, in area sottoposta a vincolo paesaggistico, e denunciato i rispettivi proprietari.<\/p>\n\n\n\n<p>L\u2019operazione rientra nell\u2019ambito delle attivit\u00e0 della campagna \u201cAnother Brick\u201d, avviata dai militari del Gruppo Forestale di Lecce e Brindisi per contrastare gli illeciti ambientali e urbanistici lungo le coste e nelle aree naturali protette del Salento, particolarmente affollate nel periodo estivo. I controlli a terra sono stati affiancati da ispezioni aeree con elicottero AW-169 del 6\u00b0 Nucleo Carabinieri di Bari-Palese e da droni ad alta tecnologia basati a Maglie.<\/p>\n\n\n\n<p>Durante una delle verifiche, i militari hanno individuato due cantieri abusivi in due distinte propriet\u00e0 adiacenti nella marina di San Foca. Nel primo caso, \u00e8 stato scoperto un nuovo vano di circa 50 metri quadrati e una pavimentazione esterna di ulteriori 90 metri quadrati. Nel secondo, erano state realizzate tre tettoie con copertura in legno e pilastri in muratura, oltre a una pavimentazione in cemento su un\u2019area di circa 300 metri quadrati.<\/p>\n\n\n\n<p>Tutte le opere risultavano prive di permesso di costruire e, soprattutto, di autorizzazione paesaggistica, obbligatoria poich\u00e9 l\u2019area rientra tra quelle tutelate dal Piano Paesaggistico Territoriale Regionale (PPTR).I due proprietari sono stati denunciati alla Procura della Repubblica di Lecce.<\/p>\n\n\n\n<p>Le accuse a loro carico fanno riferimento all\u2019art. 44 del Testo Unico sull\u2019Edilizia (D.P.R. 380\/2001) e all\u2019art. 181 del Codice dei Beni Culturali e del Paesaggio (D.Lgs. 42\/2004), per aver effettuato lavori edilizi in assenza delle necessarie autorizzazioni urbanistiche e paesaggistiche.I controlli proseguiranno per tutto il periodo estivo, con particolare attenzione alle zone costiere e ai contesti naturalistici pi\u00f9 sensibili.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/san-foca-due-abusi-edilizi-in-zona-vincolata-denunciati-i-proprietari\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/01\/san-foca-due-abusi-edilizi-in-zona-vincolata-denunciati-i-proprietari\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)_________ Nuovi controlli contro l\u2019abusivismo edilizio lungo le coste salentine: i Carabinieri Forestali hanno scoperto due interventi edilizi irregolari a San Foca, in area sottoposta a vincolo paesaggistico, e denunciato i rispettivi proprietari. L\u2019operazione rientra nell\u2019ambito delle attivit\u00e0 della campagna \u201cAnother Brick\u201d, avviata dai militari del Gruppo Forestale di Lecce e Brindisi per contrastare gli [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246890"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246890"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246890\/revisions"}],"predecessor-version":[{"id":246892,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246890\/revisions\/246892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246891"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}