{"id":246917,"date":"2025-08-02T10:22:00","date_gmt":"2025-08-02T08:22:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=246917"},"modified":"2025-08-02T16:40:28","modified_gmt":"2025-08-02T14:40:28","slug":"__trashed-16","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/02\/__trashed-16\/","title":{"rendered":"PADRE E FIGLIO ARRESTATI A BRINDISI PER SPACCIO DI DROGA: SEQUESTRATI HASHISH, MARIJUANA E CONTANTI"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"604\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782047b58aea_l-logo.jpeg\" alt=\"\" class=\"wp-image-246936\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782047b58aea_l-logo.jpeg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782047b58aea_l-logo-300x201.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782047b58aea_l-logo-768x515.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>(f.f.)__________<\/p>\n\n\n\n<p>Un&#8217; operazione antidroga condotta dalla Polizia di Stato di Brindisi ha portato all\u2019arresto di un uomo e di suo figlio, accusati di detenere e confezionare sostanze stupefacenti presumibilmente destinate allo smercio. L\u2019intervento \u00e8 scattato nel pomeriggio del 28 luglio, nell\u2019ambito di un piano di controlli mirati contro il traffico di droga, predisposto dal Questore.<\/p>\n\n\n\n<p>Gli agenti della Squadra Mobile, dopo aver raccolto informazioni secondo cui all\u2019interno dell\u2019abitazione dei due uomini potesse essere nascosto un notevole quantitativo di stupefacente, hanno effettuato una perquisizione domiciliare. Le verifiche hanno confermato i sospetti: all\u2019interno della camera da letto del figlio e nel gazebo della propriet\u00e0 sono stati trovati diversi panetti di hashish, per un peso totale di circa due chilogrammi. In aggiunta, \u00e8 stata rinvenuta marijuana gi\u00e0 porzionata in dosi, per un peso complessivo di circa 10 grammi.<\/p>\n\n\n\n<p>Nel corso dell\u2019operazione sono stati inoltre sequestrati bilancini di precisione, strumenti utilizzati per il confezionamento delle dosi e una somma in denaro contante pari a 16.785 euro, ritenuta provento dell\u2019attivit\u00e0 di spaccio. Parte della droga era stata occultata all\u2019interno del frigorifero.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"599\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782462c6de90_l-logo.jpeg\" alt=\"\" class=\"wp-image-246937\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782462c6de90_l-logo.jpeg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782462c6de90_l-logo-300x200.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1753782462c6de90_l-logo-768x511.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Padre e figlio, maggiorenne, sono stati condotti in Questura e, dopo le formalit\u00e0 di rito, arrestati con l\u2019accusa di detenzione di stupefacenti ai fini di spaccio. Su disposizione del Pubblico Ministero, sono stati trasferiti nel carcere di Brindisi, a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/02\/__trashed-16\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/02\/__trashed-16\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)__________ Un&#8217; operazione antidroga condotta dalla Polizia di Stato di Brindisi ha portato all\u2019arresto di un uomo e di suo figlio, accusati di detenere e confezionare sostanze stupefacenti presumibilmente destinate allo smercio. L\u2019intervento \u00e8 scattato nel pomeriggio del 28 luglio, nell\u2019ambito di un piano di controlli mirati contro il traffico di droga, predisposto dal Questore. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":246936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246917"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=246917"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246917\/revisions"}],"predecessor-version":[{"id":246942,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/246917\/revisions\/246942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/246936"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=246917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=246917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=246917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}