{"id":247033,"date":"2025-08-04T15:47:34","date_gmt":"2025-08-04T13:47:34","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=247033"},"modified":"2025-08-04T15:48:28","modified_gmt":"2025-08-04T13:48:28","slug":"gallipoli-controlli-straordinari-sanzioni-denunce-e-sequestri-di-droga-e-armi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/04\/gallipoli-controlli-straordinari-sanzioni-denunce-e-sequestri-di-droga-e-armi\/","title":{"rendered":"GALLIPOLI, CONTROLLI STRAORDINARI: SANZIONI, DENUNCE E SEQUESTRI"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG-20250804-WA0006-768x1024.jpg\" alt=\"\" class=\"wp-image-247034\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG-20250804-WA0006-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG-20250804-WA0006-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG-20250804-WA0006-1152x1536.jpg 1152w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG-20250804-WA0006.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>(f.f.)___________<\/p>\n\n\n\n<p>Proseguono intensi i controlli straordinari disposti dal Questore di Lecce, Giampietro Lionetti, per garantire ordine, sicurezza e rispetto della legalit\u00e0 nelle marine gallipoline, soprattutto in vista dell\u2019afflusso turistico estivo. Nella serata di ieri, una vasta operazione interforze ha interessato le principali aree del divertimento, coinvolgendo gli agenti del Commissariato di Gallipoli, della Polizia Stradale e altri reparti della Polizia di Stato.<\/p>\n\n\n\n<p>Durante l\u2019attivit\u00e0 sono stati controllati 146 veicoli: due di questi sono stati fermati per irregolarit\u00e0 tecniche (violazione dell\u2019articolo 80 del Codice della Strada) e sottoposti a sospensione dalla circolazione. In totale, le persone identificate sono state 382.Particolare attenzione \u00e8 stata rivolta alla guida in stato di alterazione. Tre individui sono stati denunciati per uso di cannabis al volante, mentre sei persone sono risultate positive all\u2019alcol test: cinque sanzionate in via amministrativa \u2013 tra cui due neopatentati \u2013 e una deferita penalmente per il superamento dei limiti consentiti.<\/p>\n\n\n\n<p>Sul fronte amministrativo, gli agenti hanno effettuato un controllo in un locale situato in via Luigi Ariosto, dove \u00e8 stato accertato lo svolgimento di uno spettacolo aperto al pubblico senza le previste autorizzazioni e senza la comunicazione all\u2019Autorit\u00e0 di Pubblica Sicurezza, in violazione dell\u2019articolo 18 del TULPS. Al titolare verranno contestate anche ulteriori irregolarit\u00e0 emerse durante la verifica, e sar\u00e0 valutata la documentazione integrativa che dovr\u00e0 essere trasmessa al Commissariato.<\/p>\n\n\n\n<p>Non sono mancate anche operazioni legate al possesso di armi e droga. Due giovani provenienti da Modena sono stati denunciati: uno per detenzione illegale di una pistola a salve priva del tappo rosso e con caricatore carico, oltre a munizioni aggiuntive e un tirapugni metallico; l\u2019altro per possesso di hashish e marijuana per un totale di oltre 6 grammi.<\/p>\n\n\n\n<p>Tutto il materiale \u00e8 stato sequestrato e messo a disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/04\/gallipoli-controlli-straordinari-sanzioni-denunce-e-sequestri-di-droga-e-armi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/04\/gallipoli-controlli-straordinari-sanzioni-denunce-e-sequestri-di-droga-e-armi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)___________ Proseguono intensi i controlli straordinari disposti dal Questore di Lecce, Giampietro Lionetti, per garantire ordine, sicurezza e rispetto della legalit\u00e0 nelle marine gallipoline, soprattutto in vista dell\u2019afflusso turistico estivo. Nella serata di ieri, una vasta operazione interforze ha interessato le principali aree del divertimento, coinvolgendo gli agenti del Commissariato di Gallipoli, della Polizia Stradale [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":247034,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247033"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=247033"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247033\/revisions"}],"predecessor-version":[{"id":247036,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247033\/revisions\/247036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/247034"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=247033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=247033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=247033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}