{"id":247210,"date":"2025-08-07T19:51:09","date_gmt":"2025-08-07T17:51:09","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=247210"},"modified":"2025-08-07T19:51:13","modified_gmt":"2025-08-07T17:51:13","slug":"anziano-in-coma-dopo-brutale-aggressione-ad-alezio-per-problemi-di-vicinato-43enne-finisce-in-carcere","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/07\/anziano-in-coma-dopo-brutale-aggressione-ad-alezio-per-problemi-di-vicinato-43enne-finisce-in-carcere\/","title":{"rendered":"ANZIANO IN COMA DOPO BRUTALE AGGRESSIONE AD ALEZIO PER PROBLEMI DI VICINATO: 43ENNE FINISCE IN CARCERE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-1024x768.jpg\" alt=\"\" class=\"wp-image-247212\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-2048x1536.jpg 2048w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/IMG_20190621_102115_6-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>di <strong>Flora Fina __________<\/strong><\/p>\n\n\n\n<p>Un episodio di violenza inaudita ha sconvolto la tranquilla comunit\u00e0 di Alezio: un uomo di 78 anni si trova ora ricoverato in coma all\u2019ospedale di Lecce, in condizioni critiche, dopo essere stato brutalmente picchiato dal vicino di casa. L\u2019aggressore, un commerciante 43enne del posto, \u00e8 stato arrestato nel pomeriggio dai carabinieri su disposizione del giudice per le indagini preliminari del Tribunale di Lecce.<\/p>\n\n\n\n<p>Secondo quanto emerso dalle indagini condotte dai militari dell\u2019Arma di Alezio, con il supporto della compagnia di Gallipoli, l\u2019aggressione si \u00e8 consumata sabato scorso in via Ferrante, al culmine di un\u2019accesa lite scoppiata \u2013 pare \u2013 per una controversia su questioni di confine e tubature idriche. Motivi di poco conto, all\u2019apparenza, ma che avrebbero fatto esplodere la furia dell\u2019uomo, identificato come Carmelo Rizzo, originario di Gallipoli.<\/p>\n\n\n\n<p>La discussione sarebbe rapidamente degenerata in insulti e, infine, in violenza fisica: il 43enne avrebbe colpito ripetutamente l\u2019anziano al volto, provocandogli traumi tali da farlo crollare a terra privo di sensi. Dopo il pestaggio, il pensionato avrebbe manifestato gravi sintomi neurologici e perso conoscenza. I soccorsi sono stati immediati: trasportato d\u2019urgenza al Dea dell\u2019ospedale \u201cVito Fazzi\u201d di Lecce, i medici hanno riscontrato un\u2019emorragia cerebrale estesa. <\/p>\n\n\n\n<p>L\u2019uomo \u00e8 ora ricoverato in terapia intensiva, attaccato a un respiratore artificiale, e la prognosi resta riservata.Nel frattempo, la Procura di Lecce, per voce della sostituta Maria Vallefuoco, ha richiesto e ottenuto la custodia cautelare in carcere per Rizzo. Il provvedimento \u00e8 stato convalidato dalla gip Giulia Proto, alla luce della gravit\u00e0 dei fatti e del rischio di reiterazione del reato.<\/p>\n\n\n\n<p>L\u2019uomo, al momento del fermo, ha accusato un malore che ha reso necessario l\u2019intervento del personale del 118 e il trasferimento in ospedale per accertamenti.Le indagini proseguono per chiarire tutti gli aspetti della vicenda, compresa la presunta rottura di un tubo idrico, elemento al centro della lite e che al momento non risulta confermato.<\/p>\n\n\n\n<p>Intanto, la comunit\u00e0 aletina resta sconvolta da un atto di violenza tanto feroce quanto inaspettato, consumatosi tra due persone che da anni vivevano porta a porta.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/07\/anziano-in-coma-dopo-brutale-aggressione-ad-alezio-per-problemi-di-vicinato-43enne-finisce-in-carcere\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/07\/anziano-in-coma-dopo-brutale-aggressione-ad-alezio-per-problemi-di-vicinato-43enne-finisce-in-carcere\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Flora Fina __________ Un episodio di violenza inaudita ha sconvolto la tranquilla comunit\u00e0 di Alezio: un uomo di 78 anni si trova ora ricoverato in coma all\u2019ospedale di Lecce, in condizioni critiche, dopo essere stato brutalmente picchiato dal vicino di casa. L\u2019aggressore, un commerciante 43enne del posto, \u00e8 stato arrestato nel pomeriggio dai carabinieri [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":247212,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247210"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=247210"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247210\/revisions"}],"predecessor-version":[{"id":247218,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247210\/revisions\/247218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/247212"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=247210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=247210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=247210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}