{"id":247219,"date":"2025-08-08T12:12:07","date_gmt":"2025-08-08T10:12:07","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=247219"},"modified":"2025-08-08T12:17:17","modified_gmt":"2025-08-08T10:17:17","slug":"blitz-antidroga-a-brindisi-in-casa-cocaina-e-pistole-prive-di-tappo-rosso","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/08\/blitz-antidroga-a-brindisi-in-casa-cocaina-e-pistole-prive-di-tappo-rosso\/","title":{"rendered":"BLITZ ANTIDROGA A BRINDISI: FINISCE IN CARCERE GIOVANE CHE AVEVA IN CASA COCAINA, PISTOLE E CARTUCCE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"637\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1754125991e99b55_l-logo.jpeg\" alt=\"\" class=\"wp-image-247220\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1754125991e99b55_l-logo.jpeg 900w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1754125991e99b55_l-logo-300x212.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/08\/1754125991e99b55_l-logo-768x544.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>(f.f.)___________<\/p>\n\n\n\n<p>Un\u2019operazione mirata della Squadra Mobile di Brindisi ha portato all\u2019arresto di un uomo poco pi\u00f9 che trentenne, gi\u00e0 noto alle forze dell\u2019ordine, sorpreso con cocaina e armi detenute illegalmente. Il fermo \u00e8 avvenuto nel pomeriggio del 1\u00b0 agosto, nell\u2019ambito dei controlli predisposti dal Questore per contrastare il traffico di stupefacenti in citt\u00e0.<\/p>\n\n\n\n<p>Gli agenti, dopo aver raccolto informazioni su un possibile giro di droga gestito dal sospettato, hanno fatto irruzione nella sua abitazione, procedendo a una perquisizione accurata. All\u2019interno di una cassaforte sono stati trovati circa 30 grammi di cocaina suddivisi in sei involucri, due bilancini di precisione e materiale per il confezionamento delle dosi.<\/p>\n\n\n\n<p>Ma la scoperta non si \u00e8 fermata alla droga: nella stessa cassaforte erano custodite due pistole \u201ca salve\u201d prive del tappo rosso e quindici cartucce calibro 9&#215;21 marca G.F.L., tutto finito immediatamente sotto sequestro. Il presunto spacciatore \u00e8 stato condotto in Questura e, dopo le formalit\u00e0 di rito, trasferito alla Casa Circondariale di Brindisi su disposizione dell\u2019Autorit\u00e0 Giudiziaria.<\/p>\n\n\n\n<p>Le indagini proseguono per verificare l\u2019origine della cocaina e delle armi, e per individuare eventuali complici nella rete di spaccio.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/08\/blitz-antidroga-a-brindisi-in-casa-cocaina-e-pistole-prive-di-tappo-rosso\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/08\/08\/blitz-antidroga-a-brindisi-in-casa-cocaina-e-pistole-prive-di-tappo-rosso\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)___________ Un\u2019operazione mirata della Squadra Mobile di Brindisi ha portato all\u2019arresto di un uomo poco pi\u00f9 che trentenne, gi\u00e0 noto alle forze dell\u2019ordine, sorpreso con cocaina e armi detenute illegalmente. Il fermo \u00e8 avvenuto nel pomeriggio del 1\u00b0 agosto, nell\u2019ambito dei controlli predisposti dal Questore per contrastare il traffico di stupefacenti in citt\u00e0. Gli agenti, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":247220,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247219"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=247219"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247219\/revisions"}],"predecessor-version":[{"id":247231,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/247219\/revisions\/247231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/247220"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=247219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=247219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=247219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}