{"id":24827,"date":"2014-02-20T11:20:13","date_gmt":"2014-02-20T11:20:13","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24827"},"modified":"2014-02-20T11:20:13","modified_gmt":"2014-02-20T11:20:13","slug":"torna-la-rassegna-culturale-scientifica-neuroscienze-cafe-domani-il-primo-incontro-nella-sala-teatrino-della-bernardini-a-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/20\/torna-la-rassegna-culturale-scientifica-neuroscienze-cafe-domani-il-primo-incontro-nella-sala-teatrino-della-bernardini-a-lecce\/","title":{"rendered":"TORNA LA RASSEGNA CULTURALE &#8211; SCIENTIFICA  \u201cNEUROSCIENZE CAF\u00c9\u201d: DOMANI IL PRIMO INCONTRO  NELLA SALA TEATRINO DELLA \u201cBERNARDINI\u201d A LECCE"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\">Si apre <span style=\"text-decoration: underline\">domani, venerd\u00ec 21 febbraio, nella sala teatrino della Biblioteca provinciale \u201cNicola Bernardini\u201d (ex Convitto Palmieri), a Lecce,<\/span> la rassegna culturale-scientifica <strong>\u201cNeuroscienze Caf\u00e9\u201d<\/strong>, organizzata dall\u2019Istituto di Arti terapie e scienze creative di Carmiano, in collaborazione con la Provincia di Lecce.<br \/>\nL\u2019appuntamento \u00e8 <span style=\"text-decoration: underline\">alle ore 16,<\/span> con il docente, attore e regista teatrale salentino <strong>Fausto Cino<\/strong>, che terr\u00e0 una relazione dal titolo <strong>\u201cTeatroterapia e riabilitazione psicosociale\u201d<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Quest\u2019anno il programma dell\u2019iniziativa prevede otto incontri, uno al mese, che si svolgeranno sempre nella sala teatrino dell\u2019ex Convitto Palmieri. <span style=\"text-decoration: underline\">La partecipazione a tutte le attivit\u00e0 \u00e8 gratuita.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Obiettivo del ciclo di incontri, che si concluder\u00e0 <span style=\"text-decoration: underline\">il 7 novembre 2014<\/span>, \u00e8 informare i cittadini sulle pi\u00f9 comuni patologie e sulle possibili applicazioni delle arti terapie come soluzioni nuove. Pi\u00f9 in particolare, si vuole promuovere un dialogo tra esperti provenienti da differenti ambiti (neurologi, scienziati, psichiatri, psicoterapeuti) e l\u2019uditorio; offrire uno spazio formativo e di approfondimento su temi di interesse clinico, scientifico e sociale; migliorare le competenze professionali degli operatori della relazione d\u2019aiuto in un\u2019ottica di prevenzione allargata; stimolare percorsi di conoscenza personali e di arricchimento culturale anche nei confronti di fasce culturali medio-basse. Tutti gli appuntamenti saranno strutturati in modo tale da unire, ad una prima fase, prettamente teorica, un successivo coinvolgimento del pubblico presente.<\/p>\n<p><span style=\"text-decoration: underline\">\u00a0<\/span><\/p>\n<p>Il prossimo incontro in programma \u00e8 per <span style=\"text-decoration: underline\">venerd\u00ec 14 marzo, dalle ore 16 alle ore 19, <\/span>con l\u2019educatore professionale e danzateraupeta <strong>Raffaella D\u2019Alterio<\/strong>, che interverr\u00e0 su \u201cDanzaterapia e autismo\u201d.<\/p>\n<p>Lecce, 20 febbraio 2014<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/20\/torna-la-rassegna-culturale-scientifica-neuroscienze-cafe-domani-il-primo-incontro-nella-sala-teatrino-della-bernardini-a-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/20\/torna-la-rassegna-culturale-scientifica-neuroscienze-cafe-domani-il-primo-incontro-nella-sala-teatrino-della-bernardini-a-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si apre domani, venerd\u00ec 21 febbraio, nella sala teatrino della Biblioteca provinciale \u201cNicola Bernardini\u201d (ex Convitto Palmieri), a Lecce, la rassegna culturale-scientifica \u201cNeuroscienze Caf\u00e9\u201d, organizzata dall\u2019Istituto di Arti terapie e scienze creative di Carmiano, in collaborazione con la Provincia di Lecce. L\u2019appuntamento \u00e8 alle ore 16, con il docente, attore e regista teatrale salentino Fausto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24827"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24827"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24827\/revisions"}],"predecessor-version":[{"id":24828,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24827\/revisions\/24828"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}