{"id":24882,"date":"2014-02-21T10:09:57","date_gmt":"2014-02-21T10:09:57","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24882"},"modified":"2014-02-21T11:20:25","modified_gmt":"2014-02-21T11:20:25","slug":"la-poverta-dellitalia-tra-euro-e-incostituzionalita","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/21\/la-poverta-dellitalia-tra-euro-e-incostituzionalita\/","title":{"rendered":"LA POVERTA&#8217; DELL&#8217;ITALIA TRA EURO E INCOSTITUZIONALITA&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A Pescara, l&#8217;otto marzo un c<span style=\"font-size: small;\">onvegno sulla crisi\/truffa dell&#8217;Italia dovuta all&#8217;Euro<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span class=\"Apple-style-span\" style=\"font-size: medium;\">Il convegno sar\u00e0 un simposio in cui si affronter\u00e0 la soluzione GIURIDICA per l&#8217;uscita dalla truffa che chiamano crisi istituita con leggi come il Pareggio di Bilancio, i Patti di Stabilit\u00e0, il Fondo Salva Stati e sopratutto con la moneta PRESTATA agli Stati, istituito con trattati europei incostituzionali, a opera della Banca Centrale Europea,\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Il convegno \u00e8 organizzato dalla scuola di studi intitolata alla memoria di Giacinto Auriti, l&#8217;illustre professore abruzzese che a lungo si adoper\u00f2 negli scorsi decenni per la sovranit\u00e0 monetaria popolare e si terr\u00e0 sabato 8 marzo 2014, alle ore 16,00, nella Sala &#8220;Figlia di Iorio&#8221; del Palazzo della Provincia di Pescara.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Dopo la presentazione del presidente del Centro Studi Auriti, Mauro Di Sabatino, con il giornalista Giuseppe Caporale quale moderatore della serata, interverranno: Luciano Barra Caracciolo, membro del Consiglio di Stato; Gennaro Varone, magistrato; e i docenti universitari Antonio Maria Rinaldi ed Ezio Sciarra.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Per la seriet\u00e0 degli organizzatori, per la profondit\u00e0 dell&#8217;impostazione, per la qualit\u00e0 dei relatori, giudichiamo questa iniziativa importantissima, perch\u00e9 va oltre la sterile, per quanto giustificata, protesta politica, volendo fornire argomentazioni giuridiche e scientifiche a successive azioni concrete, che ci portino fuori dalla disperata e disperante situazione in cui ci dibattiamo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: medium;\">Seguiremo quindi direttamente i lavori, per offrire una documentazione seria e attendibile, anche a livello operativo, di queste fondamentali problematiche.<\/span><\/p>\n<p style=\"text-align: justify;\">***<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: x-small;\"><strong>Nel frattempo ospitiamo volentieri un primo contributo, lo studio di Gerardo Campagna, della scuola Auriti, che qui di seguito, come documentazione in materia, qui di seguito volentieri pubblichiamo:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>IL FALLIMENTO DEI PARAMETRI UE E BCE<\/strong><\/p>\n<p style=\"text-align: justify;\">Uno dei parametri di maggiore uso\u00a0e\u00a0importanza nella politica economica europea, \u00e8 il rapporto deficit\/PIL,\u00a0che attualmente \u00e8 fissato per l\u2019eurozona, nel rispetto del patto di &#8220;stabilit\u00e0 e crescita&#8221;, al 3%.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Il numeratore, o deficit, o disavanzo, \u00e8 una variabile che cresce indefinitamente nel tempo a causa degli interessi sull\u2019emissione di moneta a debito, sullo stock di debito e sui titoli di stato.<\/li>\n<li>Il denominatore, o PIL, o produzione, \u00e8 una variabile che, per sua natura, a causa delle capacit\u00e0 produttive e della saturazione del mercato, ha invece un limite fisico, rappresentato dall\u2019indice tecnologico nel processo produttivo e dalla qualit\u00e0 della vita che incide sul numero e qualit\u00e0 della domanda.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">La funzione \u00e8 quindi destinata a crescere indefinitamente, anche oltre il quoziente 3, appunto per l\u2019illimitatezza irrazionale del debito contro il limite fisico, o razionale, del PIL. Da qui l\u2019insolvenza ineluttabile del debito pubblico.<\/p>\n<p style=\"text-align: justify;\">Il consumismo,\u00a0in rapporto reciproco col concetto di &#8220;crescita&#8221;, si inserisce in tale funzione al denominatore nel tentativo di sostenere la validit\u00e0 matematica della funzione entro il limite del<br \/>\nvalore 3.<\/p>\n<p style=\"text-align: justify;\">Incentivando i consumi con una pi\u00f9 numerosa e segmentata offerta, aumenta la domanda e di conseguenza la produzione; in tal modo la crescita del deficit viene controbilanciata da una crescita del PIL, al fine di rallentare la crescita della funzione.<\/p>\n<p style=\"text-align: justify;\">\u00c8 evidente che anche il consumismo stesso ha un suo limite fisico: se si ipotizzasse per assurdo una popolazione col 100% di ricchi, essi raggiungerebbero comunque una soglia di stazionariet\u00e0, anche a pieno regime di sfarzi ed eccessi. Lo stesso vale per la produttivit\u00e0, il cui limite fisico \u00e8 rappresentato dal picco di automazione produttiva assieme alla saturazione della manodopera, e delle risorse ed energie disponibili. Si ribadisce ancora una volta pertanto, l\u2019assoluta insolvibilit\u00e0 del debito pubblico, o, se vogliamo, in maniera pi\u00f9 razionale, la certezza matematica della crescita indefinita della funzione, che quindi si rivela falsa, DEF\/PIL<\/p>\n<p style=\"text-align: justify;\">Il consumismo, o la crescita,\u00a0sono quindi lo stesso tentativo, vano, di sostenere razionalmente l\u2019ineluttibilit\u00e0 del debito, aggravato peraltro dalle rendite finanziarie ed altre forme di <em>trading<\/em>, che svuotano, succhiandone il valore, l\u2019econom\u00eca reale che, a sua volta, indirettamente, causa l\u2019insostenibilit\u00e0 del consumismo stesso. Il consumismo \u00e8 in definitiva un fattore di ordinariet\u00e0 nel sistema della moneta-debito. \u00c8 cio\u00e8 necessario affinch\u00e8 il sistema di moneta-debito funzioni, seppure in maniera consapevolmente limitata nel tempo a causa della naturale insolvenza aggravata dalla finanziarizzazione dell\u2019econom\u00eca.<\/p>\n<p style=\"text-align: justify;\">Allo stesso modo \u00e8 insostenibile l&#8217;altro parametro contenuto nel patto di stabilit\u00e0 e crescita: il rapporto debito\/PIL, che deve essere inferiore al 60%, anch&#8217;esso fisicamente insostenibile.<\/p>\n<p style=\"text-align: justify;\">Oltre il significato matematico e locale del rapporto col deficit o col debito, la variabile PIL, legata alla domanda, e quindi ancora una volta al c.d. consumismo, \u00e8 anche funzione della variazione dell\u2019indice dei prezzi, o inflazione. La politica monetaria della BCE impone attualmente\u00a0il tasso inflazione obiettivo, che \u00e8 attualmente fissato pari al 2%. Appare evidente come tale obiettivo, di natura strettamente monetaria, nel momento in cui viene fissato proprio da chi emette la moneta a debito,\u00a0pu\u00f2 essere anche perseguita con politiche di inflazione e deflazione mediante controllo dell\u2019indice di rarit\u00e0. A titolo di esempio, con la teoria quantitativa della moneta, la relazione PxT=MxV [<em>variazione prezzi\u00a0o Inflazione x PIL = massa monetaria x velocit\u00e0 di circolazione<\/em>],\u00a0fermo restando le necessarie politiche di controllo sul sistema economico reale, l&#8217;equilibrio poteva avvenire infine con &#8220;aggiustamenti&#8221; di M (moneta)\u00a0da parte della banca. Oggi, la BCE invece,\u00a0impone a priori\u00a0un altro parametro, peraltro di primaria importanza nell&#8217;intero quadro delle politiche economiche europee da rispettare:\u00a0il tasso inflazione obiettivo, e non controlli sull&#8217;economia reale, per qualunque valore verificabile nelle variabili T o V di cui alla relazione precedente (o per qualunque cosa accada all&#8217;economia reale).\u00a0Si intuisce quindi,\u00a0la prevalenza della politica monetaria rispetto a quella pi\u00f9 strettamente occupazionale e produttiva, che dovrebbe &#8220;anche&#8221; dipendere dalle politiche nazionali.\u00a0Peraltro, potendo l&#8217;ente emittente imporre valori non variabili nei dati invece variabili dei mercati globali\u00a0e della libera contrattazione, diviene anche in grado fare previsioni, in quanto \u00e8 in grado di causarle.<\/p>\n<p style=\"text-align: justify;\">Chiariti i concetti di crescita e consumismo ci si spiega anche a cosa servono, o a cosa sono serviti,\u00a0robot e ciminiere&#8230; gli inutili mostri che hanno peraltro devastato l&#8217;ambiente.<\/p>\n<p style=\"text-align: justify;\">Questo sistema \u00e8 ora matematicamente fallito. E&#8217; stata creata una mole di ricchezza immensa, catalogata elettronicamente, e concentrata nel potere di pochi azionisti. Tutta quella che doveva essere ricchezza prodotta da\u00a0un lavoro coadiuvato dall&#8217;automazione e dalla meccanizzazione,\u00a0\u00e8 stata annientata per essere trasformata\u00a0nel potere di pochi giocatori.<\/p>\n<p style=\"text-align: justify;\">Di fronte al crescente aumento della tassazione, del costo dell&#8217;energ\u00eca e del costo della vita, avendo cos\u00ec causato il rallentamento del sistema funzionale alla creazione di ricchezza con la moneta &#8211; debito, pur sostenibile nel breve per\u00ecodo, si passa a una fase di riscossione del debito, mediante\u00a0gli aumenti\u00a0fiscali sui consumi, sul risparmio, e infine sulla ricchezza capitalizzata, fino a poterne alienare la propriet\u00e0.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 un caso che tutto questo in Europa non abbia funzionato, \u00e8 lo stesso motivo per cui in Italia tante opere pubbliche vengono iniziate, o a volte solo progettate, per non essere mai portate a termine o rese funzionali.<\/p>\n<p style=\"text-align: justify;\"><strong>Gerardo Campagna\u00a0<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/21\/la-poverta-dellitalia-tra-euro-e-incostituzionalita\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/21\/la-poverta-dellitalia-tra-euro-e-incostituzionalita\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>A Pescara, l&#8217;otto marzo un convegno sulla crisi\/truffa dell&#8217;Italia dovuta all&#8217;Euro Il convegno sar\u00e0 un simposio in cui si affronter\u00e0 la soluzione GIURIDICA per l&#8217;uscita dalla truffa che chiamano crisi istituita con leggi come il Pareggio di Bilancio, i Patti di Stabilit\u00e0, il Fondo Salva Stati e sopratutto con la moneta PRESTATA agli Stati, istituito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24884,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[44],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24882"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24882"}],"version-history":[{"count":9,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24882\/revisions"}],"predecessor-version":[{"id":24887,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24882\/revisions\/24887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24884"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}