{"id":24957,"date":"2014-02-22T07:57:11","date_gmt":"2014-02-22T07:57:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24957"},"modified":"2014-02-22T07:58:10","modified_gmt":"2014-02-22T07:58:10","slug":"international-open-data-day-lecce-ce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/international-open-data-day-lecce-ce\/","title":{"rendered":"INTERNATIONAL OPEN DATA DAY, LECCE C\u2019E\u2019"},"content":{"rendered":"<p style=\"text-align: left\" align=\"center\"><strong><em>Sabato 22 febbraio,\u00a0 all\u2019Open Space di Palazzo Carafa, dalle ore 12 alle ore 13, <\/em><\/strong><strong><em>collegamento con l\u2018Archivio Centrale dello Stato di Roma. Protagonisti saranno i social network: i dati richiesti da cittadini, imprese ed enti passeranno per i nuovi mezzi di comunicazione.<br \/>\n<\/em><\/strong><strong>Sabato 22 febbraio, all\u2019Open Space di Palazzo Carafa, dalle ore 12 alle ore 13,<\/strong> si terr\u00e0 il collegamento con l\u2018Archivio Centrale dello Stato di Roma, che funge da Hub\u00a0 dell\u2019<strong><em>\u201cInternational Open Data Day- Italia 2014\u201d.<\/em><\/strong><\/p>\n<p>Nel corso dell\u2019intervento leccese, che sar\u00e0 trasmesso in diretta streaming su <a href=\"http:\/\/www.facebook.com\/l.php?u=http%3A%2F%2Fwww.salentoweb.tv%2F&amp;h=tAQHJA0Wx&amp;enc=AZN8szEqYRltfUv4SFI0EHniXzMH49YDLmVdFfvB_KEhUrlaJvdS23at55eWm6Kr68k&amp;s=1\">www.salentoweb.tv<\/a> e che vedr\u00e0 la partecipazione di <strong>Alessandro Delli Noci<\/strong>, assessore all\u2019Innovazione Tecnologica del Comune di Lecce, verranno presentati i primi dati relativi alle richieste di dataset da rendere \u201copen\u201d.<\/p>\n<p>Durante la sessione pomeridiana, trasmessa in diretta streaming su <a href=\"http:\/\/opendataday.it\/live\/\">http:\/\/opendataday.it\/live\/<\/a> dalle 14.30 alle 15.30 direttamente da Roma, interverr\u00e0 <strong>Giulia Antonucci<\/strong> di Puglia Smart Lab, Living Lab del Dhitech Scarl, per illustrare la metodologia utilizzata per tradurre i dati in informazioni utili alla cittadinanza.\u00a0 Dati richiesti dai cittadini stessi, ma anche dalle imprese e dagli enti e che passeranno per i nuovi mezzi di comunicazione perch\u00e9 <strong><em>\u201cOpen Data\u201d<\/em><\/strong> \u00e8 innovazione.<\/p>\n<p>Sar\u00e0 strettissima, quindi, la connessione con i social network, che avranno un ruolo di primo piano grazie alla creazione degli hashtag specifici che indicizzeranno le richieste e che collegheranno in rete gli attori partecipanti (istituzioni, enti, aziende, cittadini, e vai discorrendo).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Partecipare \u00e8 semplice: basta collegarsi a Twitter e utilizzare gli hashtag #opendatalecce, #chedativuoi e #ODDIT14. Quest\u2019ultimo, \u00e8 l\u2019hashtag lanciato da International Open Data Day- Italia 2014.<\/strong><\/p>\n<p>I dati richiesti toccheranno numerosi settori come <strong>trasporti, dati geografici, cultura,<\/strong> <strong>ambiente, tempo, statistiche, scienze e finanza<\/strong> e che in altre citt\u00e0 grazie al gi\u00e0 realizzato primo Open Data sono gi\u00e0 stati resi noti e accessibili a tutti e riutilizzabili senza limitazioni di copyright. Basta pensarci un attimo e un\u2019infinita richiesta di dati pu\u00f2 venire in mente a chiunque abbia sete di conoscenza specifica e sempre utile per la comprensione di alcuni settori della vita pubblica e privata quotidiana.<\/p>\n<p>Il fine dell\u2019iniziativa \u00e8 la trasparenza dei dati prodotti nei vari livelli amministrativi, la creazione di imprese e servizi che generano nuove opportunit\u00e0 e l\u2019aumento della partecipazione del cittadino che verr\u00e0 quindi coinvolto nel processo decisionale di governance.<\/p>\n<p>L\u2019appuntamento \u00e8 uno dei vari tasselli per la \u201ccostruzione\u201d di Lecce Smart City e la progettazione della citt\u00e0 di Lecce candidata come <em>Capitale Europea della Cultura 2019.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\">\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/international-open-data-day-lecce-ce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/international-open-data-day-lecce-ce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Sabato 22 febbraio,\u00a0 all\u2019Open Space di Palazzo Carafa, dalle ore 12 alle ore 13, collegamento con l\u2018Archivio Centrale dello Stato di Roma. Protagonisti saranno i social network: i dati richiesti da cittadini, imprese ed enti passeranno per i nuovi mezzi di comunicazione. Sabato 22 febbraio, all\u2019Open Space di Palazzo Carafa, dalle ore 12 alle ore [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24957"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24957"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24957\/revisions"}],"predecessor-version":[{"id":24959,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24957\/revisions\/24959"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}