{"id":24986,"date":"2014-02-22T14:25:43","date_gmt":"2014-02-22T14:25:43","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=24986"},"modified":"2014-02-22T14:25:43","modified_gmt":"2014-02-22T14:25:43","slug":"stage-di-aikido-a-lecce-con-il-maestro-cozzi-fiordineve","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/stage-di-aikido-a-lecce-con-il-maestro-cozzi-fiordineve\/","title":{"rendered":"STAGE DI AIKIDO A LECCE CON IL MAESTRO COZZI FIORDINEVE"},"content":{"rendered":"<div>\n<div>\n<div>\n<div>\n<div><span style=\"font-family: verdana\"><a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/stage-aikido-lecce.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/stage-aikido-lecce-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-24987\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/stage-aikido-lecce-212x300.jpg 212w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/stage-aikido-lecce-724x1024.jpg 724w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/stage-aikido-lecce.jpg 849w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a>Oggi, sabato 22 e Domenica 23 febbraio si terr\u00e0 c\/o il &#8220;Dojo Il Cavaliere&#8221; a Lecce in via Puccini 32, lo Stage di Aikido diretto dal Maestro Cozzi Fiordineve VI Dan dell&#8217;Aikikai d&#8217;Italia Ente Morale riconosciuto dal Ministero degli Interni. Lo Stage ha la finalit\u00e0 di far conoscere questa moderna e affascinante arte marziale.<\/span><\/div>\n<\/div>\n<div><span style=\"font-family: verdana\">Lo Stage \u00e8 aperto anche ai praticanti di altre discipline.<\/span><\/div>\n<div><span style=\"font-family: verdana\"><br \/>\n<\/span><\/div>\n<div><span style=\"font-family: verdana\">Di seguito il programma dello stage:<\/span><\/div>\n<div>\n<div><\/div>\n<div>Sabato<\/div>\n<div>ore 17:00-18:00 \u00a0Lezione per tutti<\/div>\n<div>ore 18:00-20:00 \u00a0Differenziata per gradi<\/div>\n<div>ore 21:00 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cena Sociale<\/div>\n<div><\/div>\n<div>Domenica<\/div>\n<div>ore 10:00-11:00 \u00a0 Jo e Boken (bastone e spada)<\/div>\n<div>ore 11:00-12:00 \u00a0 Differenziata per gradi<\/div>\n<div>ore 12:00-13:00 \u00a0 Esami<\/div>\n<div><\/div>\n<div>Per informazioni rivolgersi al M\u00b0 Valerio Melcore tel 329 2509093<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/stage-di-aikido-a-lecce-con-il-maestro-cozzi-fiordineve\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/22\/stage-di-aikido-a-lecce-con-il-maestro-cozzi-fiordineve\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Oggi, sabato 22 e Domenica 23 febbraio si terr\u00e0 c\/o il &#8220;Dojo Il Cavaliere&#8221; a Lecce in via Puccini 32, lo Stage di Aikido diretto dal Maestro Cozzi Fiordineve VI Dan dell&#8217;Aikikai d&#8217;Italia Ente Morale riconosciuto dal Ministero degli Interni. Lo Stage ha la finalit\u00e0 di far conoscere questa moderna e affascinante arte marziale. Lo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24986"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=24986"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24986\/revisions"}],"predecessor-version":[{"id":24988,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/24986\/revisions\/24988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/24987"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=24986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=24986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=24986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}