{"id":250028,"date":"2025-10-10T11:59:05","date_gmt":"2025-10-10T09:59:05","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250028"},"modified":"2025-10-10T11:59:07","modified_gmt":"2025-10-10T09:59:07","slug":"sport-day-santa-rosa-giochi-e-discipline-a-lecce-domenica-12","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/sport-day-santa-rosa-giochi-e-discipline-a-lecce-domenica-12\/","title":{"rendered":"&#8220;Sport day Santa Rosa&#8221;, GIOCHI E DISCIPLINE  A LECCE DOMENICA 12"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"200\" height=\"200\" class=\"wp-image-250029\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/rirri-o-ne.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/rirri-o-ne.jpg 200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/rirri-o-ne-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/rirri-o-ne-60x60.jpg 60w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p>\n\n\n\n<p>Riceviamo e volentieri pubblichiamo _____________<\/p>\n\n\n\n<p>In occasione della settimana europea dello sport, Rione Santa Rosa APS Lecce e ASD Nest organizzano domenica 12 ottobre dalle ore 9 alle ore 13 \u201cSPORT DAY SANTA ROSA\u201d.<\/p>\n\n\n\n<p>L\u2019evento, accreditato da&nbsp;<em>Sport e Salute Spa<\/em>&nbsp;e patrocinato dal&nbsp;<em>Comune di Lecce<\/em>&nbsp;e dalla&nbsp;<em>Provincia di Lecce<\/em>, si terr\u00e0 in Piazza Santa Rosa da Lima, nel quartiere di Santa Rosa, ed \u00e8 finalizzato a promuovere sani stili di vita e la cultura dello sport. Sono previsti giochi all\u2019aperto, attrazioni per i pi\u00f9 piccoli e lezioni dimostrative di varie discipline sportive, rivolte gratuitamente a simpatizzanti e appassionati. Durante le attivit\u00e0 ludico-sportive presenzieranno l\u2019Istituto comprensivo Tempesta-Galateo con l\u2019esibizione dell&#8217;orchestra musicale e l\u2019associazione di volontariato \u201cGiubbe Verdi &#8211; Compagnia Salento\u201d che consentir\u00e0, tramite attivit\u00e0 assistita, un giro a cavallo, con finalit\u00e0 ludico-ricreative. L\u2019attivit\u00e0 rientra nel Festival del benessere psicofisico, dello sport e della pari opportunit\u00e0 nell\u2019ambito del Programma Game Upi 2.0 \u2013 Progetto Game Open Ionico \u2013 Adriatico promosso dalla Provincia di Lecce. La giornata che promuover\u00e0 lo sport come strumento di inclusione sociale e di benessere psico-fisico, rappresenta l\u2019impegno costante dell\u2019associazione Rione Santa Rosa APS Lecce e ASD NEST, sul territorio, nel dare nuova linfa culturale, sociale e sportiva nel quartiere.&nbsp;<\/p>\n\n\n\n<p>Sensibilizzare TUTTI che&nbsp;lo sport \u00e8 sinonimo di benessere fisico e psicologico, non conosce disuguaglianze, ed \u00e8 la forma pi\u00f9 alta di integrazione e socializzazione.<\/p>\n\n\n\n<p><strong>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;RIONE SANTA ROSA APS&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; ASD NEST<\/strong><\/p>\n\n\n\n<p>\u00a0<em><strong>Pierluigi Caiulo\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<strong>Giovanna De Razza<\/strong><\/em><\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1280\" height=\"1600\" class=\"wp-image-250030\" style=\"width: 800px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA.jpeg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA.jpeg 1280w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA-240x300.jpeg 240w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA-819x1024.jpeg 819w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA-768x960.jpeg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/SPORT-DAY-SANTA-ROSA-1229x1536.jpeg 1229w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n\n\n\n<p><em><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0 <\/strong><\/em><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/sport-day-santa-rosa-giochi-e-discipline-a-lecce-domenica-12\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/sport-day-santa-rosa-giochi-e-discipline-a-lecce-domenica-12\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo _____________ In occasione della settimana europea dello sport, Rione Santa Rosa APS Lecce e ASD Nest organizzano domenica 12 ottobre dalle ore 9 alle ore 13 \u201cSPORT DAY SANTA ROSA\u201d. L\u2019evento, accreditato da&nbsp;Sport e Salute Spa&nbsp;e patrocinato dal&nbsp;Comune di Lecce&nbsp;e dalla&nbsp;Provincia di Lecce, si terr\u00e0 in Piazza Santa Rosa da Lima, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,36,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250028"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250028"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250028\/revisions"}],"predecessor-version":[{"id":250031,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250028\/revisions\/250031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250029"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}