{"id":250049,"date":"2025-10-10T15:26:07","date_gmt":"2025-10-10T13:26:07","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250049"},"modified":"2025-10-15T09:07:16","modified_gmt":"2025-10-15T07:07:16","slug":"utopia-sport-si-fa-in-quattro-squadre-e-porta-a-casa-nuovi-strabilianti-risultati-al-campionato-regionale-di-tennis-tavolo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/utopia-sport-si-fa-in-quattro-squadre-e-porta-a-casa-nuovi-strabilianti-risultati-al-campionato-regionale-di-tennis-tavolo\/","title":{"rendered":"UTOPIA SPORT SI FA IN QUATTRO&#8230;SQUADRE E PORTA A CASA NUOVI STRABILIANTI RISULTATI AL CAMPIONATO REGIONALE DI TENNIS TAVOLO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-1024x768.jpg\" alt=\"\" class=\"wp-image-250050\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-2048x1536.jpg 2048w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/tutt-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><br>di <strong>Carmen Leo<\/strong> __________ Il primo fine settimana di settembre ha segnato l\u2019inizio ufficiale del campionato regionale di <strong>Tennis Tavolo<\/strong>, un evento atteso con trepidazione non solo dai giocatori, ma anche dagli appassionati e dai sostenitori delle quattro squadre dell&#8217;Associazione <strong><em>Utopia Sport <\/em><\/strong>di Vernole.<\/p>\n\n\n\n<p>Quest\u2019anno, le formazioni sono divise tra la <strong>Serie D1<\/strong> e la <strong>Serie D2,<\/strong>  tutte pronte a dare il massimo in ogni incontro sportivo in calendario.<\/p>\n\n\n\n<p><br>Le prime sfide hanno visto protagoniste le due compagini <strong>Neretine<\/strong>, che si sono distinte con prestazioni encomiabili. <\/p>\n\n\n\n<p>La squadra di <strong>Serie D1<\/strong> ha affrontato il <strong>Team<\/strong> <strong>Casarano<\/strong> in trasferta, dove un mix di innegabile talento e indispensabile determinazione ha permesso agli atleti di conquistare una vittoria preziosa. <\/p>\n\n\n\n<p>Nonostante qualche difficolt\u00e0, i giovani e diversamente giovani atleti sono riusciti a portare a casa <strong>il punteggio di 4 a 3<\/strong>, un risultato che dimostra come la tenacia, la forza di volont\u00e0 e la grandissima passione per questo avvincente sport possano riuscire a superare qualsiasi ostacolo.<\/p>\n\n\n\n<p><br>Ma non pensiate sia finita qui! <\/p>\n\n\n\n<p>nella <strong>Serie D2<\/strong>, a Manduria, <strong><em>Utopia Sport<\/em><\/strong> che, come i nostri assidui lettori e fan sportivi avranno ormai ben compreso, di <strong>utopico<\/strong> ha soltanto il nome simbolico, si \u00e8 imposta in maniera decisa con un <strong>incredibile risultato di 6 a 1<\/strong>. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/9438-Sandro-Lezzi-LZZSDR58A05L074B.jpg\" alt=\"\" class=\"wp-image-250052\" width=\"312\" height=\"239\"\/><figcaption class=\"wp-element-caption\">SANDRO LEZZI<\/figcaption><\/figure><\/div>\n\n\n<p>Grazie all\u2019esperienza accumulata nel corso degli anni dai Coach e dai loro fedelissimi atleti, alla strepitosa associazione sportiva salentina \u00e8 stato possibile dimostrare che la preparazione assidua e costante, unitamente all&#8217;imprescindibile <strong>lavoro di squadra<\/strong>, sono fondamentali per ottenere i successi attesi e meritati.<\/p>\n\n\n\n<p>Negli incontri svoltisi in casa, tuttavia, le cose si sono rivelate pi\u00f9 complicate.<\/p>\n\n\n\n<p>La squadra <strong><em>Utopia Home Idea<\/em><\/strong>, capitanata da <strong><em>Marco Bevilacqua<\/em><\/strong> (in basso nella foto a destra) e composta da <strong><em>Sandro Lezzi (<\/em><\/strong>nella foto in alto<strong><em>) <\/em><\/strong>e <strong><em>Marco Botrugno<\/em><\/strong> (in basso nella foto a sinistra), ha affrontato il <strong><em>TT D. G. Palam\u00e0 <\/em><\/strong>di Sogliano Cavour.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/883009-Marco-Bevilacqua-BVLMRC79D11F152S.jpg\" alt=\"\" class=\"wp-image-250053\" width=\"218\" height=\"394\"\/><figcaption class=\"wp-element-caption\">MARCO BEVILACQUA<\/figcaption><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p>Qui, la lunga assenza dai tavoli da gioco dei due <strong>Marco<\/strong> si \u00e8 fatta sentire. <\/p>\n\n\n\n<p>Nonostante gli sforzi e il tifo agguerrito del pubblico, la squadra \u00e8 riuscita a vincere solo il doppio, chiudendo il match con una sconfitta per 6 a 1. <\/p>\n\n\n\n<p>Un risultato difficile da digerire, ma che rappresenta anche una lezione importante per il futuro.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/30569-Marco-Botrugno-BTRMRC83R07C978P.jpg\" alt=\"\" class=\"wp-image-250054\" width=\"258\" height=\"327\"\/><figcaption class=\"wp-element-caption\">MARCO BOTRUGNO<\/figcaption><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p>In contemporanea, sull\u2019altro campo, la squadra di Serie D2,  <strong><em>Utopia Body Master<\/em><\/strong>, guidata da <strong><em>Stefano Greco<\/em><\/strong> e affiancata da <strong><em>Matteo Ralletto, Luigi De Pascalis <\/em><\/strong>e<strong><em> Alberto Giannone<\/em><\/strong>, (nella foto in basso il team al completo), ha brillato con una prestazione solida e decisa. <\/p>\n\n\n\n<p>Sin dal primo incontro, la formazione ha cercato di imporsi, e il capitano ha schierato <strong><em>Alberto<\/em><\/strong>, che ha aperto le danze sportive portando il primo punto alla squadra.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"341\" height=\"329\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/1010063-Stefano-Greco-GRCSFN77H25I119L.jpg\" alt=\"\" class=\"wp-image-250056\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/1010063-Stefano-Greco-GRCSFN77H25I119L.jpg 341w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/1010063-Stefano-Greco-GRCSFN77H25I119L-300x289.jpg 300w\" sizes=\"(max-width: 341px) 100vw, 341px\" \/><figcaption class=\"wp-element-caption\">STEFANO GRECO <\/figcaption><\/figure><\/div>\n\n\n<p><\/p>\n\n\n\n<p>Anche <strong><em>Greco<\/em><\/strong>, nonostante alcune difficolt\u00e0, ha contribuito al bottino, seguito dall\u2019esordiente <strong><em>Matteo<\/em><\/strong>, che ha conquistato il suo primo punto in un match molto ostico. <\/p>\n\n\n\n<p>Da quel momento, <strong><em>De Pascalis<\/em><\/strong> ha confermato la fiducia del suo capitano, chiudendo l\u2019incontro con un <strong>trionfo convincente per 6 a 1<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-1024x768.jpg\" alt=\"\" class=\"wp-image-250055\" width=\"805\" height=\"604\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/BODY-MASTER.jpg 2040w\" sizes=\"(max-width: 805px) 100vw, 805px\" \/><figcaption class=\"wp-element-caption\">TEAM BODY MASTER<\/figcaption><\/figure>\n\n\n\n<p>Il primo fine settimana di campionato si \u00e8, quindi, concluso con ben <strong>tre vittorie su quattro<\/strong> e una grande soddisfazione nel cuore di tutti i tesserati dell<strong><em>\u2019Utopia<\/em><\/strong>. <\/p>\n\n\n\n<p>L\u2019atmosfera \u00e8 gi\u00e0 &#8220;<strong>carica a palline da ping pong&#8221; <\/strong>di entusiasmo e voglia di vincere!<\/p>\n\n\n\n<p><strong><em>Utopia<\/em><\/strong> nel weekend del 18 e 19 settembre scorsi \u00e8 scesa in campo nazionale con la <strong>Serie A Paralimpica<\/strong> a Roma e con la <strong>Serie C Master<\/strong> con altri eccellenti risultati. <\/p>\n\n\n\n<p>Le aspettative per chi segue da tifoso questo sport e, soprattutto i <strong>SuperFantastic<\/strong>i atleti di <strong><em>Utopia Sport<\/em><\/strong> sono sempre molto alte, ma mai superiori, possiamo senza dubbio alcuno affermare, alla determinazione e al coraggio di questi atleti e atlete, in ciascuna delle categorie di appartenenza.<\/p>\n\n\n\n<p>La loro straordinaria forza non appartiene soltanto alla prestanza fisica e disciplina dei singoli atleti\/e, ma nell&#8217;educazione ferrea al <strong>gioco di squadra<\/strong>, che comprende la volont\u00e0 di tutti di sostenere ognuno e di poter, in tal modo, assistere al successo di ciascuno, che conduce inevitabilmente e con immensa soddisfazione al vero trionfo di <strong>TUTTI<\/strong>.  <\/p>\n\n\n\n<p>Sar\u00e0 questo il vero <strong>segreto dei grandi success<\/strong>i della grande famiglia di <strong><em>Utopia Sport?<\/em><\/strong><\/p>\n\n\n\n<p>Una <strong>famiglia<\/strong> certamente allargata, che riunisce in s\u00e8 atleti\/e normodotati e paralimpici, perfettamente integrati tra loro da non sentire e vedere quelle barriere architettoniche metafisiche che solo una societ\u00e0 gretta e chiusa continua ad erigere, per abbattere le quali i nostri <strong>Utopici Atleti&amp;Atlete<\/strong> hanno fatto proprio l&#8217;aforisma: &#8220;<strong><em>Sii sempre sordo quando qualcuno ti dice che non puoi realizzare i tuoi sogni!&#8221;<\/em><\/strong><\/p>\n\n\n\n<p>E noi potremmo aggiungere, con una punta, consentiteci, di garbata ironia: <strong><em>&#8220;Non c&#8217;\u00e8 peggior cieco di chi non vuol vedere che Loro hanno perfettamente ragione!&#8221;<\/em><\/strong> <\/p>\n\n\n\n<p> <strong>Amici&amp;Amiche<\/strong>, lettori, sportivi e appassionati di tutte le et\u00e0, tenetevi pronti, il campionato e le grandi, nuove, avventure e vittorie di <strong><em>Utopia Sport<\/em> <\/strong>sono appena cominciate: <strong>STAY TUNED!!!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1-576x1024.jpg\" alt=\"\" class=\"wp-image-250057\" width=\"289\" height=\"515\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1-576x1024.jpg 576w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1-169x300.jpg 169w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1-768x1365.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1-864x1536.jpg 864w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/mattia-e-rod-1.jpg 1152w\" sizes=\"(max-width: 289px) 100vw, 289px\" \/><\/figure>\n\n\n\n<p><br><\/p>\n\n\n\n<p><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/utopia-sport-si-fa-in-quattro-squadre-e-porta-a-casa-nuovi-strabilianti-risultati-al-campionato-regionale-di-tennis-tavolo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/utopia-sport-si-fa-in-quattro-squadre-e-porta-a-casa-nuovi-strabilianti-risultati-al-campionato-regionale-di-tennis-tavolo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Carmen Leo __________ Il primo fine settimana di settembre ha segnato l\u2019inizio ufficiale del campionato regionale di Tennis Tavolo, un evento atteso con trepidazione non solo dai giocatori, ma anche dagli appassionati e dai sostenitori delle quattro squadre dell&#8217;Associazione Utopia Sport di Vernole. Quest\u2019anno, le formazioni sono divise tra la Serie D1 e la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,75,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250049"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250049"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250049\/revisions"}],"predecessor-version":[{"id":250071,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250049\/revisions\/250071"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}