{"id":250066,"date":"2025-10-10T12:23:00","date_gmt":"2025-10-10T10:23:00","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250066"},"modified":"2025-10-10T15:55:52","modified_gmt":"2025-10-10T13:55:52","slug":"lequile-tentano-il-colpo-in-gioielleria-arrestate-due-donne","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/lequile-tentano-il-colpo-in-gioielleria-arrestate-due-donne\/","title":{"rendered":"LEQUILE: TENTANO IL COLPO IN GIOIELLERIA, ARRESTATE DUE DONNE"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"728\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-1024x728.jpg\" alt=\"\" class=\"wp-image-250067\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-1024x728.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-300x213.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-768x546.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-1536x1092.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/Piazza_Lequile-2048x1456.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>(f.f.)_____________<\/p>\n\n\n\n<p>Hanno provato a mettere a segno l\u2019ennesimo raggiro ai danni di un commerciante, ma questa volta il piano non \u00e8 andato come previsto. Due donne, madre e figlia, entrambe originarie della Campania e gi\u00e0 conosciute dalle forze dell\u2019ordine per precedenti simili, sono finite in arresto a Lequile dopo aver tentato di sottrarre preziosi da una gioielleria del centro.<\/p>\n\n\n\n<p>Il modus operandi era quello classico: mentre una distraeva il titolare con richieste e domande, l\u2019altra tentava di impossessarsi di alcuni oggetti di valore esposti in vetrina. Il gioielliere, per\u00f2, insospettito dai loro movimenti, ha immediatamente contattato il 112 chiedendo l\u2019intervento dei carabinieri.<\/p>\n\n\n\n<p>Sul posto sono accorsi i militari del Nucleo operativo e radiomobile della compagnia di Lecce insieme ai colleghi della stazione di San Pietro in Lama. Le due sospettate sono state bloccate in flagranza di reato e condotte in caserma.<\/p>\n\n\n\n<p>Terminate le procedure di rito, su disposizione del pubblico ministero di turno della Procura di Lecce, le donne sono state dichiarate in arresto con l\u2019accusa di tentato furto aggravato.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/lequile-tentano-il-colpo-in-gioielleria-arrestate-due-donne\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/10\/lequile-tentano-il-colpo-in-gioielleria-arrestate-due-donne\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)_____________ Hanno provato a mettere a segno l\u2019ennesimo raggiro ai danni di un commerciante, ma questa volta il piano non \u00e8 andato come previsto. Due donne, madre e figlia, entrambe originarie della Campania e gi\u00e0 conosciute dalle forze dell\u2019ordine per precedenti simili, sono finite in arresto a Lequile dopo aver tentato di sottrarre preziosi da [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250067,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250066"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250066"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250066\/revisions"}],"predecessor-version":[{"id":250069,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250066\/revisions\/250069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250067"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}