{"id":25072,"date":"2014-02-26T16:30:55","date_gmt":"2014-02-26T16:30:55","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=25072"},"modified":"2014-02-26T16:30:55","modified_gmt":"2014-02-26T16:30:55","slug":"casting-2014","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/26\/casting-2014\/","title":{"rendered":"CASTING 2014"},"content":{"rendered":"<p>Italian Talent Lab: domenica 2 marzo il Casting a Monteroni<br \/>\n<a href=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/1780674_651954354864518_619470165_n.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/1780674_651954354864518_619470165_n-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-25073\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/1780674_651954354864518_619470165_n-212x300.jpg 212w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2014\/02\/1780674_651954354864518_619470165_n.jpg 480w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a>Il Concorso cerca e valorizza talenti tra i 5 e i 16 anni<br \/>\nContinuano le selezioni del Concorso Nazionale Italian Talent Lab, nato con l\u2019obiettivo di valorizzare i talenti di et\u00e0 compresa tra i 5 e i 16 anni nell\u2019ambito di svariate discipline: dal canto alla recitazione, dalla musica al cabaret, dalla danza alla moda.<br \/>\nDomenica 2 marzo, presso la Palestra Action a Monteroni, avranno luogo i Casting validi per l\u2019ammissione al Concorso Nazionale Italian Talent Lab.<br \/>\nLa Vip Animation, in qualit\u00e0 di Produzione Nazionale, oltre ad organizzare le Pre-Finali e Finali Nazionali, si occuper\u00e0 anche delle selezioni in Puglia.<br \/>\nLa scorsa edizione ha visto proprio un salentino trionfare nel corso della finale svoltasi nella suggestiva cornice dell\u2019anfiteatro dell\u2019Hotel &amp; Resort Messapia di Santa Maria di Leuca. Qui, Federico Sanfrancesco, cabarettista salentino, ha vinto il titolo di Italian Talent Lab 2013.<br \/>\nIl Concorso, organizzato da Giovanni Conversano, si sviluppa attraverso Casting d\u2019accesso per poi toccare le Piazze pi\u00f9 belle d\u2019Italia con le rispettive selezioni provinciali e Finali Regionali che permetteranno ai vincitori di accedere alle Pre-Finali Nazionali in programma dal 14 al 16 settembre 2014 proprio nel Salento.<br \/>\nLa precedente edizione ha visto arrivare in finale un\u2019elevata qualit\u00e0 artistica, frutto dell\u2019eccellente lavoro svolto nelle selezioni dagli Agenti Regionali di tutta Italia che hanno saputo scoprire dei grandi talenti \u201cnascosti\u201d dalla giovane et\u00e0 e portati alla luce dal talent show itinerante.<br \/>\nPer partecipare al Casting di domenica 2 marzo a Monteroni di Lecce, basta iscriversi gratuitamente attraverso il sito www.italiantalentlab.it o contattare il 3466846414.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/26\/casting-2014\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2014\/02\/26\/casting-2014\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Italian Talent Lab: domenica 2 marzo il Casting a Monteroni Il Concorso cerca e valorizza talenti tra i 5 e i 16 anni Continuano le selezioni del Concorso Nazionale Italian Talent Lab, nato con l\u2019obiettivo di valorizzare i talenti di et\u00e0 compresa tra i 5 e i 16 anni nell\u2019ambito di svariate discipline: dal canto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25072"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=25072"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25072\/revisions"}],"predecessor-version":[{"id":25074,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/25072\/revisions\/25074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/25073"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=25072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=25072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=25072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}