{"id":250797,"date":"2025-10-29T13:14:56","date_gmt":"2025-10-29T12:14:56","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250797"},"modified":"2025-10-29T13:16:36","modified_gmt":"2025-10-29T12:16:36","slug":"lecce-tragedia-in-cantiere-operaio-muore-folgorato-durante-i-lavori-in-campagna","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/lecce-tragedia-in-cantiere-operaio-muore-folgorato-durante-i-lavori-in-campagna\/","title":{"rendered":"LECCE, TRAGEDIA IN CANTIERE: OPERAIO MUORE FOLGORATO DURANTE LAVORI"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/images-16.jpeg\" alt=\"\" class=\"wp-image-250798\" width=\"396\" height=\"222\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/images-16.jpeg 739w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/images-16-300x168.jpeg 300w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/figure>\n\n\n\n<p>(f.f.)__________<\/p>\n\n\n\n<p>Un grave incidente sul lavoro \u00e8 costato la vita questa mattina a un operaio di 67 anni di origine albanese, residente nel capoluogo salentino. L\u2019uomo \u00e8 rimasto folgorato mentre era impegnato in alcuni lavori edili nella zona di via Vecchia Frigole, in aperta campagna.<\/p>\n\n\n\n<p>Secondo una prima ricostruzione, la vittima stava collaborando alla costruzione di un muretto a secco quando, per cause in corso di accertamento, la pompa per l\u2019impasto del cemento avrebbe urtato i cavi dell\u2019alta tensione. L\u2019impatto con i fili elettrici ha generato una violenta scarica che ha colpito in pieno l\u2019operaio, folgorandolo all\u2019istante.L\u2019allarme \u00e8 stato lanciato immediatamente dai colleghi presenti, che hanno chiesto l\u2019intervento dei soccorsi. <\/p>\n\n\n\n<p>Sul posto sono giunti in pochi minuti i sanitari del 118, ma ogni tentativo di rianimazione si \u00e8 rivelato inutile: per l\u2019uomo non c\u2019era pi\u00f9 nulla da fare.<\/p>\n\n\n\n<p>In via Vecchia Frigole sono intervenuti anche i vigili del fuoco del comando provinciale di Lecce per mettere in sicurezza l\u2019area e il macchinario coinvolto. Presenti inoltre gli agenti della polizia di Stato, i carabinieri e il personale dello Spesal, incaricato di eseguire i rilievi tecnici e di verificare il rispetto delle norme di sicurezza sul lavoro.Su disposizione del magistrato di turno, la salma \u00e8 stata trasferita presso la camera mortuaria dell\u2019ospedale \u201cVito Fazzi\u201d per i successivi accertamenti. <\/p>\n\n\n\n<p>L\u2019autorit\u00e0 giudiziaria ha aperto un\u2019inchiesta per chiarire le dinamiche dell\u2019incidente e valutare eventuali responsabilit\u00e0.La comunit\u00e0 locale, sconvolta dalla notizia, si stringe attorno ai familiari dell\u2019uomo, descritto come un lavoratore esperto e instancabile. L\u2019ennesimo tragico episodio che riaccende i riflettori sul tema della sicurezza nei cantieri, troppo spesso teatro di incidenti fatali.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/lecce-tragedia-in-cantiere-operaio-muore-folgorato-durante-i-lavori-in-campagna\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/lecce-tragedia-in-cantiere-operaio-muore-folgorato-durante-i-lavori-in-campagna\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)__________ Un grave incidente sul lavoro \u00e8 costato la vita questa mattina a un operaio di 67 anni di origine albanese, residente nel capoluogo salentino. L\u2019uomo \u00e8 rimasto folgorato mentre era impegnato in alcuni lavori edili nella zona di via Vecchia Frigole, in aperta campagna. Secondo una prima ricostruzione, la vittima stava collaborando alla costruzione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250798,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250797"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250797"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250797\/revisions"}],"predecessor-version":[{"id":250805,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250797\/revisions\/250805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250798"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}