{"id":250801,"date":"2025-10-29T14:04:39","date_gmt":"2025-10-29T13:04:39","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250801"},"modified":"2025-10-29T14:04:42","modified_gmt":"2025-10-29T13:04:42","slug":"svolta-nelle-indagini-bancomat-due-giovani-arrestati-mentre-preparavano-un-nuovo-assalto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/svolta-nelle-indagini-bancomat-due-giovani-arrestati-mentre-preparavano-un-nuovo-assalto\/","title":{"rendered":"SVOLTA NELLE INDAGINI BANCOMAT: DUE GIOVANI ARRESTATI MENTRE PREPARAVANO UN NUOVO ASSALTO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/e12d5e19-0cc2-4817-96f7-204574433926.jpeg\" alt=\"\" class=\"wp-image-250803\" width=\"396\" height=\"286\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/e12d5e19-0cc2-4817-96f7-204574433926.jpeg 996w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/e12d5e19-0cc2-4817-96f7-204574433926-300x217.jpeg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/10\/e12d5e19-0cc2-4817-96f7-204574433926-768x555.jpeg 768w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/figure>\n\n\n\n<p>(f.f.)____________<\/p>\n\n\n\n<p>Si stringe il cerchio attorno alla cosiddetta \u201cbanda della marmotta\u201d, il gruppo criminale che nelle ultime settimane ha fatto saltare numerosi sportelli automatici in tutta la Puglia. Due giovani, un 21enne di Foggia e un 20enne originario di Orta Nova, sono stati fermati ieri dai carabinieri a Galatone mentre, secondo le indagini, si preparavano a colpire ancora.<\/p>\n\n\n\n<p>L\u2019operazione \u00e8 scattata intorno alle 23, quando una pattuglia ha intercettato una Opel Corsa a noleggio lungo via San Giuseppe da Copertino. A bordo, i militari hanno rinvenuto un vero arsenale da scasso: diversi chili di esplosivo, guanti, passamontagna e strumenti utilizzati per aprire forzieri. <\/p>\n\n\n\n<p>Tutto lasciava pensare che il gruppo stesse per mettere a segno un nuovo colpo ai danni di un bancomat della zona. I due fermati, identificati come Simone Armeri e Denis Nicola Arace, sono stati condotti nel carcere di Borgo San Nicola, a Lecce, su disposizione della Procura. Le indagini, coordinate dal Nucleo investigativo dei carabinieri di Lecce e guidate dal tenente colonnello Cristiano Marella, hanno visto la collaborazione delle compagnie di Gallipoli e Foggia.<\/p>\n\n\n\n<p>Gli investigatori sospettano che i due facciano parte di una rete pi\u00f9 ampia e ben organizzata, responsabile di almeno tredici assalti tra le province di Lecce e Brindisi, oltre ad altri episodi nel resto della regione. L\u2019azione di ieri notte, infatti, potrebbe rappresentare solo l\u2019ultimo tassello di una lunga catena di esplosioni che, a partire dall\u2019estate, ha devastato numerosi sportelli automatici, seminando paura e danni ingenti.In alcuni dei colpi pi\u00f9 recenti, come quelli avvenuti a Torre San Giovanni e Presicce-Acquarica, la banda aveva utilizzato automobili rubate, successivamente ritrovate bruciate per cancellare ogni traccia.<\/p>\n\n\n\n<p>Un modus operandi che denota freddezza e pianificazione, segno di un\u2019organizzazione rodata e abituata a muoversi con rapidit\u00e0 sul territorio.Nelle stesse ore, altri due uomini sono stati fermati nel Foggiano, ritenuti complici dei giovani bloccati nel Salento. Tutto il materiale esplosivo e gli attrezzi recuperati sono stati sequestrati e saranno ora analizzati per individuare eventuali collegamenti con le precedenti esplosioni.<\/p>\n\n\n\n<p>Gli inquirenti non escludono nuovi sviluppi nelle prossime ore: la \u201cbanda della marmotta\u201d, che negli ultimi mesi ha messo in allerta istituti di credito e forze dell\u2019ordine in tutta la regione, potrebbe finalmente avere i giorni contati.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/svolta-nelle-indagini-bancomat-due-giovani-arrestati-mentre-preparavano-un-nuovo-assalto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/29\/svolta-nelle-indagini-bancomat-due-giovani-arrestati-mentre-preparavano-un-nuovo-assalto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.f.)____________ Si stringe il cerchio attorno alla cosiddetta \u201cbanda della marmotta\u201d, il gruppo criminale che nelle ultime settimane ha fatto saltare numerosi sportelli automatici in tutta la Puglia. Due giovani, un 21enne di Foggia e un 20enne originario di Orta Nova, sono stati fermati ieri dai carabinieri a Galatone mentre, secondo le indagini, si preparavano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250803,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250801"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250801"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250801\/revisions"}],"predecessor-version":[{"id":250810,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250801\/revisions\/250810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250803"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}