{"id":250911,"date":"2025-11-01T12:29:02","date_gmt":"2025-11-01T11:29:02","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250911"},"modified":"2025-11-04T13:03:55","modified_gmt":"2025-11-04T12:03:55","slug":"io-non-sto-con-sigfrido-ranucci-io-sto-con-agostino-ghiglia","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/io-non-sto-con-sigfrido-ranucci-io-sto-con-agostino-ghiglia\/","title":{"rendered":"IO NON STO CON SIGFRIDO RANUCCI, IO STO CON AGOSTINO GHIGLIA"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1200\" height=\"771\" class=\"wp-image-250912\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Privacy_Agostino_Ghiglia-scaled-e1636466245891.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Privacy_Agostino_Ghiglia-scaled-e1636466245891.jpg 1200w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Privacy_Agostino_Ghiglia-scaled-e1636466245891-300x193.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Privacy_Agostino_Ghiglia-scaled-e1636466245891-1024x658.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/Privacy_Agostino_Ghiglia-scaled-e1636466245891-768x493.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n\n\n\n<p>di <strong>Giuseppe Puppo ____________<\/strong><\/p>\n\n\n\n<p>&#8220;Sono membro di un&#8217;Autorit\u00e0 che svolge un ruolo delicato e complesso e da giorni mi trovo esposto ad una invereconda gogna mediatica&#8221;. <\/p>\n\n\n\n<p>Comincia cos\u00ec una dichiarazione all&#8217;agenzia Ansa di Agostino Ghiglia, 60 anni, di Torino, gi\u00e0 consigliere regionale e deputato al Parlamento, attualmente componente dell&#8217;Autorit\u00e0 Garante per la Privacy, in quota Fratelli d&#8217;Italia. Ruolo per cui egli rivendica<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8220;assoluta linearit\u00e0 e trasparenza dell&#8217;attivit\u00e0 del Collegio e dei funzionari del Garante che, nonostante l&#8217;acclarato sottodimensionamento, profondono tutte le loro energie per difendere, sempre e senza sconti, i diritti delle persone comuni o famose che siano, nei tempi corretti e senza alcun favoritismo o via preferenziale&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>In un&#8217;intervista a Giuseppe Legato del quotidiano La Stampa, ad un certo punto poi Agostino Ghiglia aggiunge, rispondendo alla domanda &#8211; <strong>Dopo anni in An e Pdl qualcuno l&#8217;ha chiamata per darle solidariet\u00e0?<\/strong><\/p>\n\n\n\n<p>\u00abNo e questo mi ha fatto riflettere umanamente parlando. Nessuno, nemmeno da sinistra, mi ha scritto. Al contrario lo hanno fatto avvocati, funzionari e dipendenti dell&#8217;ufficio. Credo di aver dato molto alla mia comunit\u00e0 anche come amministratore. Un messaggino me lo sarei aspettato\u00bb.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un messaggino social, glielo mando io, che non faccio parte della sua comunit\u00e0, che non mi riconosco in Fratelli d&#8217;Italia e non mi riconoscevo nemmeno in Alleanza Nazionale, io che con lui, che ovviamente conosco e che ho frequentato nei tanti anni in cui sono stato addetto stampa della Regione Piemonte, ho avuto un rapporto spesso critico e anzi conflittuale, su tante questioni politiche, ma comunque di stima, per cui i nostri dialoghi, quando, per una ragione o per l&#8217;altra ci incrociavamo da qualche parte, erano sempre a brevi dialoghi sincopati, ma sempre col sorriso sulle labbra.<\/p>\n\n\n\n<p>Il messaggino \u00e8 questo: io non sto con Sigfrido Ranucci, io sto con Agostino Ghiglia.<\/p>\n\n\n\n<p>Dico questo dopo aver passato ore a studiare i casi di cui si \u00e8 trattato e si tratter\u00e0 ancora nella trasmissione &#8220;Report&#8221;, perch\u00e9 mi piace parlare e anzi scrivere solo di cose che conosco: bene, in tutti questi casi &#8220;imputati&#8221; da Sigfrido Ranucci ad Agostino Ghiglia io, dopo averli analizzati in dettaglio, non ho trovato nessuna presunta colpa e invece ho ravvisato solamente l&#8217;adempimento corretto del suo compito di Commissario dell&#8217; Autorit\u00e0 per la Privacy.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A dirla tutta, non mi piace questo modo di fare giornalismo, intendo dell&#8217;invasione nella sfera privata delle persone, delle registrazioni spuntate fuori per miracolo, dei video segreti, degli appostamenti e dell&#8217;accanimento multimediale.<\/p>\n\n\n\n<p>Ho visto poi, nel corso delle mie ricerche, che nei confronti di Ghiglia all&#8217;epoca ragazzo \u00e8 stata riesumata anche una vecchia storia di violenza politica, per qualificarlo come &#8220;picchiatore fascista&#8221;. A chi l&#8217;ha risumata, vorrei sommessammente far notare che gli anni di piombo &#8211; con ci\u00f2 intendo tutto quello che a tale espressione viene comunemente associato &#8211; a Torino e in Piemonte sono durati due decenni di pi\u00f9 che in tutto il resto d&#8217;Italia, e anche qui posso parlare con cognizione di causa: a Torino e in Piemonte sono finiti solamente con l&#8217;inizio del nuovo secolo e del nuovo millennio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Infine, aggiungo che le persone cambiano, a volte in meglio, a volte in peggio. Ghiglia \u00e8 cambiato in meglio, proprio facendo politica, anzi proprio negli ultimi anni in cui, sia pur in quota Fratelli d&#8217;Italia &#8211; partito, giova ricordarlo, che delle diavolerie alla Elon Musk e delle americanate collegate ha fatto componenti aggiuntive della propria identit\u00e0 politica &#8211; \u00e8 membro super partes di un&#8217;Autorit\u00e0 governativa super partes.  <\/p>\n\n\n\n<p>Dico questo dopo aver letto le sue lucide osservazioni postate sul diario di Facebook personale: non avevo mai letto &#8211; e c&#8217;\u00e8 da riflettere, c&#8217;\u00e8 da imparare &#8211; niente di pi\u00f9 lucido, di pi\u00f9 attuale e di pi\u00f9 profetico al tempo stesso, delle denunce elaborate da Agostino Ghiglia sui percoli della cos\u00ec detta Intelligenza Artificiale e sulla invadenza della cos\u00ec detta Tecnologia nelle nostre vite  quotidiane di contemporanei.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/io-non-sto-con-sigfrido-ranucci-io-sto-con-agostino-ghiglia\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/io-non-sto-con-sigfrido-ranucci-io-sto-con-agostino-ghiglia\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Giuseppe Puppo ____________ &#8220;Sono membro di un&#8217;Autorit\u00e0 che svolge un ruolo delicato e complesso e da giorni mi trovo esposto ad una invereconda gogna mediatica&#8221;. Comincia cos\u00ec una dichiarazione all&#8217;agenzia Ansa di Agostino Ghiglia, 60 anni, di Torino, gi\u00e0 consigliere regionale e deputato al Parlamento, attualmente componente dell&#8217;Autorit\u00e0 Garante per la Privacy, in quota [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250911"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250911"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250911\/revisions"}],"predecessor-version":[{"id":250924,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250911\/revisions\/250924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250912"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}