{"id":250925,"date":"2025-11-01T14:38:23","date_gmt":"2025-11-01T13:38:23","guid":{"rendered":"https:\/\/www.leccecronaca.it\/?p=250925"},"modified":"2025-11-04T13:19:51","modified_gmt":"2025-11-04T12:19:51","slug":"usanze-tradizioni-e-miti-della-sardegna-nelle-festivita-di-ognissanti-e-dei-morti-manuela-congiu-le-racconta-a-leccecronaca-it","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/usanze-tradizioni-e-miti-della-sardegna-nelle-festivita-di-ognissanti-e-dei-morti-manuela-congiu-le-racconta-a-leccecronaca-it\/","title":{"rendered":"USANZE, TRADIZIONI E MITI DELLA SARDEGNA NELLE FESTIVITA&#8217; DI OGNISSANTI E DEI MORTI. MANUELA CONGIU LE RACCONTA A leccecronaca.it"},"content":{"rendered":"\n<p><img decoding=\"async\" loading=\"lazy\" width=\"384\" height=\"384\" class=\"wp-image-250926\" style=\"width: 1500px;\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/mc.jpg\" alt=\"\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/mc.jpg 384w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/mc-300x300.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/mc-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2025\/11\/mc-60x60.jpg 60w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/p>\n\n\n\n<p>di <strong>Cristina Pipoli ______________<\/strong><\/p>\n\n\n\n<p>\u201cPer far vivere il seme Qualcosa deve morire e trasformarsi, cos\u00ec da dare energia al seme per poter rinasce. Il culto dei morti in Sardegna molto profondo perch\u00e9 ci connette alle nostre radici e loro, i nostri antenati e le nostre antenate, non mancano di farci visita in questo periodo\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Vuole raccontarci qualcosa su questi due giorni di festa?<\/p>\n\n\n\n<p>R- &#8220;In questo periodo in Sardegna si possono notare ancora molto forti reminiscenze del mondo sciamanico che sia andato a mischiare con la religione cattolica&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Come descriverebbe lo sciamanesimo alle persone che ci leggono?<\/p>\n\n\n\n<p>R- &#8220;Lo sciamanesimo, prima di essere una religione, \u00e8 una realt\u00e0 impalpabile. Questo \u00e8 un periodo in cui bisogna stare molto attenti con le pratiche sciamaniche perch\u00e9 i portali sono aperti: sarebbe meglio non fare niente se non si sanno fare le cose in sicurezza, almeno questo \u00e8 il mio consiglio per questo periodo&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Ci vuole raccontare qualche antica tradizione della sua terra inerente il 1 e il 2 novembre?<\/p>\n\n\n\n<p>R- &#8220;In questo periodo In Sardegna ci sono un sacco di tradizioni a seconda del paese e delle famiglie. Tutti sappiamo che in questo periodo gli spiriti degli antenati e delle antenate vanno a trovare il loro discendenti e le loro discendenti: portano messaggi, portano amore, portano richieste. I dolci tipici di in questo periodo sono scuri e molto nutrienti, di solito contengono semi e stanno a simboleggiare da un lato la morte e dall&#8217;altro la rinascita.<\/p>\n\n\n\n<p>Il clou del culto degli antenati si ha il 2 novembre, quando solitamente le persone si riversano nei cimiteri a pulirli. Ognuno si occupa delle tombe della sua famiglia, le pulisce, le riempie di fiori e si ferma a pregare per i propri defunti&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Quali sono i dolci tipici della sua terra?<\/p>\n\n\n\n<p>R- &#8220;I dolci tipici sardi di questo periodo sono il pane Saba e le papassine, biscotti golosi con  mandorle, uva passa e noci. <\/p>\n\n\n\n<p>Per il pane Saba esistono diverse ricette. A seconda dei territori e delle famiglie ci sono delle versioni che hanno tantissima frutta secca impastata con la sapa ( una sorta di marmellata molto densa che si pu\u00f2 fare col mosto, le fico d&#8217;India, le arance e il miele), poca farina o semola,  in un mix di spezie dal sapore antico, oppure versioni che sono pi\u00f9 simili a una torta come nel mio territorio con dentro le mandorle e ovviamente non possono mancare sapa e spezie&#8221;&nbsp;<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Vuole condividere con noi qualche tradizione tipica della sua famiglia?<\/p>\n\n\n\n<p>R- &#8220;Nella mia famiglia materna, forse per tenerci un po&#8217; impegnati quando eravamo in cimitero, la mia mamma e le mie nonne ci hanno insegnato a pulire le tombe abbandonate, quelle dove non c&#8217;\u00e8 pi\u00f9 nessuno che li ricord. Quindi quando prendiamo i fiori per i nostri defunti qualcuno lo lasciamo per le tombe abbandonate, in modo da onorare anche le persone che non hanno pi\u00f9 chi le ricorda. Comunque il culto dei morti in Sardegna \u00e8 vivo tutto l&#8217;anno nelle famiglie. Per esempio, nelle case della mia famiglia non mancano le foto degli avi e delle ave&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Altre antiche tradizioni sarde?<\/p>\n\n\n\n<p>R- &#8220;In alcune cimiteri in Sardegna c&#8217;\u00e8 anche un monumento in cui si possono mettere i fiori per i defunti che sono sepolti lontani.<\/p>\n\n\n\n<p>Un&#8217;altra usanza \u00e8 lasciare apparecchiato il tavolo con cibo acqua e vino; a seconda delle zone ci sono modi diversi, per esempio in alcune zone non si mettono le posate perch\u00e9 se il morto che viene a mangiare di malumore potrebbe fare male alle persone&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>D- Cosa vuole dirci sulla foto che la ritrae oggi in questa intervista?<\/p>\n\n\n\n<p>R- &#8220;E&#8217; un murales che ho dipinto intorno ai 21 anni e parla delle nostre antiche tradizioni. Si trova a Muravera, fu anche premiato&#8221;.<\/p>\n\n\n\n<p>_______________<\/p>\n\n\n\n<p>Info sulla scuola COME LA FENICE:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/manuelacongiujanabella\/?locale=it_IT\">https:\/\/www.facebook.com\/manuelacongiujanabella\/?locale=it_IT<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>LA RICERCA nel nostro articolo del 19 ottobre scorso<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-leccecronaca-it wp-block-embed-leccecronaca-it\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"EMzUgoOf7j\"><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/19\/lintervista-manuela-congiu-janabella-fondatrice-della-scuola-come-la-fenice-qui-si-impara-a-tornare-a-se-stessi-a-riscoprire-i-propri-talenti-e-riaprire-il-contatto-con-la-propria\/\">L&#8217;INTERVISTA \/ MANUELA CONGIU JANABELLA, FONDATRICE DELLA SCUOLA &#8216;COME LA FENICE&#8217;: \u201cQui si impara a tornare a s\u00e9 stessi, a riscoprire i propri talenti e riaprire il contatto con la propria anima\u201d<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;L&#8217;INTERVISTA \/ MANUELA CONGIU JANABELLA, FONDATRICE DELLA SCUOLA &#8216;COME LA FENICE&#8217;: \u201cQui si impara a tornare a s\u00e9 stessi, a riscoprire i propri talenti e riaprire il contatto con la propria anima\u201d&#8221; &#8212; LecceCronaca.it\" src=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/10\/19\/lintervista-manuela-congiu-janabella-fondatrice-della-scuola-come-la-fenice-qui-si-impara-a-tornare-a-se-stessi-a-riscoprire-i-propri-talenti-e-riaprire-il-contatto-con-la-propria\/embed\/#?secret=4hPXjwFM0f#?secret=EMzUgoOf7j\" data-secret=\"EMzUgoOf7j\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/usanze-tradizioni-e-miti-della-sardegna-nelle-festivita-di-ognissanti-e-dei-morti-manuela-congiu-le-racconta-a-leccecronaca-it\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/11\/01\/usanze-tradizioni-e-miti-della-sardegna-nelle-festivita-di-ognissanti-e-dei-morti-manuela-congiu-le-racconta-a-leccecronaca-it\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Cristina Pipoli ______________ \u201cPer far vivere il seme Qualcosa deve morire e trasformarsi, cos\u00ec da dare energia al seme per poter rinasce. Il culto dei morti in Sardegna molto profondo perch\u00e9 ci connette alle nostre radici e loro, i nostri antenati e le nostre antenate, non mancano di farci visita in questo periodo\u201d. D- [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":250926,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250925"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=250925"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250925\/revisions"}],"predecessor-version":[{"id":250929,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/250925\/revisions\/250929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/250926"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=250925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=250925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=250925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}